{"id":13695,"date":"2024-07-03T13:25:23","date_gmt":"2024-07-03T19:25:23","guid":{"rendered":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?p=13695"},"modified":"2024-07-03T13:38:08","modified_gmt":"2024-07-03T19:38:08","slug":"en-menos-de-24-horas-la-policia-municipal-aseguro-a-4-sujetos","status":"publish","type":"post","link":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/en-menos-de-24-horas-la-policia-municipal-aseguro-a-4-sujetos\/","title":{"rendered":"En menos de 24 horas, la Polic\u00eda Municipal asegur\u00f3 a 4 sujetos."},"content":{"rendered":"<h2>Tres de ellos en posesi\u00f3n de armas de fuego.<\/h2>\n<ul>\n<li>Tambi\u00e9n se recuper\u00f3 un veh\u00edculo con reporte de robo.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h6>POR REDACCI\u00d3N, DIARIO ABC DE MICHOAC\u00c1N, 03 DE JULIO DE 2024.<\/h6>\n<hr \/>\n<p>Uruapan, Mich. &#8211; Acciones operativas realizadas por la Polic\u00eda Municipal en la zona urbana y conurbada de Uruapan, en las \u00faltimas 24 horas arroj\u00f3 como resultado la detenci\u00f3n de cuatro personas del sexo masculino, as\u00ed como la recuperaci\u00f3n de un veh\u00edculo con reporte de robo.<\/p>\n<p>&nbsp;<\/p>\n<p>A trav\u00e9s de un reporte ciudadano sobre la presencia de una persona con actitud sospechosa en calles de la colonia Cuauht\u00e9moc, agentes municipales realizaron recorridos de vigilancia en la zona, visualizando a una persona con caracter\u00edsticas similares al sujeto que hab\u00eda sido denunciado; al efectuarle una inspecci\u00f3n de seguridad, entre sus pertenencias se localiz\u00f3 un arma de fuego calibre .22, motivo por el que fue asegurado y puesto a disposici\u00f3n de la autoridad competente.<\/p><div id=\"diari-3691551493\" class=\"diari-contenido diari-entity-placement\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-05-07-at-10.12.40-a.m.jpeg\" alt=\"\"  srcset=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-05-07-at-10.12.40-a.m.jpeg 400w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-05-07-at-10.12.40-a.m-150x150.jpeg 150w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-05-07-at-10.12.40-a.m-300x300.jpeg 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" width=\"400\" height=\"400\"  style=\"display: inline-block;\" \/><\/div>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-13700\" src=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-03-at-1.06.24-PM-375x500.jpeg\" alt=\"\" width=\"375\" height=\"500\" srcset=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-03-at-1.06.24-PM-375x500.jpeg 375w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-03-at-1.06.24-PM-768x1024.jpeg 768w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-03-at-1.06.24-PM-1152x1536.jpeg 1152w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-03-at-1.06.24-PM-150x200.jpeg 150w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-03-at-1.06.24-PM-300x400.jpeg 300w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-03-at-1.06.24-PM-696x928.jpeg 696w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-03-at-1.06.24-PM-1068x1424.jpeg 1068w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-03-at-1.06.24-PM.jpeg 1200w\" sizes=\"auto, (max-width: 375px) 100vw, 375px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Asimismo, al efectuar patrullajes para la prevenci\u00f3n del delito sobre el Boulevard Industrial, elementos del agrupamiento Jaguares, visualizaron a una pareja de masculinos que viajaban a bordo de una motocicleta en posesi\u00f3n aparente de un arma de fuego, al solicitarles un alto y efectuarles una inspecci\u00f3n de seguridad, entre sus pertenencias se localizaron dos replicas de armas de fuego, as\u00ed como un inhibidor de se\u00f1al, por lo que fueron asegurados y puestos a disposici\u00f3n de la instancia pertinente, a fin de determinar su situaci\u00f3n legal.<\/p>\n<p>&nbsp;<\/p>\n<p>Por \u00faltimo, en la colonia Casa del Ni\u00f1o, elementos de la Polic\u00eda Municipal localizaron un veh\u00edculo Volkswagen tipo sedan de la l\u00ednea Bora, que el pasado 26 de junio, hab\u00eda sido reportado como robado. Durante la acci\u00f3n a su vez de realiz\u00f3 la detenci\u00f3n del conductor que, junto con el automotor, fueron puestos a disposici\u00f3n de la autoridad correspondiente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tres de ellos en posesi\u00f3n de armas de fuego. Tambi\u00e9n se recuper\u00f3 un veh\u00edculo con reporte de robo. &nbsp; POR REDACCI\u00d3N, DIARIO ABC DE MICHOAC\u00c1N, 03 DE JULIO DE 2024. Uruapan, Mich. &#8211; Acciones operativas realizadas por la Polic\u00eda Municipal en la zona urbana y conurbada de Uruapan, en las \u00faltimas 24 horas arroj\u00f3 como [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":13702,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19,25,27,3],"tags":[],"class_list":["post-13695","post","type-post","status-publish","format-standard","has-post-thumbnail","category-ayuntamiento-de-uruapan","category-seguridad","category-slider","category-uruapan"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>En menos de 24 horas, la Polic\u00eda Municipal asegur\u00f3 a 4 sujetos. - Diario ABC de Michoac\u00e1n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/en-menos-de-24-horas-la-policia-municipal-aseguro-a-4-sujetos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En menos de 24 horas, la Polic\u00eda Municipal asegur\u00f3 a 4 sujetos. - Diario ABC de Michoac\u00e1n\" \/>\n<meta property=\"og:description\" content=\"Tres de ellos en posesi\u00f3n de armas de fuego. Tambi\u00e9n se recuper\u00f3 un veh\u00edculo con reporte de robo. &nbsp; POR REDACCI\u00d3N, DIARIO ABC DE MICHOAC\u00c1N, 03 DE JULIO DE 2024. Uruapan, Mich. &#8211; Acciones operativas realizadas por la Polic\u00eda Municipal en la zona urbana y conurbada de Uruapan, en las \u00faltimas 24 horas arroj\u00f3 como [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/en-menos-de-24-horas-la-policia-municipal-aseguro-a-4-sujetos\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario ABC de Michoac\u00e1n\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-03T19:25:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-03T19:38:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-03-at-1.06.23-PM.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1565\" \/>\n\t<meta property=\"og:image:height\" content=\"1566\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"AR\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"AR\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/en-menos-de-24-horas-la-policia-municipal-aseguro-a-4-sujetos\/\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/en-menos-de-24-horas-la-policia-municipal-aseguro-a-4-sujetos\/\",\"name\":\"En menos de 24 horas, la Polic\u00eda Municipal asegur\u00f3 a 4 sujetos. - Diario ABC de Michoac\u00e1n\",\"isPartOf\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/en-menos-de-24-horas-la-policia-municipal-aseguro-a-4-sujetos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/en-menos-de-24-horas-la-policia-municipal-aseguro-a-4-sujetos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-03-at-1.06.23-PM.jpeg\",\"datePublished\":\"2024-07-03T19:25:23+00:00\",\"dateModified\":\"2024-07-03T19:38:08+00:00\",\"author\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/19ae376040f6cbc489682ebdd8524852\"},\"breadcrumb\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/en-menos-de-24-horas-la-policia-municipal-aseguro-a-4-sujetos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/en-menos-de-24-horas-la-policia-municipal-aseguro-a-4-sujetos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/en-menos-de-24-horas-la-policia-municipal-aseguro-a-4-sujetos\/#primaryimage\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-03-at-1.06.23-PM.jpeg\",\"contentUrl\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-03-at-1.06.23-PM.jpeg\",\"width\":1565,\"height\":1566},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/en-menos-de-24-horas-la-policia-municipal-aseguro-a-4-sujetos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En menos de 24 horas, la Polic\u00eda Municipal asegur\u00f3 a 4 sujetos.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/\",\"name\":\"Diario ABC de Michoac\u00e1n\",\"description\":\"Las noticias al momento\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/19ae376040f6cbc489682ebdd8524852\",\"name\":\"AR\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/620dde31bffc1d1abdb08a27461f06f796e6d74bba9feb506eda89b4e07120bb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/620dde31bffc1d1abdb08a27461f06f796e6d74bba9feb506eda89b4e07120bb?s=96&d=mm&r=g\",\"caption\":\"AR\"},\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/author\/adrian\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En menos de 24 horas, la Polic\u00eda Municipal asegur\u00f3 a 4 sujetos. - Diario ABC de Michoac\u00e1n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/en-menos-de-24-horas-la-policia-municipal-aseguro-a-4-sujetos\/","og_locale":"es_ES","og_type":"article","og_title":"En menos de 24 horas, la Polic\u00eda Municipal asegur\u00f3 a 4 sujetos. - Diario ABC de Michoac\u00e1n","og_description":"Tres de ellos en posesi\u00f3n de armas de fuego. Tambi\u00e9n se recuper\u00f3 un veh\u00edculo con reporte de robo. &nbsp; POR REDACCI\u00d3N, DIARIO ABC DE MICHOAC\u00c1N, 03 DE JULIO DE 2024. Uruapan, Mich. &#8211; Acciones operativas realizadas por la Polic\u00eda Municipal en la zona urbana y conurbada de Uruapan, en las \u00faltimas 24 horas arroj\u00f3 como [&hellip;]","og_url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/en-menos-de-24-horas-la-policia-municipal-aseguro-a-4-sujetos\/","og_site_name":"Diario ABC de Michoac\u00e1n","article_published_time":"2024-07-03T19:25:23+00:00","article_modified_time":"2024-07-03T19:38:08+00:00","og_image":[{"width":1565,"height":1566,"url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-03-at-1.06.23-PM.jpeg","type":"image\/jpeg"}],"author":"AR","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"AR","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/en-menos-de-24-horas-la-policia-municipal-aseguro-a-4-sujetos\/","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/en-menos-de-24-horas-la-policia-municipal-aseguro-a-4-sujetos\/","name":"En menos de 24 horas, la Polic\u00eda Municipal asegur\u00f3 a 4 sujetos. - Diario ABC de Michoac\u00e1n","isPartOf":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/en-menos-de-24-horas-la-policia-municipal-aseguro-a-4-sujetos\/#primaryimage"},"image":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/en-menos-de-24-horas-la-policia-municipal-aseguro-a-4-sujetos\/#primaryimage"},"thumbnailUrl":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-03-at-1.06.23-PM.jpeg","datePublished":"2024-07-03T19:25:23+00:00","dateModified":"2024-07-03T19:38:08+00:00","author":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/19ae376040f6cbc489682ebdd8524852"},"breadcrumb":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/en-menos-de-24-horas-la-policia-municipal-aseguro-a-4-sujetos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/en-menos-de-24-horas-la-policia-municipal-aseguro-a-4-sujetos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/en-menos-de-24-horas-la-policia-municipal-aseguro-a-4-sujetos\/#primaryimage","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-03-at-1.06.23-PM.jpeg","contentUrl":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-03-at-1.06.23-PM.jpeg","width":1565,"height":1566},{"@type":"BreadcrumbList","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/en-menos-de-24-horas-la-policia-municipal-aseguro-a-4-sujetos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/"},{"@type":"ListItem","position":2,"name":"En menos de 24 horas, la Polic\u00eda Municipal asegur\u00f3 a 4 sujetos."}]},{"@type":"WebSite","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/","name":"Diario ABC de Michoac\u00e1n","description":"Las noticias al momento","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/19ae376040f6cbc489682ebdd8524852","name":"AR","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/620dde31bffc1d1abdb08a27461f06f796e6d74bba9feb506eda89b4e07120bb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/620dde31bffc1d1abdb08a27461f06f796e6d74bba9feb506eda89b4e07120bb?s=96&d=mm&r=g","caption":"AR"},"url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/author\/adrian\/"}]}},"_links":{"self":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/13695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/comments?post=13695"}],"version-history":[{"count":1,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/13695\/revisions"}],"predecessor-version":[{"id":13703,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/13695\/revisions\/13703"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/media\/13702"}],"wp:attachment":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/media?parent=13695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/categories?post=13695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/tags?post=13695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}