{"id":5023,"date":"2024-05-12T17:09:53","date_gmt":"2024-05-12T23:09:53","guid":{"rendered":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?p=5023"},"modified":"2024-05-12T17:09:53","modified_gmt":"2024-05-12T23:09:53","slug":"alerta-godoy-que-la-oposicion-prepara-escenario-para-anular-eleccion","status":"publish","type":"post","link":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/alerta-godoy-que-la-oposicion-prepara-escenario-para-anular-eleccion\/","title":{"rendered":"Alerta Godoy que la oposici\u00f3n prepara escenario para anular elecci\u00f3n"},"content":{"rendered":"<h2>Godoy Rangel, acus\u00f3 al PRI y Acci\u00f3n Nacional (PAN), de analizar los escenarios para buscar la nulidad de la elecci\u00f3n.<\/h2>\n<h6>POR AM\u00c9RICA JU\u00c1REZ NAVARRO, DIARIO ABC DE MICHOAC\u00c1N, 12 DE MAYO DE 2024.<\/h6>\n<hr \/>\n<p>Morelia, Mich.- El actual candidato de Morena, PT y partido Verde Ecologista, por el Distrito Federal de L\u00e1zaro C\u00e1rdenas, alert\u00f3 de lo que consider\u00f3 es la narrativa de violencia de la oposici\u00f3n, para hacer que se caiga la elecci\u00f3n.<\/p>\n<p>Godoy Rangel, acus\u00f3 al PRI y Acci\u00f3n Nacional (PAN), de analizar los escenarios para buscar la nulidad de la elecci\u00f3n, y sostuvo que no observa el riesgo de que el crimen organizado pueda hacer da\u00f1o o intervenci\u00f3n en el proceso electoral.<\/p><div id=\"diari-1249547732\" class=\"diari-contenido diari-entity-placement\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-05-07-at-10.12.40-a.m.jpeg\" alt=\"\"  srcset=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-05-07-at-10.12.40-a.m.jpeg 400w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-05-07-at-10.12.40-a.m-150x150.jpeg 150w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-05-07-at-10.12.40-a.m-300x300.jpeg 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" width=\"400\" height=\"400\"  style=\"display: inline-block;\" \/><\/div>\n<p>Esta narrativa, insisti\u00f3, tiene una intenci\u00f3n pol\u00edtica, misma que no va a prosperar, porque el Estado Mexicano es m\u00e1s poderoso que cualquier grupo delictivo<\/p>\n<p>Record\u00f3 que tambi\u00e9n forma parte como diputado federal de la comisi\u00f3n permanente del Congreso de la Uni\u00f3n, ah\u00ed es la misma l\u00ednea discursiva de los diputados del PRI, PAN y PRD, para pintar un escenario \u00abdantesco\u00bb en el pa\u00eds, que no existe, no obstante, reconoci\u00f3 que todos los aspirantes y no solo los de la oposici\u00f3n, tienen problemas.<\/p>\n<p>\u00abA nadie le conviene que en ninguna parte haya violencia, nosotros vamos a que las elecciones se lleven en paz, de propuestas y no de odio\u00bb, agreg\u00f3 al exponer que se le apuesta a la Guardia Nacional recorra el pa\u00eds y que les corresponde, y si bien se\u00f1al\u00f3 que el ej\u00e9rcito es quien antes patrullaba, ahora ser\u00e1 con la Guardia Nacional que es \u00abmuy respetable en el pa\u00eds\u00bb, si lo hace, asegur\u00f3 habr\u00e1 una elecci\u00f3n en paz en el pa\u00eds.<\/p>\n<p>En el caso de Michoac\u00e1n, mencion\u00f3 que algunas zonas de riesgo en el pa\u00eds, en Michoac\u00e1n, pero son regiones a las que se les debe poner atenci\u00f3n. \u00abEn Tierra Caliente son zonas que se les tienen que poner m\u00e1s atenci\u00f3n, pero como siempre ha sido as\u00ed\u00bb, mencion\u00f3 al manifestar que nadie est\u00e1 exento de sufrir un acto de violencia del crimen organizado, pero justo por eso, se tiene que blindar la elecci\u00f3n, justamente con propuestas, no caer en provocaciones, o no hacer campa\u00f1as de odio entre candidatos, no generar y no promover odio, es lo que se est\u00e1 haciendo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Godoy Rangel, acus\u00f3 al PRI y Acci\u00f3n Nacional (PAN), de analizar los escenarios para buscar la nulidad de la elecci\u00f3n. POR AM\u00c9RICA JU\u00c1REZ NAVARRO, DIARIO ABC DE MICHOAC\u00c1N, 12 DE MAYO DE 2024. Morelia, Mich.- El actual candidato de Morena, PT y partido Verde Ecologista, por el Distrito Federal de L\u00e1zaro C\u00e1rdenas, alert\u00f3 de lo [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":5024,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,17,27],"tags":[],"class_list":["post-5023","post","type-post","status-publish","format-standard","has-post-thumbnail","category-estado","category-gobierno-de-michoacan","category-slider"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Alerta Godoy que la oposici\u00f3n prepara escenario para anular elecci\u00f3n - Diario ABC de Michoac\u00e1n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/alerta-godoy-que-la-oposicion-prepara-escenario-para-anular-eleccion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alerta Godoy que la oposici\u00f3n prepara escenario para anular elecci\u00f3n - Diario ABC de Michoac\u00e1n\" \/>\n<meta property=\"og:description\" content=\"Godoy Rangel, acus\u00f3 al PRI y Acci\u00f3n Nacional (PAN), de analizar los escenarios para buscar la nulidad de la elecci\u00f3n. POR AM\u00c9RICA JU\u00c1REZ NAVARRO, DIARIO ABC DE MICHOAC\u00c1N, 12 DE MAYO DE 2024. Morelia, Mich.- El actual candidato de Morena, PT y partido Verde Ecologista, por el Distrito Federal de L\u00e1zaro C\u00e1rdenas, alert\u00f3 de lo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/alerta-godoy-que-la-oposicion-prepara-escenario-para-anular-eleccion\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario ABC de Michoac\u00e1n\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-12T23:09:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/05\/Screenshot_20240512-170813-143.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"852\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"MD\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MD\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/alerta-godoy-que-la-oposicion-prepara-escenario-para-anular-eleccion\/\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/alerta-godoy-que-la-oposicion-prepara-escenario-para-anular-eleccion\/\",\"name\":\"Alerta Godoy que la oposici\u00f3n prepara escenario para anular elecci\u00f3n - Diario ABC de Michoac\u00e1n\",\"isPartOf\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/alerta-godoy-que-la-oposicion-prepara-escenario-para-anular-eleccion\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/alerta-godoy-que-la-oposicion-prepara-escenario-para-anular-eleccion\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/05\/Screenshot_20240512-170813-143.png\",\"datePublished\":\"2024-05-12T23:09:53+00:00\",\"dateModified\":\"2024-05-12T23:09:53+00:00\",\"author\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/657e7c20ff5297f317664d985712e8e8\"},\"breadcrumb\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/alerta-godoy-que-la-oposicion-prepara-escenario-para-anular-eleccion\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/alerta-godoy-que-la-oposicion-prepara-escenario-para-anular-eleccion\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/alerta-godoy-que-la-oposicion-prepara-escenario-para-anular-eleccion\/#primaryimage\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/05\/Screenshot_20240512-170813-143.png\",\"contentUrl\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/05\/Screenshot_20240512-170813-143.png\",\"width\":1080,\"height\":852},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/alerta-godoy-que-la-oposicion-prepara-escenario-para-anular-eleccion\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alerta Godoy que la oposici\u00f3n prepara escenario para anular elecci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/\",\"name\":\"Diario ABC de Michoac\u00e1n\",\"description\":\"Las noticias al momento\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/657e7c20ff5297f317664d985712e8e8\",\"name\":\"MD\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ab8060b9949d8a7e308bf9094991ba1ead69c6983c61a28c9f4d981c77c3b55a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ab8060b9949d8a7e308bf9094991ba1ead69c6983c61a28c9f4d981c77c3b55a?s=96&d=mm&r=g\",\"caption\":\"MD\"},\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/author\/merelydpa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alerta Godoy que la oposici\u00f3n prepara escenario para anular elecci\u00f3n - Diario ABC de Michoac\u00e1n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/alerta-godoy-que-la-oposicion-prepara-escenario-para-anular-eleccion\/","og_locale":"es_ES","og_type":"article","og_title":"Alerta Godoy que la oposici\u00f3n prepara escenario para anular elecci\u00f3n - Diario ABC de Michoac\u00e1n","og_description":"Godoy Rangel, acus\u00f3 al PRI y Acci\u00f3n Nacional (PAN), de analizar los escenarios para buscar la nulidad de la elecci\u00f3n. POR AM\u00c9RICA JU\u00c1REZ NAVARRO, DIARIO ABC DE MICHOAC\u00c1N, 12 DE MAYO DE 2024. Morelia, Mich.- El actual candidato de Morena, PT y partido Verde Ecologista, por el Distrito Federal de L\u00e1zaro C\u00e1rdenas, alert\u00f3 de lo [&hellip;]","og_url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/alerta-godoy-que-la-oposicion-prepara-escenario-para-anular-eleccion\/","og_site_name":"Diario ABC de Michoac\u00e1n","article_published_time":"2024-05-12T23:09:53+00:00","og_image":[{"width":1080,"height":852,"url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/05\/Screenshot_20240512-170813-143.png","type":"image\/png"}],"author":"MD","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"MD","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/alerta-godoy-que-la-oposicion-prepara-escenario-para-anular-eleccion\/","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/alerta-godoy-que-la-oposicion-prepara-escenario-para-anular-eleccion\/","name":"Alerta Godoy que la oposici\u00f3n prepara escenario para anular elecci\u00f3n - Diario ABC de Michoac\u00e1n","isPartOf":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/alerta-godoy-que-la-oposicion-prepara-escenario-para-anular-eleccion\/#primaryimage"},"image":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/alerta-godoy-que-la-oposicion-prepara-escenario-para-anular-eleccion\/#primaryimage"},"thumbnailUrl":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/05\/Screenshot_20240512-170813-143.png","datePublished":"2024-05-12T23:09:53+00:00","dateModified":"2024-05-12T23:09:53+00:00","author":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/657e7c20ff5297f317664d985712e8e8"},"breadcrumb":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/alerta-godoy-que-la-oposicion-prepara-escenario-para-anular-eleccion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/alerta-godoy-que-la-oposicion-prepara-escenario-para-anular-eleccion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/alerta-godoy-que-la-oposicion-prepara-escenario-para-anular-eleccion\/#primaryimage","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/05\/Screenshot_20240512-170813-143.png","contentUrl":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/05\/Screenshot_20240512-170813-143.png","width":1080,"height":852},{"@type":"BreadcrumbList","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/alerta-godoy-que-la-oposicion-prepara-escenario-para-anular-eleccion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/"},{"@type":"ListItem","position":2,"name":"Alerta Godoy que la oposici\u00f3n prepara escenario para anular elecci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/","name":"Diario ABC de Michoac\u00e1n","description":"Las noticias al momento","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/657e7c20ff5297f317664d985712e8e8","name":"MD","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ab8060b9949d8a7e308bf9094991ba1ead69c6983c61a28c9f4d981c77c3b55a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ab8060b9949d8a7e308bf9094991ba1ead69c6983c61a28c9f4d981c77c3b55a?s=96&d=mm&r=g","caption":"MD"},"url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/author\/merelydpa\/"}]}},"_links":{"self":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/5023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/comments?post=5023"}],"version-history":[{"count":1,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/5023\/revisions"}],"predecessor-version":[{"id":5025,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/5023\/revisions\/5025"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/media\/5024"}],"wp:attachment":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/media?parent=5023"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/categories?post=5023"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/tags?post=5023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}