{"id":5382,"date":"2024-05-14T17:20:49","date_gmt":"2024-05-14T23:20:49","guid":{"rendered":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?p=5382"},"modified":"2024-05-14T17:20:49","modified_gmt":"2024-05-14T23:20:49","slug":"eligen-a-2-recipiendarios-de-la-presa-generalisimo-morelos","status":"publish","type":"post","link":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/eligen-a-2-recipiendarios-de-la-presa-generalisimo-morelos\/","title":{"rendered":"Eligen a 2 recipiendarios de la Presa General\u00edsimo Morelos"},"content":{"rendered":"<h3>El abogado e historiador Jos\u00e9 Fabi\u00e1n Ru\u00edz y al fundador de la productora y escuela de cine Solaris, Juan Pablo Arroyo Abraham<\/h3>\n<ul>\n<li>Se entregar\u00e1n el pr\u00f3ximo 18 de mayo, en Sesi\u00f3n Solemne de Cabildo, a las 10:00 horas.<\/li>\n<\/ul>\n<h6>POR REDACCI\u00d3N, DIARIO ABC DE MICHOAC\u00c1N, 14 DE MAYO DE 2024.<\/h6>\n<hr \/>\n<p>Morelia, Michoac\u00e1n; 14 de mayo de 2024.-Tras la revisi\u00f3n de la Comisi\u00f3n Evaluadora de Preseas Municipales y una selecci\u00f3n por votaci\u00f3n cedular, en Sesi\u00f3n Ordinaria de Cabildo, se eligieron a dos recipiendarios de la presea General\u00edsimo Morelos, que ser\u00e1 entregada al abogado e historiador, Jos\u00e9 Fabi\u00e1n Ru\u00edz y al fundador de la productora y escuela de cine Solaris, Juan Pablo Arroyo Abraham.<\/p>\n<p>Nominado por el Consejo de Fomento Cultural Mi Lindo Michoac\u00e1n, A.C., se encuentra Jos\u00e9 Fabi\u00e1n Ru\u00edz, reconocido escritor, abogado e historiador que se desempe\u00f1\u00f3 como director del Museo Casa Natal de Morelos durante casi 23 a\u00f1os. Ha publicado 51 libros entre los que destacan: Semblanzas Michoacanas, Tribuna Hist\u00f3rica Michoacana, Im\u00e1genes Michoacanas, Morelos Frente a sus Mitos y Leyendas, La Conspiraci\u00f3n de Valladolid de 1809.<\/p><div id=\"diari-972853304\" class=\"diari-contenido diari-entity-placement\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-05-07-at-10.12.40-a.m.jpeg\" alt=\"\"  srcset=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-05-07-at-10.12.40-a.m.jpeg 400w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-05-07-at-10.12.40-a.m-150x150.jpeg 150w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-05-07-at-10.12.40-a.m-300x300.jpeg 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" width=\"400\" height=\"400\"  style=\"display: inline-block;\" \/><\/div>\n<p>En tanto, Juan Pablo Arroyo, es fundador de la productora y escuela de cine Solaris en Morelia. Su documental \u201cClandestino\u201d le otorg\u00f3 el premio a mejor documental en la Sexta Edici\u00f3n del Festival Internacional de Cine. Entre sus grandes producciones destacan: Espacio Vac\u00edo, Alias, D\u00eda Seis, Almas Rotas. Fue galardonado en 2018 con la presea Tocav\u00e9n otorgada por la Voz de Michoac\u00e1n, al m\u00e9rito empresarial. Ha sido consejero en: grupo Banorte, Comisi\u00f3n F\u00edlmica de Morelia, Grupo Salinas, Consejo Michoacano de Negocios, entre otros.<\/p>\n<p>Dicha presea ser\u00e1 entregada en sesi\u00f3n solemne de Cabildo el pr\u00f3ximo s\u00e1bado 18 de mayo del presente, a las 10:00 horas en Palacio Municipal, en el marco del 483 Aniversario de la Fundaci\u00f3n de la Ciudad de Morelia. Los galardonados recibieron 5 votos cada uno para hacerse acreedores a la m\u00e1xima distinci\u00f3n que otorga el Ayuntamiento.<\/p>\n<p>En esta misma sesi\u00f3n, con voto un\u00e1nime qued\u00f3 aprobada la entrega a las y los j\u00f3venes ganadores de la Condecoraci\u00f3n al M\u00e9rito Juvenil 2024 que anualmente entrega el Instituto de la Juventud Moreliana (IJUM) en los \u00e1mbitos: Acad\u00e9mico; art\u00edstico-cultural; Profesional; Social; Deportivo; Discapacidad e Integraci\u00f3n; Innovaci\u00f3n Tecnol\u00f3gica; Medio Ambiente, a entregarse en el presente mes de mayo como parte de los festejos de aniversario de fundaci\u00f3n de la ciudad.<\/p>\n<p>Asimismo, se aprob\u00f3 en sesi\u00f3n extraordinaria de Cabildo el acuerdo por el cual el Ayuntamiento de Morelia aval\u00f3 de manera por unanimidad la Ampliaci\u00f3n Liquida al Presupuesto de Ingresos y Presupuesto Egresos correspondiente al Ejercicio Fiscal 2024, por un monto de 4 millones 679 mil 584 pesos con 20 centavos, con la cual los presupuestos ascienden a 3 mil 774 millones 256 mil 957 pesos con 97 centavos para dar suficiencia presupuestaria a varios programas y proyectos municipales.<\/p>\n<p><strong>En apego a las acciones preventivas implementadas por la Administraci\u00f3n Municipal, en raz\u00f3n de las disposiciones emitidas por las autoridades electorales, este contenido tiene fines informativos.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El abogado e historiador Jos\u00e9 Fabi\u00e1n Ru\u00edz y al fundador de la productora y escuela de cine Solaris, Juan Pablo Arroyo Abraham Se entregar\u00e1n el pr\u00f3ximo 18 de mayo, en Sesi\u00f3n Solemne de Cabildo, a las 10:00 horas. POR REDACCI\u00d3N, DIARIO ABC DE MICHOAC\u00c1N, 14 DE MAYO DE 2024. Morelia, Michoac\u00e1n; 14 de mayo de [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":5383,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,17,27],"tags":[],"class_list":["post-5382","post","type-post","status-publish","format-standard","has-post-thumbnail","category-estado","category-gobierno-de-michoacan","category-slider"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Eligen a 2 recipiendarios de la Presa General\u00edsimo Morelos - Diario ABC de Michoac\u00e1n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/eligen-a-2-recipiendarios-de-la-presa-generalisimo-morelos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eligen a 2 recipiendarios de la Presa General\u00edsimo Morelos - Diario ABC de Michoac\u00e1n\" \/>\n<meta property=\"og:description\" content=\"El abogado e historiador Jos\u00e9 Fabi\u00e1n Ru\u00edz y al fundador de la productora y escuela de cine Solaris, Juan Pablo Arroyo Abraham Se entregar\u00e1n el pr\u00f3ximo 18 de mayo, en Sesi\u00f3n Solemne de Cabildo, a las 10:00 horas. POR REDACCI\u00d3N, DIARIO ABC DE MICHOAC\u00c1N, 14 DE MAYO DE 2024. Morelia, Michoac\u00e1n; 14 de mayo de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/eligen-a-2-recipiendarios-de-la-presa-generalisimo-morelos\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario ABC de Michoac\u00e1n\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-14T23:20:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/05\/Screenshot_20240514-171511-773.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"786\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"MD\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MD\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/eligen-a-2-recipiendarios-de-la-presa-generalisimo-morelos\/\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/eligen-a-2-recipiendarios-de-la-presa-generalisimo-morelos\/\",\"name\":\"Eligen a 2 recipiendarios de la Presa General\u00edsimo Morelos - Diario ABC de Michoac\u00e1n\",\"isPartOf\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/eligen-a-2-recipiendarios-de-la-presa-generalisimo-morelos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/eligen-a-2-recipiendarios-de-la-presa-generalisimo-morelos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/05\/Screenshot_20240514-171511-773.png\",\"datePublished\":\"2024-05-14T23:20:49+00:00\",\"dateModified\":\"2024-05-14T23:20:49+00:00\",\"author\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/657e7c20ff5297f317664d985712e8e8\"},\"breadcrumb\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/eligen-a-2-recipiendarios-de-la-presa-generalisimo-morelos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/eligen-a-2-recipiendarios-de-la-presa-generalisimo-morelos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/eligen-a-2-recipiendarios-de-la-presa-generalisimo-morelos\/#primaryimage\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/05\/Screenshot_20240514-171511-773.png\",\"contentUrl\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/05\/Screenshot_20240514-171511-773.png\",\"width\":1080,\"height\":786},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/eligen-a-2-recipiendarios-de-la-presa-generalisimo-morelos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eligen a 2 recipiendarios de la Presa General\u00edsimo Morelos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/\",\"name\":\"Diario ABC de Michoac\u00e1n\",\"description\":\"Las noticias al momento\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/657e7c20ff5297f317664d985712e8e8\",\"name\":\"MD\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ab8060b9949d8a7e308bf9094991ba1ead69c6983c61a28c9f4d981c77c3b55a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ab8060b9949d8a7e308bf9094991ba1ead69c6983c61a28c9f4d981c77c3b55a?s=96&d=mm&r=g\",\"caption\":\"MD\"},\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/author\/merelydpa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eligen a 2 recipiendarios de la Presa General\u00edsimo Morelos - Diario ABC de Michoac\u00e1n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/eligen-a-2-recipiendarios-de-la-presa-generalisimo-morelos\/","og_locale":"es_ES","og_type":"article","og_title":"Eligen a 2 recipiendarios de la Presa General\u00edsimo Morelos - Diario ABC de Michoac\u00e1n","og_description":"El abogado e historiador Jos\u00e9 Fabi\u00e1n Ru\u00edz y al fundador de la productora y escuela de cine Solaris, Juan Pablo Arroyo Abraham Se entregar\u00e1n el pr\u00f3ximo 18 de mayo, en Sesi\u00f3n Solemne de Cabildo, a las 10:00 horas. POR REDACCI\u00d3N, DIARIO ABC DE MICHOAC\u00c1N, 14 DE MAYO DE 2024. Morelia, Michoac\u00e1n; 14 de mayo de [&hellip;]","og_url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/eligen-a-2-recipiendarios-de-la-presa-generalisimo-morelos\/","og_site_name":"Diario ABC de Michoac\u00e1n","article_published_time":"2024-05-14T23:20:49+00:00","og_image":[{"width":1080,"height":786,"url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/05\/Screenshot_20240514-171511-773.png","type":"image\/png"}],"author":"MD","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"MD","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/eligen-a-2-recipiendarios-de-la-presa-generalisimo-morelos\/","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/eligen-a-2-recipiendarios-de-la-presa-generalisimo-morelos\/","name":"Eligen a 2 recipiendarios de la Presa General\u00edsimo Morelos - Diario ABC de Michoac\u00e1n","isPartOf":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/eligen-a-2-recipiendarios-de-la-presa-generalisimo-morelos\/#primaryimage"},"image":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/eligen-a-2-recipiendarios-de-la-presa-generalisimo-morelos\/#primaryimage"},"thumbnailUrl":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/05\/Screenshot_20240514-171511-773.png","datePublished":"2024-05-14T23:20:49+00:00","dateModified":"2024-05-14T23:20:49+00:00","author":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/657e7c20ff5297f317664d985712e8e8"},"breadcrumb":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/eligen-a-2-recipiendarios-de-la-presa-generalisimo-morelos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/eligen-a-2-recipiendarios-de-la-presa-generalisimo-morelos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/eligen-a-2-recipiendarios-de-la-presa-generalisimo-morelos\/#primaryimage","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/05\/Screenshot_20240514-171511-773.png","contentUrl":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/05\/Screenshot_20240514-171511-773.png","width":1080,"height":786},{"@type":"BreadcrumbList","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/eligen-a-2-recipiendarios-de-la-presa-generalisimo-morelos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/"},{"@type":"ListItem","position":2,"name":"Eligen a 2 recipiendarios de la Presa General\u00edsimo Morelos"}]},{"@type":"WebSite","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/","name":"Diario ABC de Michoac\u00e1n","description":"Las noticias al momento","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/657e7c20ff5297f317664d985712e8e8","name":"MD","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ab8060b9949d8a7e308bf9094991ba1ead69c6983c61a28c9f4d981c77c3b55a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ab8060b9949d8a7e308bf9094991ba1ead69c6983c61a28c9f4d981c77c3b55a?s=96&d=mm&r=g","caption":"MD"},"url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/author\/merelydpa\/"}]}},"_links":{"self":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/5382","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/comments?post=5382"}],"version-history":[{"count":1,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/5382\/revisions"}],"predecessor-version":[{"id":5384,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/5382\/revisions\/5384"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/media\/5383"}],"wp:attachment":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/media?parent=5382"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/categories?post=5382"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/tags?post=5382"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}