{"id":56715,"date":"2025-04-28T17:47:29","date_gmt":"2025-04-28T23:47:29","guid":{"rendered":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?p=56715"},"modified":"2025-04-28T17:47:29","modified_gmt":"2025-04-28T23:47:29","slug":"se-aprueban-141-solicitudes-para-participar-como-observadoras-electorales-ine-michoacan","status":"publish","type":"post","link":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/se-aprueban-141-solicitudes-para-participar-como-observadoras-electorales-ine-michoacan\/","title":{"rendered":"Se aprueban 141 solicitudes para participar como observadoras electorales: INE Michoac\u00e1n"},"content":{"rendered":"<ul>\n<li>En total son 3 mil 923 personas observadoras electorales<\/li>\n<\/ul>\n<hr \/>\n<p>Morelia, Michoac\u00e1n.- El Consejo Local del Instituto Nacional Electoral en el Estado de Michoac\u00e1n, en sesi\u00f3n extraordinaria aprob\u00f3 141 solicitudes individuales que fueron presentadas a trav\u00e9s del Portal del Instituto Nacional Electoral y ante la propia Junta Local, lo cual han cumplido con los requisitos establecidos por la normativa.<\/p>\n<p>Durante su intervenci\u00f3n, el Lic. David Alejandro Delgado Arroyo, Consejero Presidente, mencion\u00f3 que con la aprobaci\u00f3n de estas 141 solicitudes m\u00e1s, se ha alcanzado la cifra de 3 mil 923 personas acreditadas como observadoras electorales en el Estado de Michoac\u00e1n.<\/p>\n<p>Cabe destacar que el total de las solicitudes recibidas en la Junta local, han sido 718 de las cuales 68 fueron aprobadas,1 denegada,4 declinadas, 61 han sido solicitudes que no completaron con los requisitos, 59 han sido registradas como militantes,1 se encuentra en ambos supuestos, y 1 se encuentra vinculada a programas sociales.<\/p>\n<p>En L\u00e1zaro C\u00e1rdenas son 1,040 solicitudes, de las cuales 88 est\u00e1n aprobadas, 1 fue negada,166 que no completaron con los requisitos, 162 est\u00e1n registradas con clave de elector como militante, 3 que se encuentran en ambos supuestos, y 1 registro con credencial vencida anterior al 2024.<\/p>\n<p>En Apatzing\u00e1n se ha recibido en total de 789, de las cuales se han aprobado 48, 2 declinadas, 5 no completaron los requisitos, 158 han sido registradas con clave de elector como militante y 4 con credenciales vencidas anteriores al 2024.<\/p>\n<p>En Zit\u00e1cuaro son 1018, de las cuales han sido aprobadas 225, 7 declinadas, 191 que no completaron los requisitos, 174 son solicitudes con clave de elector registrados como militantes, 4 solicitudes registradas en el sistema de registro de precandidatos y candidatos, 5 est\u00e1 en ambos supuestos y 8 se presentaron con credencial vencida.<\/p>\n<p>Jiquilpan tiene un total de 1,076, de las cuales 361 han aprobadas,172 no completaron los requisitos, 159 han sido registradas con clave como militante, 6 est\u00e1n registradas en el sistema de registro de precandidatos y candidatos, 2 est\u00e1 en ambos supuestos, 5 que no completaron los requisitos por no tener una credencial vigente.<\/p>\n<p>En Zamora, se han presentado un total de 1656 solicitudes, 294 han sido aprobadas, 3 declinadas, 316 no completaron el registro,304 tiene clave de elector registrada como militante, 3 con clave de electro registrada en el sistema de registro precandidatos y candidatos, 7 se encuentran en ambos supuestos, 2 que no complementaron los requisitos por no tener una credencial vigente.<\/p>\n<p>En Ciudad Hidalgo se han solicitado en total 1391, de las cuales 469 est\u00e1n aprobadas, 10 fue denegadas, 3 declinadas, 204 que no completaron los requisitos, 201 est\u00e1n registradas con clave de elector como militante, 1 que se encuentran en ambos supuestos, 2 que no complementaron los requisitos por no tener una credencial vigente.<\/p>\n<p>En Zacapu, se han presentado un total de 1507 solicitudes, 867 han sido aprobadas, 6 denegadas, 10 declinadas, 308 no completaron los requisitos, 297 tiene clave de elector registrada como militante, 8 se encuentran en ambos supuestos, 3 que no complementaron los requisitos por no tener una credencial vigente.<\/p>\n<p>En Morelia, se han presentado un total de 1944 solicitudes, 539 han sido aprobadas, 2 canceladas, 3 declinadas, 54 no completaron los requisitos,53 tiene clave de elector registrada como militante, 1 que no completaron los requisitos por no tener una credencial vigente.<\/p>\n<p>En Uruapan, se han presentado un total de 663 solicitudes, 315 han sido aprobadas, 61 no completaron los requisitos,56 tiene clave de elector registrada como militante, 1 con clave de electro registrada en el sistema de registro precandidatos y candidatos, 2 que se encuentran en ambos supuestos, 2 que no complementaron los requisitos por no tener una credencial vigente.<\/p>\n<p>En Morelia, se han presentado un total de 1114 solicitudes, 342 han sido aprobadas, 3 canceladas, 6 declinadas, 147 que no completaron los requisitos,145 tiene clave de elector registrada como militante, 1 en ambos supuestos, 1 que no complementaron los requisitos por no tener una credencial vigente.<\/p>\n<p>En P\u00e1tzcuaro, se han presentado un total de 915 solicitudes, 166 han sido aprobadas,1 denegada, 1 declinadas, 129 que no completaron los requisitos,125 tiene clave de elector registrada como militante, 1 con clave de electro registrada en el sistema de registro precandidatos y candidatos, 3 en ambos supuestos.<\/p>\n<p>Lo que suma de manera general en el estado un total de 13 mil 831 solicitudes de las cuales se han aprobado 3782, 19 han sido denegadas, 5 canceladas, 39 declinadas, 1814 no ha complementado los requisitos, 1736 con clave de elector registrada como militante, 15 con clave de electro registrada en el sistema de registro precandidatos y candidatos, 33 que se encuentran en ambos supuestos, 29 que no completaron los requisitos por no tener credencial vigente y 1 que complementaron los requisitos por estar vinculados con programas sociales.<\/p>\n<p>Si se hace la sumatoria de las solicitudes aprobadas de la entidad son 3782 m\u00e1s las 141 que se aprobaron en la sesi\u00f3n, da un total de 3 mil 923.<\/p>\n<p>COMUNICADO<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En total son 3 mil 923 personas observadoras electorales Morelia, Michoac\u00e1n.- El Consejo Local del Instituto Nacional Electoral en el Estado de Michoac\u00e1n, en sesi\u00f3n extraordinaria aprob\u00f3 141 solicitudes individuales que fueron presentadas a trav\u00e9s del Portal del Instituto Nacional Electoral y ante la propia Junta Local, lo cual han cumplido con los requisitos establecidos [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":56716,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,4,7,28,3,5],"tags":[],"class_list":{"0":"post-56715","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-apatzingan","8":"category-lazaro-cardenas","9":"category-morelia","10":"category-politica","11":"category-uruapan","12":"category-zamora"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Se aprueban 141 solicitudes para participar como observadoras electorales: INE Michoac\u00e1n - Diario ABC de Michoac\u00e1n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/se-aprueban-141-solicitudes-para-participar-como-observadoras-electorales-ine-michoacan\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se aprueban 141 solicitudes para participar como observadoras electorales: INE Michoac\u00e1n - Diario ABC de Michoac\u00e1n\" \/>\n<meta property=\"og:description\" content=\"En total son 3 mil 923 personas observadoras electorales Morelia, Michoac\u00e1n.- El Consejo Local del Instituto Nacional Electoral en el Estado de Michoac\u00e1n, en sesi\u00f3n extraordinaria aprob\u00f3 141 solicitudes individuales que fueron presentadas a trav\u00e9s del Portal del Instituto Nacional Electoral y ante la propia Junta Local, lo cual han cumplido con los requisitos establecidos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/se-aprueban-141-solicitudes-para-participar-como-observadoras-electorales-ine-michoacan\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario ABC de Michoac\u00e1n\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-28T23:47:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-04-28-at-17.27.52-e1745882971374.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MD\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MD\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/se-aprueban-141-solicitudes-para-participar-como-observadoras-electorales-ine-michoacan\/\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/se-aprueban-141-solicitudes-para-participar-como-observadoras-electorales-ine-michoacan\/\",\"name\":\"Se aprueban 141 solicitudes para participar como observadoras electorales: INE Michoac\u00e1n - Diario ABC de Michoac\u00e1n\",\"isPartOf\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/se-aprueban-141-solicitudes-para-participar-como-observadoras-electorales-ine-michoacan\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/se-aprueban-141-solicitudes-para-participar-como-observadoras-electorales-ine-michoacan\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-04-28-at-17.27.52-e1745882971374.jpeg\",\"datePublished\":\"2025-04-28T23:47:29+00:00\",\"dateModified\":\"2025-04-28T23:47:29+00:00\",\"author\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/657e7c20ff5297f317664d985712e8e8\"},\"breadcrumb\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/se-aprueban-141-solicitudes-para-participar-como-observadoras-electorales-ine-michoacan\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/se-aprueban-141-solicitudes-para-participar-como-observadoras-electorales-ine-michoacan\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/se-aprueban-141-solicitudes-para-participar-como-observadoras-electorales-ine-michoacan\/#primaryimage\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-04-28-at-17.27.52-e1745882971374.jpeg\",\"contentUrl\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-04-28-at-17.27.52-e1745882971374.jpeg\",\"width\":800,\"height\":533},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/se-aprueban-141-solicitudes-para-participar-como-observadoras-electorales-ine-michoacan\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se aprueban 141 solicitudes para participar como observadoras electorales: INE Michoac\u00e1n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/\",\"name\":\"Diario ABC de Michoac\u00e1n\",\"description\":\"Las noticias al momento\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/657e7c20ff5297f317664d985712e8e8\",\"name\":\"MD\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a769375eedc94419a5b67bc5d63567af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a769375eedc94419a5b67bc5d63567af?s=96&d=mm&r=g\",\"caption\":\"MD\"},\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/author\/merelydpa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Se aprueban 141 solicitudes para participar como observadoras electorales: INE Michoac\u00e1n - Diario ABC de Michoac\u00e1n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/se-aprueban-141-solicitudes-para-participar-como-observadoras-electorales-ine-michoacan\/","og_locale":"es_ES","og_type":"article","og_title":"Se aprueban 141 solicitudes para participar como observadoras electorales: INE Michoac\u00e1n - Diario ABC de Michoac\u00e1n","og_description":"En total son 3 mil 923 personas observadoras electorales Morelia, Michoac\u00e1n.- El Consejo Local del Instituto Nacional Electoral en el Estado de Michoac\u00e1n, en sesi\u00f3n extraordinaria aprob\u00f3 141 solicitudes individuales que fueron presentadas a trav\u00e9s del Portal del Instituto Nacional Electoral y ante la propia Junta Local, lo cual han cumplido con los requisitos establecidos [&hellip;]","og_url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/se-aprueban-141-solicitudes-para-participar-como-observadoras-electorales-ine-michoacan\/","og_site_name":"Diario ABC de Michoac\u00e1n","article_published_time":"2025-04-28T23:47:29+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-04-28-at-17.27.52-e1745882971374.jpeg","type":"image\/jpeg"}],"author":"MD","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"MD","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/se-aprueban-141-solicitudes-para-participar-como-observadoras-electorales-ine-michoacan\/","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/se-aprueban-141-solicitudes-para-participar-como-observadoras-electorales-ine-michoacan\/","name":"Se aprueban 141 solicitudes para participar como observadoras electorales: INE Michoac\u00e1n - Diario ABC de Michoac\u00e1n","isPartOf":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/se-aprueban-141-solicitudes-para-participar-como-observadoras-electorales-ine-michoacan\/#primaryimage"},"image":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/se-aprueban-141-solicitudes-para-participar-como-observadoras-electorales-ine-michoacan\/#primaryimage"},"thumbnailUrl":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-04-28-at-17.27.52-e1745882971374.jpeg","datePublished":"2025-04-28T23:47:29+00:00","dateModified":"2025-04-28T23:47:29+00:00","author":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/657e7c20ff5297f317664d985712e8e8"},"breadcrumb":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/se-aprueban-141-solicitudes-para-participar-como-observadoras-electorales-ine-michoacan\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/se-aprueban-141-solicitudes-para-participar-como-observadoras-electorales-ine-michoacan\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/se-aprueban-141-solicitudes-para-participar-como-observadoras-electorales-ine-michoacan\/#primaryimage","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-04-28-at-17.27.52-e1745882971374.jpeg","contentUrl":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-04-28-at-17.27.52-e1745882971374.jpeg","width":800,"height":533},{"@type":"BreadcrumbList","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/se-aprueban-141-solicitudes-para-participar-como-observadoras-electorales-ine-michoacan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/"},{"@type":"ListItem","position":2,"name":"Se aprueban 141 solicitudes para participar como observadoras electorales: INE Michoac\u00e1n"}]},{"@type":"WebSite","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/","name":"Diario ABC de Michoac\u00e1n","description":"Las noticias al momento","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/657e7c20ff5297f317664d985712e8e8","name":"MD","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a769375eedc94419a5b67bc5d63567af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a769375eedc94419a5b67bc5d63567af?s=96&d=mm&r=g","caption":"MD"},"url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/author\/merelydpa\/"}]}},"_links":{"self":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/56715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/comments?post=56715"}],"version-history":[{"count":1,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/56715\/revisions"}],"predecessor-version":[{"id":56722,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/56715\/revisions\/56722"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/media\/56716"}],"wp:attachment":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/media?parent=56715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/categories?post=56715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/tags?post=56715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}