{"id":59301,"date":"2025-05-17T18:51:16","date_gmt":"2025-05-18T00:51:16","guid":{"rendered":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?p=59301"},"modified":"2025-05-17T18:51:16","modified_gmt":"2025-05-18T00:51:16","slug":"gobierno-de-morelia-informa-objetos-prohibidos-y-recomendaciones-para-concierto-de-aniversario","status":"publish","type":"post","link":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gobierno-de-morelia-informa-objetos-prohibidos-y-recomendaciones-para-concierto-de-aniversario\/","title":{"rendered":"Gobierno de Morelia informa objetos prohibidos y recomendaciones para concierto de aniversario"},"content":{"rendered":"<ul>\n<li>Armas, objetos punzocortantes, botellas y bebidas embriagantes ser\u00e1n detectadas en arcos de ingreso.<\/li>\n<\/ul>\n<hr \/>\n<p>Morelia, Michoac\u00e1n.- Con el objetivo de que todos y todas disfruten de manera segura y ordenada el concierto gratuito por el 484 Aniversario de Morelia, el Gobierno Municipal encabezado por el presidente Alfonso Mart\u00ednez Alc\u00e1zar, informa los objetos prohibidos en el evento, a la par que emite recomendaciones para vivir una mejor experiencia.<\/p>\n<p>Los objetos que no pueden ingresarse y ser\u00e1n detectados en los arcos de seguridad, son:<\/p>\n<p>* Armas<br \/>\n* Encendedores u objetos inflamables.<br \/>\n* Botellas de vidrio.<br \/>\n* Navajas, cuchillos u objetos punzocortantes.<br \/>\n* Bebidas embriagantes.<br \/>\n* Sombrillas.<\/p>\n<p>A su vez, las recomendaciones para vivir una experiencia agradable y divertida en este aniversario de nuestra ciudad, son:<\/p>\n<p>* Planear su traslado al centro hist\u00f3rico con suficiente anticipaci\u00f3n.<br \/>\n* Considerar los cortes viales a la circulaci\u00f3n vehicular.<br \/>\n* Usar ropa y calzado c\u00f3modo.<br \/>\n* Tener un cuidado permanente de ni\u00f1os y adultos mayores si se asiste con ellos.<\/p>\n<p>La administraci\u00f3n municipal refrenda que todas las dependencias del Ayuntamiento de Morelia se encuentran colaborando y en servicio a la ciudadan\u00eda para que vivan un aniversario de la ciudad seguro, ordenado y con mucha diversi\u00f3n.<\/p>\n<p>COMUNICADO<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Armas, objetos punzocortantes, botellas y bebidas embriagantes ser\u00e1n detectadas en arcos de ingreso. Morelia, Michoac\u00e1n.- Con el objetivo de que todos y todas disfruten de manera segura y ordenada el concierto gratuito por el 484 Aniversario de Morelia, el Gobierno Municipal encabezado por el presidente Alfonso Mart\u00ednez Alc\u00e1zar, informa los objetos prohibidos en el evento, [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":59303,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18,7,25],"tags":[],"class_list":{"0":"post-59301","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-ayuntamiento-de-morelia","8":"category-morelia","9":"category-seguridad"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gobierno de Morelia informa objetos prohibidos y recomendaciones para concierto de aniversario - Diario ABC de Michoac\u00e1n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gobierno-de-morelia-informa-objetos-prohibidos-y-recomendaciones-para-concierto-de-aniversario\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gobierno de Morelia informa objetos prohibidos y recomendaciones para concierto de aniversario - Diario ABC de Michoac\u00e1n\" \/>\n<meta property=\"og:description\" content=\"Armas, objetos punzocortantes, botellas y bebidas embriagantes ser\u00e1n detectadas en arcos de ingreso. Morelia, Michoac\u00e1n.- Con el objetivo de que todos y todas disfruten de manera segura y ordenada el concierto gratuito por el 484 Aniversario de Morelia, el Gobierno Municipal encabezado por el presidente Alfonso Mart\u00ednez Alc\u00e1zar, informa los objetos prohibidos en el evento, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gobierno-de-morelia-informa-objetos-prohibidos-y-recomendaciones-para-concierto-de-aniversario\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario ABC de Michoac\u00e1n\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-18T00:51:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-17-at-18.47.37-e1747529390321.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MD\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MD\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gobierno-de-morelia-informa-objetos-prohibidos-y-recomendaciones-para-concierto-de-aniversario\/\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gobierno-de-morelia-informa-objetos-prohibidos-y-recomendaciones-para-concierto-de-aniversario\/\",\"name\":\"Gobierno de Morelia informa objetos prohibidos y recomendaciones para concierto de aniversario - Diario ABC de Michoac\u00e1n\",\"isPartOf\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gobierno-de-morelia-informa-objetos-prohibidos-y-recomendaciones-para-concierto-de-aniversario\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gobierno-de-morelia-informa-objetos-prohibidos-y-recomendaciones-para-concierto-de-aniversario\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-17-at-18.47.37-e1747529390321.jpeg\",\"datePublished\":\"2025-05-18T00:51:16+00:00\",\"dateModified\":\"2025-05-18T00:51:16+00:00\",\"author\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/657e7c20ff5297f317664d985712e8e8\"},\"breadcrumb\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gobierno-de-morelia-informa-objetos-prohibidos-y-recomendaciones-para-concierto-de-aniversario\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gobierno-de-morelia-informa-objetos-prohibidos-y-recomendaciones-para-concierto-de-aniversario\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gobierno-de-morelia-informa-objetos-prohibidos-y-recomendaciones-para-concierto-de-aniversario\/#primaryimage\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-17-at-18.47.37-e1747529390321.jpeg\",\"contentUrl\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-17-at-18.47.37-e1747529390321.jpeg\",\"width\":800,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gobierno-de-morelia-informa-objetos-prohibidos-y-recomendaciones-para-concierto-de-aniversario\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gobierno de Morelia informa objetos prohibidos y recomendaciones para concierto de aniversario\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/\",\"name\":\"Diario ABC de Michoac\u00e1n\",\"description\":\"Las noticias al momento\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/657e7c20ff5297f317664d985712e8e8\",\"name\":\"MD\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a769375eedc94419a5b67bc5d63567af?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a769375eedc94419a5b67bc5d63567af?s=96&d=mm&r=g\",\"caption\":\"MD\"},\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/author\/merelydpa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gobierno de Morelia informa objetos prohibidos y recomendaciones para concierto de aniversario - Diario ABC de Michoac\u00e1n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gobierno-de-morelia-informa-objetos-prohibidos-y-recomendaciones-para-concierto-de-aniversario\/","og_locale":"es_ES","og_type":"article","og_title":"Gobierno de Morelia informa objetos prohibidos y recomendaciones para concierto de aniversario - Diario ABC de Michoac\u00e1n","og_description":"Armas, objetos punzocortantes, botellas y bebidas embriagantes ser\u00e1n detectadas en arcos de ingreso. Morelia, Michoac\u00e1n.- Con el objetivo de que todos y todas disfruten de manera segura y ordenada el concierto gratuito por el 484 Aniversario de Morelia, el Gobierno Municipal encabezado por el presidente Alfonso Mart\u00ednez Alc\u00e1zar, informa los objetos prohibidos en el evento, [&hellip;]","og_url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gobierno-de-morelia-informa-objetos-prohibidos-y-recomendaciones-para-concierto-de-aniversario\/","og_site_name":"Diario ABC de Michoac\u00e1n","article_published_time":"2025-05-18T00:51:16+00:00","og_image":[{"width":800,"height":1000,"url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-17-at-18.47.37-e1747529390321.jpeg","type":"image\/jpeg"}],"author":"MD","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"MD","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gobierno-de-morelia-informa-objetos-prohibidos-y-recomendaciones-para-concierto-de-aniversario\/","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gobierno-de-morelia-informa-objetos-prohibidos-y-recomendaciones-para-concierto-de-aniversario\/","name":"Gobierno de Morelia informa objetos prohibidos y recomendaciones para concierto de aniversario - Diario ABC de Michoac\u00e1n","isPartOf":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gobierno-de-morelia-informa-objetos-prohibidos-y-recomendaciones-para-concierto-de-aniversario\/#primaryimage"},"image":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gobierno-de-morelia-informa-objetos-prohibidos-y-recomendaciones-para-concierto-de-aniversario\/#primaryimage"},"thumbnailUrl":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-17-at-18.47.37-e1747529390321.jpeg","datePublished":"2025-05-18T00:51:16+00:00","dateModified":"2025-05-18T00:51:16+00:00","author":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/657e7c20ff5297f317664d985712e8e8"},"breadcrumb":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gobierno-de-morelia-informa-objetos-prohibidos-y-recomendaciones-para-concierto-de-aniversario\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gobierno-de-morelia-informa-objetos-prohibidos-y-recomendaciones-para-concierto-de-aniversario\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gobierno-de-morelia-informa-objetos-prohibidos-y-recomendaciones-para-concierto-de-aniversario\/#primaryimage","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-17-at-18.47.37-e1747529390321.jpeg","contentUrl":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-17-at-18.47.37-e1747529390321.jpeg","width":800,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gobierno-de-morelia-informa-objetos-prohibidos-y-recomendaciones-para-concierto-de-aniversario\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/"},{"@type":"ListItem","position":2,"name":"Gobierno de Morelia informa objetos prohibidos y recomendaciones para concierto de aniversario"}]},{"@type":"WebSite","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/","name":"Diario ABC de Michoac\u00e1n","description":"Las noticias al momento","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/657e7c20ff5297f317664d985712e8e8","name":"MD","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a769375eedc94419a5b67bc5d63567af?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a769375eedc94419a5b67bc5d63567af?s=96&d=mm&r=g","caption":"MD"},"url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/author\/merelydpa\/"}]}},"_links":{"self":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/59301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/comments?post=59301"}],"version-history":[{"count":1,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/59301\/revisions"}],"predecessor-version":[{"id":59305,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/59301\/revisions\/59305"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/media\/59303"}],"wp:attachment":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/media?parent=59301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/categories?post=59301"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/tags?post=59301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}