{"id":60999,"date":"2025-06-01T14:06:12","date_gmt":"2025-06-01T20:06:12","guid":{"rendered":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?p=60999"},"modified":"2025-06-01T14:10:21","modified_gmt":"2025-06-01T20:10:21","slug":"michoacan-recupera-espacios-publicos-con-torneo-de-futbol-sesesp","status":"publish","type":"post","link":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/michoacan-recupera-espacios-publicos-con-torneo-de-futbol-sesesp\/","title":{"rendered":"Michoac\u00e1n recupera espacios p\u00fablicos con torneo de f\u00fatbol: SESESP"},"content":{"rendered":"<p>Participan 600 equipos en 40 municipios para promover la sana convivencia<\/p>\n<hr \/>\n<p>Zamora, Michoac\u00e1n.- El Gobierno de Michoac\u00e1n, a trav\u00e9s del Secretariado Ejecutivo del Sistema Estatal de Seguridad P\u00fablica (SESESP), llev\u00f3 a cabo en Zamora la inauguraci\u00f3n del 1er Torneo Estatal de F\u00fatbol 7 Fortapaz \u201cJuguemos por la Paz\u201d, el cual se realizar\u00e1 en 40 municipios del estado y contar\u00e1 con la participaci\u00f3n de m\u00e1s de 600 equipos.<\/p>\n<p>El torneo es una de las acciones que impulsa el SESESP a trav\u00e9s del Fondo para el Fortalecimiento para la Paz (Fortapaz) y tiene como objetivo promover la sana convivencia y la reconstrucci\u00f3n del tejido social a trav\u00e9s del deporte.<\/p>\n<p>Los municipios que participar\u00e1n en esta justa deportiva son los 40 que fueron beneficiados con la construcci\u00f3n de las canchas de f\u00fatbol 7 del Fortapaz, entre los que se encuentran Apatzing\u00e1n, Hidalgo, Huetamo, Jacona, L\u00e1zaro C\u00e1rdenas, Morelia, P\u00e1tzcuaro, Perib\u00e1n, Sahuayo, Salvador Escalante, Tac\u00e1mbaro, Tar\u00edmbaro, Uruapan, Yur\u00e9cuaro y Ziracuaretiro, entre otros.<\/p>\n<p>El titular del SESESP, C\u00e9sar Erwin S\u00e1nchez Coria, se\u00f1al\u00f3 que este torneo va m\u00e1s all\u00e1 de la competencia deportiva: \u201ces una herramienta para consolidar una cultura de paz, rescatando y apropi\u00e1ndonos de los espacios p\u00fablicos, transform\u00e1ndolos en lugares seguros, llenos de vida y esperanza, donde el deporte se convierte en un veh\u00edculo para el cambio\u201d.<\/p>\n<p>Tras esta primera jornada de competencia, los ganadores fueron: en la categor\u00eda infantil, el triunfo fue para Nacional Am\u00e9rica en ramas femenil y varonil; en adolescentes, Leonas Valencia se coron\u00f3 en femenil y Brazzimo en varonil; finalmente, en la categor\u00eda j\u00f3venes, Cobra destac\u00f3 en femenil y Leones Valencia en varonil.<\/p>\n<p>Cada uno de estos equipos recibieron un incentivo econ\u00f3mico de 5 mil pesos, como reconocimiento a su esfuerzo, disciplina y compromiso con la construcci\u00f3n de una comunidad m\u00e1s segura y unida.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-61000\" src=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/06\/IMG-20250601-WA0111.jpg\" alt=\"\" width=\"1600\" height=\"1066\" srcset=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/06\/IMG-20250601-WA0111.jpg 1600w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/06\/IMG-20250601-WA0111-500x333.jpg 500w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/06\/IMG-20250601-WA0111-1024x682.jpg 1024w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/06\/IMG-20250601-WA0111-768x512.jpg 768w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/06\/IMG-20250601-WA0111-1536x1023.jpg 1536w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/06\/IMG-20250601-WA0111-630x420.jpg 630w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/06\/IMG-20250601-WA0111-150x100.jpg 150w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/06\/IMG-20250601-WA0111-300x200.jpg 300w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/06\/IMG-20250601-WA0111-696x464.jpg 696w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/06\/IMG-20250601-WA0111-1068x712.jpg 1068w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-61002\" src=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/06\/IMG-20250601-WA0108.jpg\" alt=\"\" width=\"1600\" height=\"1066\" srcset=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/06\/IMG-20250601-WA0108.jpg 1600w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/06\/IMG-20250601-WA0108-500x333.jpg 500w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/06\/IMG-20250601-WA0108-1024x682.jpg 1024w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/06\/IMG-20250601-WA0108-768x512.jpg 768w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/06\/IMG-20250601-WA0108-1536x1023.jpg 1536w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/06\/IMG-20250601-WA0108-630x420.jpg 630w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/06\/IMG-20250601-WA0108-150x100.jpg 150w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/06\/IMG-20250601-WA0108-300x200.jpg 300w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/06\/IMG-20250601-WA0108-696x464.jpg 696w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/06\/IMG-20250601-WA0108-1068x712.jpg 1068w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-61003\" src=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/06\/IMG-20250601-WA0109.jpg\" alt=\"\" width=\"1600\" height=\"1066\" srcset=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/06\/IMG-20250601-WA0109.jpg 1600w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/06\/IMG-20250601-WA0109-500x333.jpg 500w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/06\/IMG-20250601-WA0109-1024x682.jpg 1024w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/06\/IMG-20250601-WA0109-768x512.jpg 768w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/06\/IMG-20250601-WA0109-1536x1023.jpg 1536w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/06\/IMG-20250601-WA0109-630x420.jpg 630w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/06\/IMG-20250601-WA0109-150x100.jpg 150w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/06\/IMG-20250601-WA0109-300x200.jpg 300w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/06\/IMG-20250601-WA0109-696x464.jpg 696w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/06\/IMG-20250601-WA0109-1068x712.jpg 1068w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/>COMUNICADO.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Participan 600 equipos en 40 municipios para promover la sana convivencia Zamora, Michoac\u00e1n.- El Gobierno de Michoac\u00e1n, a trav\u00e9s del Secretariado Ejecutivo del Sistema Estatal de Seguridad P\u00fablica (SESESP), llev\u00f3 a cabo en Zamora la inauguraci\u00f3n del 1er Torneo Estatal de F\u00fatbol 7 Fortapaz \u201cJuguemos por la Paz\u201d, el cual se realizar\u00e1 en 40 municipios [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":61001,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,10,17],"tags":[],"class_list":{"0":"post-60999","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-deportes","8":"category-estado","9":"category-gobierno-de-michoacan"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Michoac\u00e1n recupera espacios p\u00fablicos con torneo de f\u00fatbol: SESESP - Diario ABC de Michoac\u00e1n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/michoacan-recupera-espacios-publicos-con-torneo-de-futbol-sesesp\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Michoac\u00e1n recupera espacios p\u00fablicos con torneo de f\u00fatbol: SESESP - Diario ABC de Michoac\u00e1n\" \/>\n<meta property=\"og:description\" content=\"Participan 600 equipos en 40 municipios para promover la sana convivencia Zamora, Michoac\u00e1n.- El Gobierno de Michoac\u00e1n, a trav\u00e9s del Secretariado Ejecutivo del Sistema Estatal de Seguridad P\u00fablica (SESESP), llev\u00f3 a cabo en Zamora la inauguraci\u00f3n del 1er Torneo Estatal de F\u00fatbol 7 Fortapaz \u201cJuguemos por la Paz\u201d, el cual se realizar\u00e1 en 40 municipios [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/michoacan-recupera-espacios-publicos-con-torneo-de-futbol-sesesp\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario ABC de Michoac\u00e1n\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-01T20:06:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-01T20:10:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/06\/IMG-20250601-WA0110.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MB\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MB\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/michoacan-recupera-espacios-publicos-con-torneo-de-futbol-sesesp\/\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/michoacan-recupera-espacios-publicos-con-torneo-de-futbol-sesesp\/\",\"name\":\"Michoac\u00e1n recupera espacios p\u00fablicos con torneo de f\u00fatbol: SESESP - Diario ABC de Michoac\u00e1n\",\"isPartOf\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/michoacan-recupera-espacios-publicos-con-torneo-de-futbol-sesesp\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/michoacan-recupera-espacios-publicos-con-torneo-de-futbol-sesesp\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/06\/IMG-20250601-WA0110.jpg\",\"datePublished\":\"2025-06-01T20:06:12+00:00\",\"dateModified\":\"2025-06-01T20:10:21+00:00\",\"author\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/0546f9c3407148f7452ca932715c5e88\"},\"breadcrumb\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/michoacan-recupera-espacios-publicos-con-torneo-de-futbol-sesesp\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/michoacan-recupera-espacios-publicos-con-torneo-de-futbol-sesesp\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/michoacan-recupera-espacios-publicos-con-torneo-de-futbol-sesesp\/#primaryimage\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/06\/IMG-20250601-WA0110.jpg\",\"contentUrl\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/06\/IMG-20250601-WA0110.jpg\",\"width\":1280,\"height\":853},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/michoacan-recupera-espacios-publicos-con-torneo-de-futbol-sesesp\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Michoac\u00e1n recupera espacios p\u00fablicos con torneo de f\u00fatbol: SESESP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/\",\"name\":\"Diario ABC de Michoac\u00e1n\",\"description\":\"Las noticias al momento\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/0546f9c3407148f7452ca932715c5e88\",\"name\":\"MB\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/adcd41fde6b8d0b5d9d0de001d3112b3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/adcd41fde6b8d0b5d9d0de001d3112b3?s=96&d=mm&r=g\",\"caption\":\"MB\"},\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/author\/bomariano03\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Michoac\u00e1n recupera espacios p\u00fablicos con torneo de f\u00fatbol: SESESP - Diario ABC de Michoac\u00e1n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/michoacan-recupera-espacios-publicos-con-torneo-de-futbol-sesesp\/","og_locale":"es_ES","og_type":"article","og_title":"Michoac\u00e1n recupera espacios p\u00fablicos con torneo de f\u00fatbol: SESESP - Diario ABC de Michoac\u00e1n","og_description":"Participan 600 equipos en 40 municipios para promover la sana convivencia Zamora, Michoac\u00e1n.- El Gobierno de Michoac\u00e1n, a trav\u00e9s del Secretariado Ejecutivo del Sistema Estatal de Seguridad P\u00fablica (SESESP), llev\u00f3 a cabo en Zamora la inauguraci\u00f3n del 1er Torneo Estatal de F\u00fatbol 7 Fortapaz \u201cJuguemos por la Paz\u201d, el cual se realizar\u00e1 en 40 municipios [&hellip;]","og_url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/michoacan-recupera-espacios-publicos-con-torneo-de-futbol-sesesp\/","og_site_name":"Diario ABC de Michoac\u00e1n","article_published_time":"2025-06-01T20:06:12+00:00","article_modified_time":"2025-06-01T20:10:21+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/06\/IMG-20250601-WA0110.jpg","type":"image\/jpeg"}],"author":"MB","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"MB","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/michoacan-recupera-espacios-publicos-con-torneo-de-futbol-sesesp\/","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/michoacan-recupera-espacios-publicos-con-torneo-de-futbol-sesesp\/","name":"Michoac\u00e1n recupera espacios p\u00fablicos con torneo de f\u00fatbol: SESESP - Diario ABC de Michoac\u00e1n","isPartOf":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/michoacan-recupera-espacios-publicos-con-torneo-de-futbol-sesesp\/#primaryimage"},"image":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/michoacan-recupera-espacios-publicos-con-torneo-de-futbol-sesesp\/#primaryimage"},"thumbnailUrl":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/06\/IMG-20250601-WA0110.jpg","datePublished":"2025-06-01T20:06:12+00:00","dateModified":"2025-06-01T20:10:21+00:00","author":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/0546f9c3407148f7452ca932715c5e88"},"breadcrumb":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/michoacan-recupera-espacios-publicos-con-torneo-de-futbol-sesesp\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/michoacan-recupera-espacios-publicos-con-torneo-de-futbol-sesesp\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/michoacan-recupera-espacios-publicos-con-torneo-de-futbol-sesesp\/#primaryimage","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/06\/IMG-20250601-WA0110.jpg","contentUrl":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/06\/IMG-20250601-WA0110.jpg","width":1280,"height":853},{"@type":"BreadcrumbList","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/michoacan-recupera-espacios-publicos-con-torneo-de-futbol-sesesp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/"},{"@type":"ListItem","position":2,"name":"Michoac\u00e1n recupera espacios p\u00fablicos con torneo de f\u00fatbol: SESESP"}]},{"@type":"WebSite","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/","name":"Diario ABC de Michoac\u00e1n","description":"Las noticias al momento","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/0546f9c3407148f7452ca932715c5e88","name":"MB","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/adcd41fde6b8d0b5d9d0de001d3112b3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/adcd41fde6b8d0b5d9d0de001d3112b3?s=96&d=mm&r=g","caption":"MB"},"url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/author\/bomariano03\/"}]}},"_links":{"self":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/60999","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/comments?post=60999"}],"version-history":[{"count":1,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/60999\/revisions"}],"predecessor-version":[{"id":61004,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/60999\/revisions\/61004"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/media\/61001"}],"wp:attachment":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/media?parent=60999"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/categories?post=60999"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/tags?post=60999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}