{"id":64283,"date":"2025-07-02T16:00:01","date_gmt":"2025-07-02T22:00:01","guid":{"rendered":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?p=64283"},"modified":"2025-07-02T16:00:01","modified_gmt":"2025-07-02T22:00:01","slug":"presenta-fabiola-alanis-reforma-integral-para-mejorar-seguridad-de-las-mujeres","status":"publish","type":"post","link":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/presenta-fabiola-alanis-reforma-integral-para-mejorar-seguridad-de-las-mujeres\/","title":{"rendered":"Presenta Fabiola Alan\u00eds reforma integral para mejorar seguridad de las mujeres"},"content":{"rendered":"<h2>Se establece la creaci\u00f3n de la Fiscal\u00eda Especializada para Atenci\u00f3n de Delitos de G\u00e9nero y se fortalecen \u00f3rdenes de protecci\u00f3n<\/h2>\n<ul>\n<li>Adelant\u00f3 que se requieren reformas para atenci\u00f3n y sanci\u00f3n de la violencia pol\u00edtica en raz\u00f3n de g\u00e9nero.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<hr \/>\n<p>Morelia, Mich., 2 de julio de 2025.- Armonizar la Ley por una Vida Libre de Violencia para las Mujeres en Michoac\u00e1n, conforme a las reformas constitucionales enviadas por la Presidenta Claudia Sheinbaum Pardo, garantizar\u00e1 que las mujeres michoacanas cuenten con servicios suficientes, adecuados, especializados e integrales para la atenci\u00f3n y el acceso a la justicia, explic\u00f3 la diputada Fabiola Alan\u00eds S\u00e1mano, al presentar la iniciativa ante el pleno del Congreso del Estado.<\/p>\n<p>En sesi\u00f3n ordinaria de este mi\u00e9rcoles, la coordinadora del Grupo Parlamentario de Morena se\u00f1al\u00f3 que esta iniciativa de reforma integral de la ley obligar\u00e1 a un mejor funcionamiento de las instituciones, que contribuir\u00e1 a mejorar la seguridad y la atenci\u00f3n integral para quienes viven violencia en raz\u00f3n de g\u00e9nero en Michoac\u00e1n.<\/p>\n<p>Cabe destacar que esta iniciativa consiste en el fortalecimiento de principios y en la mejora de los procesos de coordinaci\u00f3n entre estado, municipios y concejos municipales, para desplegar las acciones encaminadas a garantizar el derecho de las mujeres, las j\u00f3venes y las ni\u00f1as a una vida libre de violencia.<\/p>\n<p>Agreg\u00f3 que un elemento fundamental es la obligaci\u00f3n de fortalecer y contar con los recursos suficientes para la creaci\u00f3n de fiscal\u00edas especializadas en la atenci\u00f3n a delitos de violencia de g\u00e9nero, la operaci\u00f3n de los Centros de Justicia para las Mujeres y el sostenimiento de refugios especializados; adem\u00e1s, se propuso armonizar el apartado referente a \u00f3rdenes y medidas de protecci\u00f3n, que ser\u00edan operadas y monitoreadas por la Secretar\u00eda de Seguridad P\u00fablica, a fin de otorgar protecci\u00f3n inmediata a mujeres en situaci\u00f3n de riesgo.<\/p>\n<p>La presidenta de la Junta de Coordinaci\u00f3n Pol\u00edtica del Congreso del Estado adelant\u00f3 que se requieren reformas adicionales para que las instituciones michoacanas respondan a las necesidades de las mujeres, principalmente, para que se elimine la concepci\u00f3n de que la violencia contra las mujeres es un asunto del \u00e1mbito privado; por lo que consider\u00f3 necesario modificar diversos ordenamientos para alinearlos a las recomendaciones internacionales en materia de derechos humanos de las mujeres.<\/p>\n<p>Entre \u00e9stos, se\u00f1al\u00f3 la diputada Fabiola Alan\u00eds, se encuentran los procedimientos y las atribuciones de las instituciones encargadas de atender y sancionar la violencia pol\u00edtica por raz\u00f3n de g\u00e9nero, que a\u00fan es un pendiente por resolver en la entidad dentro de estructuras como la del Instituto Electoral de Michoac\u00e1n y del propio Congreso del Estado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se establece la creaci\u00f3n de la Fiscal\u00eda Especializada para Atenci\u00f3n de Delitos de G\u00e9nero y se fortalecen \u00f3rdenes de protecci\u00f3n Adelant\u00f3 que se requieren reformas para atenci\u00f3n y sanci\u00f3n de la violencia pol\u00edtica en raz\u00f3n de g\u00e9nero. &nbsp; Morelia, Mich., 2 de julio de 2025.- Armonizar la Ley por una Vida Libre de Violencia para [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":64285,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,22,28,27],"tags":[],"class_list":{"0":"post-64283","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-congreso","8":"category-congreso-de-michoacan","9":"category-politica","10":"category-slider"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Presenta Fabiola Alan\u00eds reforma integral para mejorar seguridad de las mujeres - Diario ABC de Michoac\u00e1n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/presenta-fabiola-alanis-reforma-integral-para-mejorar-seguridad-de-las-mujeres\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Presenta Fabiola Alan\u00eds reforma integral para mejorar seguridad de las mujeres - Diario ABC de Michoac\u00e1n\" \/>\n<meta property=\"og:description\" content=\"Se establece la creaci\u00f3n de la Fiscal\u00eda Especializada para Atenci\u00f3n de Delitos de G\u00e9nero y se fortalecen \u00f3rdenes de protecci\u00f3n Adelant\u00f3 que se requieren reformas para atenci\u00f3n y sanci\u00f3n de la violencia pol\u00edtica en raz\u00f3n de g\u00e9nero. &nbsp; Morelia, Mich., 2 de julio de 2025.- Armonizar la Ley por una Vida Libre de Violencia para [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/presenta-fabiola-alanis-reforma-integral-para-mejorar-seguridad-de-las-mujeres\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario ABC de Michoac\u00e1n\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-02T22:00:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/Imagen-de-WhatsApp-2025-07-02-a-las-15.35.05_efe0a47f-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"AR\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"AR\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/presenta-fabiola-alanis-reforma-integral-para-mejorar-seguridad-de-las-mujeres\/\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/presenta-fabiola-alanis-reforma-integral-para-mejorar-seguridad-de-las-mujeres\/\",\"name\":\"Presenta Fabiola Alan\u00eds reforma integral para mejorar seguridad de las mujeres - Diario ABC de Michoac\u00e1n\",\"isPartOf\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/presenta-fabiola-alanis-reforma-integral-para-mejorar-seguridad-de-las-mujeres\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/presenta-fabiola-alanis-reforma-integral-para-mejorar-seguridad-de-las-mujeres\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/Imagen-de-WhatsApp-2025-07-02-a-las-15.35.05_efe0a47f-scaled.jpg\",\"datePublished\":\"2025-07-02T22:00:01+00:00\",\"dateModified\":\"2025-07-02T22:00:01+00:00\",\"author\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/19ae376040f6cbc489682ebdd8524852\"},\"breadcrumb\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/presenta-fabiola-alanis-reforma-integral-para-mejorar-seguridad-de-las-mujeres\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/presenta-fabiola-alanis-reforma-integral-para-mejorar-seguridad-de-las-mujeres\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/presenta-fabiola-alanis-reforma-integral-para-mejorar-seguridad-de-las-mujeres\/#primaryimage\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/Imagen-de-WhatsApp-2025-07-02-a-las-15.35.05_efe0a47f-scaled.jpg\",\"contentUrl\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/Imagen-de-WhatsApp-2025-07-02-a-las-15.35.05_efe0a47f-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/presenta-fabiola-alanis-reforma-integral-para-mejorar-seguridad-de-las-mujeres\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Presenta Fabiola Alan\u00eds reforma integral para mejorar seguridad de las mujeres\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/\",\"name\":\"Diario ABC de Michoac\u00e1n\",\"description\":\"Las noticias al momento\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/19ae376040f6cbc489682ebdd8524852\",\"name\":\"AR\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/44eca2ff970262234e20e1e082872af0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/44eca2ff970262234e20e1e082872af0?s=96&d=mm&r=g\",\"caption\":\"AR\"},\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/author\/adrian\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Presenta Fabiola Alan\u00eds reforma integral para mejorar seguridad de las mujeres - Diario ABC de Michoac\u00e1n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/presenta-fabiola-alanis-reforma-integral-para-mejorar-seguridad-de-las-mujeres\/","og_locale":"es_ES","og_type":"article","og_title":"Presenta Fabiola Alan\u00eds reforma integral para mejorar seguridad de las mujeres - Diario ABC de Michoac\u00e1n","og_description":"Se establece la creaci\u00f3n de la Fiscal\u00eda Especializada para Atenci\u00f3n de Delitos de G\u00e9nero y se fortalecen \u00f3rdenes de protecci\u00f3n Adelant\u00f3 que se requieren reformas para atenci\u00f3n y sanci\u00f3n de la violencia pol\u00edtica en raz\u00f3n de g\u00e9nero. &nbsp; Morelia, Mich., 2 de julio de 2025.- Armonizar la Ley por una Vida Libre de Violencia para [&hellip;]","og_url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/presenta-fabiola-alanis-reforma-integral-para-mejorar-seguridad-de-las-mujeres\/","og_site_name":"Diario ABC de Michoac\u00e1n","article_published_time":"2025-07-02T22:00:01+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/Imagen-de-WhatsApp-2025-07-02-a-las-15.35.05_efe0a47f-scaled.jpg","type":"image\/jpeg"}],"author":"AR","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"AR","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/presenta-fabiola-alanis-reforma-integral-para-mejorar-seguridad-de-las-mujeres\/","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/presenta-fabiola-alanis-reforma-integral-para-mejorar-seguridad-de-las-mujeres\/","name":"Presenta Fabiola Alan\u00eds reforma integral para mejorar seguridad de las mujeres - Diario ABC de Michoac\u00e1n","isPartOf":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/presenta-fabiola-alanis-reforma-integral-para-mejorar-seguridad-de-las-mujeres\/#primaryimage"},"image":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/presenta-fabiola-alanis-reforma-integral-para-mejorar-seguridad-de-las-mujeres\/#primaryimage"},"thumbnailUrl":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/Imagen-de-WhatsApp-2025-07-02-a-las-15.35.05_efe0a47f-scaled.jpg","datePublished":"2025-07-02T22:00:01+00:00","dateModified":"2025-07-02T22:00:01+00:00","author":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/19ae376040f6cbc489682ebdd8524852"},"breadcrumb":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/presenta-fabiola-alanis-reforma-integral-para-mejorar-seguridad-de-las-mujeres\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/presenta-fabiola-alanis-reforma-integral-para-mejorar-seguridad-de-las-mujeres\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/presenta-fabiola-alanis-reforma-integral-para-mejorar-seguridad-de-las-mujeres\/#primaryimage","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/Imagen-de-WhatsApp-2025-07-02-a-las-15.35.05_efe0a47f-scaled.jpg","contentUrl":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/Imagen-de-WhatsApp-2025-07-02-a-las-15.35.05_efe0a47f-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/presenta-fabiola-alanis-reforma-integral-para-mejorar-seguridad-de-las-mujeres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/"},{"@type":"ListItem","position":2,"name":"Presenta Fabiola Alan\u00eds reforma integral para mejorar seguridad de las mujeres"}]},{"@type":"WebSite","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/","name":"Diario ABC de Michoac\u00e1n","description":"Las noticias al momento","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/19ae376040f6cbc489682ebdd8524852","name":"AR","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/44eca2ff970262234e20e1e082872af0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/44eca2ff970262234e20e1e082872af0?s=96&d=mm&r=g","caption":"AR"},"url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/author\/adrian\/"}]}},"_links":{"self":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/64283","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/comments?post=64283"}],"version-history":[{"count":1,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/64283\/revisions"}],"predecessor-version":[{"id":64286,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/64283\/revisions\/64286"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/media\/64285"}],"wp:attachment":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/media?parent=64283"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/categories?post=64283"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/tags?post=64283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}