{"id":64962,"date":"2025-07-13T13:44:46","date_gmt":"2025-07-13T19:44:46","guid":{"rendered":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?p=64962"},"modified":"2025-07-13T13:44:46","modified_gmt":"2025-07-13T19:44:46","slug":"sumergete-en-la-diversion-con-la-espectacular-pecera-360-del-zoologico-de-morelia","status":"publish","type":"post","link":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/sumergete-en-la-diversion-con-la-espectacular-pecera-360-del-zoologico-de-morelia\/","title":{"rendered":"Sum\u00e9rgete en la diversi\u00f3n con la espectacular pecera 360\u00b0 del Zool\u00f3gico de Morelia"},"content":{"rendered":"<p>A partir de ma\u00f1ana los visitantes vivir\u00e1n una gran experiencia con esta instalaci\u00f3n \u00fanica en el pa\u00eds<\/p>\n<hr \/>\n<p>Morelia, Michoac\u00e1n.- El director del Zool\u00f3gico de Morelia, Julio C\u00e9sar Medina \u00c1vila, anunci\u00f3 que el d\u00eda de ma\u00f1ana se llevar\u00e1 a cabo la inauguraci\u00f3n de la nueva pecera 360\u00b0, una instalaci\u00f3n \u00fanica en el pa\u00eds que enriquecer\u00e1 la experiencia de los visitantes y reforzar\u00e1 su compromiso con la conservaci\u00f3n y educaci\u00f3n ambiental.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-64968\" src=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0054.jpg\" alt=\"\" width=\"1600\" height=\"1200\" srcset=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0054.jpg 1600w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0054-500x375.jpg 500w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0054-1024x768.jpg 1024w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0054-768x576.jpg 768w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0054-1536x1152.jpg 1536w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0054-560x420.jpg 560w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0054-80x60.jpg 80w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0054-150x113.jpg 150w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0054-300x225.jpg 300w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0054-696x522.jpg 696w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0054-1068x801.jpg 1068w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/p>\n<p>Explic\u00f3 que esta innovadora pecera, con capacidad para 17 mil litros de agua, est\u00e1 especialmente dise\u00f1ada para albergar rayas en un ambiente que recrea un h\u00e1bitat amaz\u00f3nico, permitiendo al p\u00fablico sumergirse visualmente en el fascinante mundo de estos extraordinarios animales. Gracias a su dise\u00f1o de visi\u00f3n panor\u00e1mica, los visitantes podr\u00e1n observar a las rayas desde todos los \u00e1ngulos, generando una experiencia inmersiva, sin precedentes en M\u00e9xico.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-64967\" src=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0053.jpg\" alt=\"\" width=\"1600\" height=\"1200\" srcset=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0053.jpg 1600w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0053-500x375.jpg 500w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0053-1024x768.jpg 1024w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0053-768x576.jpg 768w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0053-1536x1152.jpg 1536w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0053-560x420.jpg 560w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0053-80x60.jpg 80w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0053-150x113.jpg 150w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0053-300x225.jpg 300w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0053-696x522.jpg 696w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0053-1068x801.jpg 1068w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/p>\n<p>Con 18 a\u00f1os de historia, el acuario del Zool\u00f3gico de Morelia es uno de los principales atractivos tur\u00edsticos y educativos del estado de Michoac\u00e1n. Con esta nueva atracci\u00f3n, reafirma su posici\u00f3n como referente nacional en exhibici\u00f3n y conservaci\u00f3n de fauna acu\u00e1tica.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-64965\" src=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0051.jpg\" alt=\"\" width=\"1600\" height=\"1200\" srcset=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0051.jpg 1600w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0051-500x375.jpg 500w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0051-1024x768.jpg 1024w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0051-768x576.jpg 768w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0051-1536x1152.jpg 1536w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0051-560x420.jpg 560w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0051-80x60.jpg 80w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0051-150x113.jpg 150w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0051-300x225.jpg 300w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0051-696x522.jpg 696w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0051-1068x801.jpg 1068w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/p>\n<p>\u201cEstamos muy orgullosos de presentar esta pecera 360\u00b0, un proyecto pensado para ofrecer a nuestros visitantes una experiencia \u00fanica y fomentar el respeto y cuidado hacia las especies acu\u00e1ticas y sus ecosistemas\u201d, expres\u00f3 Medina \u00c1vila.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-64964\" src=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0055.jpg\" alt=\"\" width=\"1600\" height=\"1200\" srcset=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0055.jpg 1600w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0055-500x375.jpg 500w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0055-1024x768.jpg 1024w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0055-768x576.jpg 768w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0055-1536x1152.jpg 1536w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0055-560x420.jpg 560w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0055-80x60.jpg 80w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0055-150x113.jpg 150w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0055-300x225.jpg 300w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0055-696x522.jpg 696w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0055-1068x801.jpg 1068w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/p>\n<p>El Zool\u00f3gico de Morelia invita a la poblaci\u00f3n michoacana a conocer esta nueva joya que enriquecer\u00e1 el patrimonio natural y tur\u00edstico de Michoac\u00e1n.<\/p>\n<p>COMUNICADO.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir de ma\u00f1ana los visitantes vivir\u00e1n una gran experiencia con esta instalaci\u00f3n \u00fanica en el pa\u00eds Morelia, Michoac\u00e1n.- El director del Zool\u00f3gico de Morelia, Julio C\u00e9sar Medina \u00c1vila, anunci\u00f3 que el d\u00eda de ma\u00f1ana se llevar\u00e1 a cabo la inauguraci\u00f3n de la nueva pecera 360\u00b0, una instalaci\u00f3n \u00fanica en el pa\u00eds que enriquecer\u00e1 la [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":64969,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,17,7],"tags":[],"class_list":{"0":"post-64962","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-estado","8":"category-gobierno-de-michoacan","9":"category-morelia"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sum\u00e9rgete en la diversi\u00f3n con la espectacular pecera 360\u00b0 del Zool\u00f3gico de Morelia - Diario ABC de Michoac\u00e1n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/sumergete-en-la-diversion-con-la-espectacular-pecera-360-del-zoologico-de-morelia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sum\u00e9rgete en la diversi\u00f3n con la espectacular pecera 360\u00b0 del Zool\u00f3gico de Morelia - Diario ABC de Michoac\u00e1n\" \/>\n<meta property=\"og:description\" content=\"A partir de ma\u00f1ana los visitantes vivir\u00e1n una gran experiencia con esta instalaci\u00f3n \u00fanica en el pa\u00eds Morelia, Michoac\u00e1n.- El director del Zool\u00f3gico de Morelia, Julio C\u00e9sar Medina \u00c1vila, anunci\u00f3 que el d\u00eda de ma\u00f1ana se llevar\u00e1 a cabo la inauguraci\u00f3n de la nueva pecera 360\u00b0, una instalaci\u00f3n \u00fanica en el pa\u00eds que enriquecer\u00e1 la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/sumergete-en-la-diversion-con-la-espectacular-pecera-360-del-zoologico-de-morelia\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario ABC de Michoac\u00e1n\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-13T19:44:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0057-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MB\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MB\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/sumergete-en-la-diversion-con-la-espectacular-pecera-360-del-zoologico-de-morelia\/\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/sumergete-en-la-diversion-con-la-espectacular-pecera-360-del-zoologico-de-morelia\/\",\"name\":\"Sum\u00e9rgete en la diversi\u00f3n con la espectacular pecera 360\u00b0 del Zool\u00f3gico de Morelia - Diario ABC de Michoac\u00e1n\",\"isPartOf\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/sumergete-en-la-diversion-con-la-espectacular-pecera-360-del-zoologico-de-morelia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/sumergete-en-la-diversion-con-la-espectacular-pecera-360-del-zoologico-de-morelia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0057-scaled.jpg\",\"datePublished\":\"2025-07-13T19:44:46+00:00\",\"dateModified\":\"2025-07-13T19:44:46+00:00\",\"author\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/0546f9c3407148f7452ca932715c5e88\"},\"breadcrumb\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/sumergete-en-la-diversion-con-la-espectacular-pecera-360-del-zoologico-de-morelia\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/sumergete-en-la-diversion-con-la-espectacular-pecera-360-del-zoologico-de-morelia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/sumergete-en-la-diversion-con-la-espectacular-pecera-360-del-zoologico-de-morelia\/#primaryimage\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0057-scaled.jpg\",\"contentUrl\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0057-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/sumergete-en-la-diversion-con-la-espectacular-pecera-360-del-zoologico-de-morelia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sum\u00e9rgete en la diversi\u00f3n con la espectacular pecera 360\u00b0 del Zool\u00f3gico de Morelia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/\",\"name\":\"Diario ABC de Michoac\u00e1n\",\"description\":\"Las noticias al momento\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/0546f9c3407148f7452ca932715c5e88\",\"name\":\"MB\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/adcd41fde6b8d0b5d9d0de001d3112b3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/adcd41fde6b8d0b5d9d0de001d3112b3?s=96&d=mm&r=g\",\"caption\":\"MB\"},\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/author\/bomariano03\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sum\u00e9rgete en la diversi\u00f3n con la espectacular pecera 360\u00b0 del Zool\u00f3gico de Morelia - Diario ABC de Michoac\u00e1n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/sumergete-en-la-diversion-con-la-espectacular-pecera-360-del-zoologico-de-morelia\/","og_locale":"es_ES","og_type":"article","og_title":"Sum\u00e9rgete en la diversi\u00f3n con la espectacular pecera 360\u00b0 del Zool\u00f3gico de Morelia - Diario ABC de Michoac\u00e1n","og_description":"A partir de ma\u00f1ana los visitantes vivir\u00e1n una gran experiencia con esta instalaci\u00f3n \u00fanica en el pa\u00eds Morelia, Michoac\u00e1n.- El director del Zool\u00f3gico de Morelia, Julio C\u00e9sar Medina \u00c1vila, anunci\u00f3 que el d\u00eda de ma\u00f1ana se llevar\u00e1 a cabo la inauguraci\u00f3n de la nueva pecera 360\u00b0, una instalaci\u00f3n \u00fanica en el pa\u00eds que enriquecer\u00e1 la [&hellip;]","og_url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/sumergete-en-la-diversion-con-la-espectacular-pecera-360-del-zoologico-de-morelia\/","og_site_name":"Diario ABC de Michoac\u00e1n","article_published_time":"2025-07-13T19:44:46+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0057-scaled.jpg","type":"image\/jpeg"}],"author":"MB","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"MB","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/sumergete-en-la-diversion-con-la-espectacular-pecera-360-del-zoologico-de-morelia\/","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/sumergete-en-la-diversion-con-la-espectacular-pecera-360-del-zoologico-de-morelia\/","name":"Sum\u00e9rgete en la diversi\u00f3n con la espectacular pecera 360\u00b0 del Zool\u00f3gico de Morelia - Diario ABC de Michoac\u00e1n","isPartOf":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/sumergete-en-la-diversion-con-la-espectacular-pecera-360-del-zoologico-de-morelia\/#primaryimage"},"image":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/sumergete-en-la-diversion-con-la-espectacular-pecera-360-del-zoologico-de-morelia\/#primaryimage"},"thumbnailUrl":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0057-scaled.jpg","datePublished":"2025-07-13T19:44:46+00:00","dateModified":"2025-07-13T19:44:46+00:00","author":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/0546f9c3407148f7452ca932715c5e88"},"breadcrumb":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/sumergete-en-la-diversion-con-la-espectacular-pecera-360-del-zoologico-de-morelia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/sumergete-en-la-diversion-con-la-espectacular-pecera-360-del-zoologico-de-morelia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/sumergete-en-la-diversion-con-la-espectacular-pecera-360-del-zoologico-de-morelia\/#primaryimage","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0057-scaled.jpg","contentUrl":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0057-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/sumergete-en-la-diversion-con-la-espectacular-pecera-360-del-zoologico-de-morelia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/"},{"@type":"ListItem","position":2,"name":"Sum\u00e9rgete en la diversi\u00f3n con la espectacular pecera 360\u00b0 del Zool\u00f3gico de Morelia"}]},{"@type":"WebSite","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/","name":"Diario ABC de Michoac\u00e1n","description":"Las noticias al momento","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/0546f9c3407148f7452ca932715c5e88","name":"MB","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/adcd41fde6b8d0b5d9d0de001d3112b3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/adcd41fde6b8d0b5d9d0de001d3112b3?s=96&d=mm&r=g","caption":"MB"},"url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/author\/bomariano03\/"}]}},"_links":{"self":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/64962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/comments?post=64962"}],"version-history":[{"count":2,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/64962\/revisions"}],"predecessor-version":[{"id":64970,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/64962\/revisions\/64970"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/media\/64969"}],"wp:attachment":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/media?parent=64962"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/categories?post=64962"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/tags?post=64962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}