{"id":65007,"date":"2025-07-13T18:19:28","date_gmt":"2025-07-14T00:19:28","guid":{"rendered":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?p=65007"},"modified":"2025-07-13T18:19:28","modified_gmt":"2025-07-14T00:19:28","slug":"solamente-quedan-cuatro-torres-por-levantar-para-el-teleferico-de-uruapan","status":"publish","type":"post","link":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/solamente-quedan-cuatro-torres-por-levantar-para-el-teleferico-de-uruapan\/","title":{"rendered":"Solamente quedan cuatro torres por levantar para el Telef\u00e9rico de Uruapan"},"content":{"rendered":"<p>Por Roberto Mestizo Ch\u00e1vez<\/p>\n<hr \/>\n<p>Uruapan, Mich.- Solamente quedan por levantar cuatro torres del Telef\u00e9rico de Uruapan, para empezar a tender el alambrado de ese moderno medio de comunicaci\u00f3n en la mancha urbana.<\/p>\n<p>Al respecto, la secretaria de Desarrollo Urbano y Movilidad en el Gobierno del Estado, Gladyz Butanda, inform\u00f3 que las torres pendientes de levantar son la que se ubicar\u00e1n en el predio de lo que fue el Cine Odeon, la de la calle Aquiles Serd\u00e1n y las dos \u00faltimas, ubicadas en la zona poniente.<\/p>\n<p>La funcionaria indic\u00f3 que los trabajos avanzan de acuerdo a lo programado y que a finales de septiembre estar\u00e1n concluidos, para luego pasar a dos meses de prueba y finalmente ponerlo en servicio a finales de noviembre.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-65010\" src=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0098.jpg\" alt=\"\" width=\"1528\" height=\"1528\" srcset=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0098.jpg 1528w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0098-500x500.jpg 500w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0098-1024x1024.jpg 1024w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0098-150x150.jpg 150w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0098-768x768.jpg 768w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0098-420x420.jpg 420w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0098-300x300.jpg 300w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0098-696x696.jpg 696w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0098-1068x1068.jpg 1068w\" sizes=\"auto, (max-width: 1528px) 100vw, 1528px\" \/><\/p>\n<p>En el caso de la torre de la calle Aquiles Serd\u00e1n, inform\u00f3 que se hab\u00edan retrasado los trabajos por no tenerse el material adecuado, pero ya se empez\u00f3 a trabajar en el levantamiento de la torre.<\/p>\n<p>Sobre la torre en el antiguo Cine Odeon, cuyo predio se encuentra resguardado por la Guardia Civil desde el martes anterior, garantiz\u00f3 que no se tendr\u00e1n da\u00f1os en la plaza Izazaga, mejor conocida como Plaza de La Ranita, pues el Instituto Nacional de Antropolog\u00eda e Historia (INAH) ha sido muy claro al se\u00f1alar que en esos trabajos solamente se permitir\u00e1 el acceso de camiones pesados cuando sea estrictamente necesario, pero labores como arrimar las varillas de acero, piedras, cemento, etc., se realizar\u00e1n manualmente.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-65009\" src=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0096.jpg\" alt=\"\" width=\"1528\" height=\"1528\" srcset=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0096.jpg 1528w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0096-500x500.jpg 500w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0096-1024x1024.jpg 1024w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0096-150x150.jpg 150w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0096-768x768.jpg 768w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0096-420x420.jpg 420w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0096-300x300.jpg 300w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0096-696x696.jpg 696w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA0096-1068x1068.jpg 1068w\" sizes=\"auto, (max-width: 1528px) 100vw, 1528px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Roberto Mestizo Ch\u00e1vez Uruapan, Mich.- Solamente quedan por levantar cuatro torres del Telef\u00e9rico de Uruapan, para empezar a tender el alambrado de ese moderno medio de comunicaci\u00f3n en la mancha urbana. Al respecto, la secretaria de Desarrollo Urbano y Movilidad en el Gobierno del Estado, Gladyz Butanda, inform\u00f3 que las torres pendientes de levantar [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":65008,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":{"0":"post-65007","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-uruapan"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Solamente quedan cuatro torres por levantar para el Telef\u00e9rico de Uruapan - Diario ABC de Michoac\u00e1n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/solamente-quedan-cuatro-torres-por-levantar-para-el-teleferico-de-uruapan\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Solamente quedan cuatro torres por levantar para el Telef\u00e9rico de Uruapan - Diario ABC de Michoac\u00e1n\" \/>\n<meta property=\"og:description\" content=\"Por Roberto Mestizo Ch\u00e1vez Uruapan, Mich.- Solamente quedan por levantar cuatro torres del Telef\u00e9rico de Uruapan, para empezar a tender el alambrado de ese moderno medio de comunicaci\u00f3n en la mancha urbana. Al respecto, la secretaria de Desarrollo Urbano y Movilidad en el Gobierno del Estado, Gladyz Butanda, inform\u00f3 que las torres pendientes de levantar [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/solamente-quedan-cuatro-torres-por-levantar-para-el-teleferico-de-uruapan\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario ABC de Michoac\u00e1n\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-14T00:19:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA00952.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1528\" \/>\n\t<meta property=\"og:image:height\" content=\"977\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MB\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MB\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/solamente-quedan-cuatro-torres-por-levantar-para-el-teleferico-de-uruapan\/\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/solamente-quedan-cuatro-torres-por-levantar-para-el-teleferico-de-uruapan\/\",\"name\":\"Solamente quedan cuatro torres por levantar para el Telef\u00e9rico de Uruapan - Diario ABC de Michoac\u00e1n\",\"isPartOf\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/solamente-quedan-cuatro-torres-por-levantar-para-el-teleferico-de-uruapan\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/solamente-quedan-cuatro-torres-por-levantar-para-el-teleferico-de-uruapan\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA00952.jpg\",\"datePublished\":\"2025-07-14T00:19:28+00:00\",\"dateModified\":\"2025-07-14T00:19:28+00:00\",\"author\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/0546f9c3407148f7452ca932715c5e88\"},\"breadcrumb\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/solamente-quedan-cuatro-torres-por-levantar-para-el-teleferico-de-uruapan\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/solamente-quedan-cuatro-torres-por-levantar-para-el-teleferico-de-uruapan\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/solamente-quedan-cuatro-torres-por-levantar-para-el-teleferico-de-uruapan\/#primaryimage\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA00952.jpg\",\"contentUrl\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA00952.jpg\",\"width\":1528,\"height\":977},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/solamente-quedan-cuatro-torres-por-levantar-para-el-teleferico-de-uruapan\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Solamente quedan cuatro torres por levantar para el Telef\u00e9rico de Uruapan\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/\",\"name\":\"Diario ABC de Michoac\u00e1n\",\"description\":\"Las noticias al momento\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/0546f9c3407148f7452ca932715c5e88\",\"name\":\"MB\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/adcd41fde6b8d0b5d9d0de001d3112b3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/adcd41fde6b8d0b5d9d0de001d3112b3?s=96&d=mm&r=g\",\"caption\":\"MB\"},\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/author\/bomariano03\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Solamente quedan cuatro torres por levantar para el Telef\u00e9rico de Uruapan - Diario ABC de Michoac\u00e1n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/solamente-quedan-cuatro-torres-por-levantar-para-el-teleferico-de-uruapan\/","og_locale":"es_ES","og_type":"article","og_title":"Solamente quedan cuatro torres por levantar para el Telef\u00e9rico de Uruapan - Diario ABC de Michoac\u00e1n","og_description":"Por Roberto Mestizo Ch\u00e1vez Uruapan, Mich.- Solamente quedan por levantar cuatro torres del Telef\u00e9rico de Uruapan, para empezar a tender el alambrado de ese moderno medio de comunicaci\u00f3n en la mancha urbana. Al respecto, la secretaria de Desarrollo Urbano y Movilidad en el Gobierno del Estado, Gladyz Butanda, inform\u00f3 que las torres pendientes de levantar [&hellip;]","og_url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/solamente-quedan-cuatro-torres-por-levantar-para-el-teleferico-de-uruapan\/","og_site_name":"Diario ABC de Michoac\u00e1n","article_published_time":"2025-07-14T00:19:28+00:00","og_image":[{"width":1528,"height":977,"url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA00952.jpg","type":"image\/jpeg"}],"author":"MB","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"MB","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/solamente-quedan-cuatro-torres-por-levantar-para-el-teleferico-de-uruapan\/","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/solamente-quedan-cuatro-torres-por-levantar-para-el-teleferico-de-uruapan\/","name":"Solamente quedan cuatro torres por levantar para el Telef\u00e9rico de Uruapan - Diario ABC de Michoac\u00e1n","isPartOf":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/solamente-quedan-cuatro-torres-por-levantar-para-el-teleferico-de-uruapan\/#primaryimage"},"image":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/solamente-quedan-cuatro-torres-por-levantar-para-el-teleferico-de-uruapan\/#primaryimage"},"thumbnailUrl":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA00952.jpg","datePublished":"2025-07-14T00:19:28+00:00","dateModified":"2025-07-14T00:19:28+00:00","author":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/0546f9c3407148f7452ca932715c5e88"},"breadcrumb":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/solamente-quedan-cuatro-torres-por-levantar-para-el-teleferico-de-uruapan\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/solamente-quedan-cuatro-torres-por-levantar-para-el-teleferico-de-uruapan\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/solamente-quedan-cuatro-torres-por-levantar-para-el-teleferico-de-uruapan\/#primaryimage","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA00952.jpg","contentUrl":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250713-WA00952.jpg","width":1528,"height":977},{"@type":"BreadcrumbList","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/solamente-quedan-cuatro-torres-por-levantar-para-el-teleferico-de-uruapan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/"},{"@type":"ListItem","position":2,"name":"Solamente quedan cuatro torres por levantar para el Telef\u00e9rico de Uruapan"}]},{"@type":"WebSite","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/","name":"Diario ABC de Michoac\u00e1n","description":"Las noticias al momento","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/0546f9c3407148f7452ca932715c5e88","name":"MB","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/adcd41fde6b8d0b5d9d0de001d3112b3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/adcd41fde6b8d0b5d9d0de001d3112b3?s=96&d=mm&r=g","caption":"MB"},"url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/author\/bomariano03\/"}]}},"_links":{"self":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/65007","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/comments?post=65007"}],"version-history":[{"count":1,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/65007\/revisions"}],"predecessor-version":[{"id":65011,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/65007\/revisions\/65011"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/media\/65008"}],"wp:attachment":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/media?parent=65007"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/categories?post=65007"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/tags?post=65007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}