{"id":65342,"date":"2025-07-20T19:10:21","date_gmt":"2025-07-21T01:10:21","guid":{"rendered":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?p=65342"},"modified":"2025-07-20T19:10:21","modified_gmt":"2025-07-21T01:10:21","slug":"umsnh-cierra-con-triunfo-la-fase-regular-de-la-primera-fuerza-en-la-liga-municipal","status":"publish","type":"post","link":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/umsnh-cierra-con-triunfo-la-fase-regular-de-la-primera-fuerza-en-la-liga-municipal\/","title":{"rendered":"UMSNH cierra con triunfo la fase regular de la Primera Fuerza en la Liga Municipal"},"content":{"rendered":"<p>La pr\u00f3xima semana el cuadro nicolaita jugar\u00e1 los cuartos de final de esta categor\u00eda<\/p>\n<hr \/>\n<p>Morelia, Michoac\u00e1n. &#8211; El conjunto de la Universidad Michoacana de San Nicol\u00e1s de Hidalgo (UMSNH) que compite en la categor\u00eda de Primera Fuerza de la Liga Municipal de F\u00fatbol Amateur Morelia cerr\u00f3 este domingo la fase regular con un triunfo de 2-0 sobre Resinas Sint\u00e9ticas.<\/p>\n<p>El duelo, que perteneci\u00f3 a la Jornada 34, se desarroll\u00f3 en la cancha de Resinas Sint\u00e9ticas, y se inclin\u00f3 desde muy temprano en favor de los Zorros, cuando al minuto 5 se marc\u00f3 un penal que Emiliano Nambo cambio por gol para poner el 1-0.<\/p>\n<p>Corr\u00eda el 25&#8242; cuando Fredy Vargas recibi\u00f3 un bal\u00f3n dentro del \u00e1rea y defini\u00f3 cruzado para poner el 2-0 con el que se fueron al descanso y que a la postre ser\u00eda definitivo.<\/p>\n<p>Durante el complemento, el cuadro nicolaita sigui\u00f3 llegando con peligro al marco rival en busca de incrementar la ventaja, pero el marcador ya no se movi\u00f3.<\/p>\n<p>Ahora, el cuadro de la Casa de Hidalgo espera a que termine la actividad para conocer a su rival en los cuartos de final, fase que se jugar\u00e1 el pr\u00f3ximo domingo.<\/p>\n<p>COMUNICADO.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La pr\u00f3xima semana el cuadro nicolaita jugar\u00e1 los cuartos de final de esta categor\u00eda Morelia, Michoac\u00e1n. &#8211; El conjunto de la Universidad Michoacana de San Nicol\u00e1s de Hidalgo (UMSNH) que compite en la categor\u00eda de Primera Fuerza de la Liga Municipal de F\u00fatbol Amateur Morelia cerr\u00f3 este domingo la fase regular con un triunfo de [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":65343,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,15,10,23],"tags":[],"class_list":{"0":"post-65342","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-deportes","8":"category-educacion","9":"category-estado","10":"category-universidad-michoacana"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>UMSNH cierra con triunfo la fase regular de la Primera Fuerza en la Liga Municipal - Diario ABC de Michoac\u00e1n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/umsnh-cierra-con-triunfo-la-fase-regular-de-la-primera-fuerza-en-la-liga-municipal\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"UMSNH cierra con triunfo la fase regular de la Primera Fuerza en la Liga Municipal - Diario ABC de Michoac\u00e1n\" \/>\n<meta property=\"og:description\" content=\"La pr\u00f3xima semana el cuadro nicolaita jugar\u00e1 los cuartos de final de esta categor\u00eda Morelia, Michoac\u00e1n. &#8211; El conjunto de la Universidad Michoacana de San Nicol\u00e1s de Hidalgo (UMSNH) que compite en la categor\u00eda de Primera Fuerza de la Liga Municipal de F\u00fatbol Amateur Morelia cerr\u00f3 este domingo la fase regular con un triunfo de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/umsnh-cierra-con-triunfo-la-fase-regular-de-la-primera-fuerza-en-la-liga-municipal\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario ABC de Michoac\u00e1n\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-21T01:10:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250720-WA0095.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MB\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MB\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/umsnh-cierra-con-triunfo-la-fase-regular-de-la-primera-fuerza-en-la-liga-municipal\/\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/umsnh-cierra-con-triunfo-la-fase-regular-de-la-primera-fuerza-en-la-liga-municipal\/\",\"name\":\"UMSNH cierra con triunfo la fase regular de la Primera Fuerza en la Liga Municipal - Diario ABC de Michoac\u00e1n\",\"isPartOf\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/umsnh-cierra-con-triunfo-la-fase-regular-de-la-primera-fuerza-en-la-liga-municipal\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/umsnh-cierra-con-triunfo-la-fase-regular-de-la-primera-fuerza-en-la-liga-municipal\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250720-WA0095.jpg\",\"datePublished\":\"2025-07-21T01:10:21+00:00\",\"dateModified\":\"2025-07-21T01:10:21+00:00\",\"author\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/0546f9c3407148f7452ca932715c5e88\"},\"breadcrumb\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/umsnh-cierra-con-triunfo-la-fase-regular-de-la-primera-fuerza-en-la-liga-municipal\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/umsnh-cierra-con-triunfo-la-fase-regular-de-la-primera-fuerza-en-la-liga-municipal\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/umsnh-cierra-con-triunfo-la-fase-regular-de-la-primera-fuerza-en-la-liga-municipal\/#primaryimage\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250720-WA0095.jpg\",\"contentUrl\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250720-WA0095.jpg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/umsnh-cierra-con-triunfo-la-fase-regular-de-la-primera-fuerza-en-la-liga-municipal\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"UMSNH cierra con triunfo la fase regular de la Primera Fuerza en la Liga Municipal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/\",\"name\":\"Diario ABC de Michoac\u00e1n\",\"description\":\"Las noticias al momento\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/0546f9c3407148f7452ca932715c5e88\",\"name\":\"MB\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/adcd41fde6b8d0b5d9d0de001d3112b3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/adcd41fde6b8d0b5d9d0de001d3112b3?s=96&d=mm&r=g\",\"caption\":\"MB\"},\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/author\/bomariano03\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"UMSNH cierra con triunfo la fase regular de la Primera Fuerza en la Liga Municipal - Diario ABC de Michoac\u00e1n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/umsnh-cierra-con-triunfo-la-fase-regular-de-la-primera-fuerza-en-la-liga-municipal\/","og_locale":"es_ES","og_type":"article","og_title":"UMSNH cierra con triunfo la fase regular de la Primera Fuerza en la Liga Municipal - Diario ABC de Michoac\u00e1n","og_description":"La pr\u00f3xima semana el cuadro nicolaita jugar\u00e1 los cuartos de final de esta categor\u00eda Morelia, Michoac\u00e1n. &#8211; El conjunto de la Universidad Michoacana de San Nicol\u00e1s de Hidalgo (UMSNH) que compite en la categor\u00eda de Primera Fuerza de la Liga Municipal de F\u00fatbol Amateur Morelia cerr\u00f3 este domingo la fase regular con un triunfo de [&hellip;]","og_url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/umsnh-cierra-con-triunfo-la-fase-regular-de-la-primera-fuerza-en-la-liga-municipal\/","og_site_name":"Diario ABC de Michoac\u00e1n","article_published_time":"2025-07-21T01:10:21+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250720-WA0095.jpg","type":"image\/jpeg"}],"author":"MB","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"MB","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/umsnh-cierra-con-triunfo-la-fase-regular-de-la-primera-fuerza-en-la-liga-municipal\/","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/umsnh-cierra-con-triunfo-la-fase-regular-de-la-primera-fuerza-en-la-liga-municipal\/","name":"UMSNH cierra con triunfo la fase regular de la Primera Fuerza en la Liga Municipal - Diario ABC de Michoac\u00e1n","isPartOf":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/umsnh-cierra-con-triunfo-la-fase-regular-de-la-primera-fuerza-en-la-liga-municipal\/#primaryimage"},"image":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/umsnh-cierra-con-triunfo-la-fase-regular-de-la-primera-fuerza-en-la-liga-municipal\/#primaryimage"},"thumbnailUrl":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250720-WA0095.jpg","datePublished":"2025-07-21T01:10:21+00:00","dateModified":"2025-07-21T01:10:21+00:00","author":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/0546f9c3407148f7452ca932715c5e88"},"breadcrumb":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/umsnh-cierra-con-triunfo-la-fase-regular-de-la-primera-fuerza-en-la-liga-municipal\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/umsnh-cierra-con-triunfo-la-fase-regular-de-la-primera-fuerza-en-la-liga-municipal\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/umsnh-cierra-con-triunfo-la-fase-regular-de-la-primera-fuerza-en-la-liga-municipal\/#primaryimage","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250720-WA0095.jpg","contentUrl":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/07\/IMG-20250720-WA0095.jpg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/umsnh-cierra-con-triunfo-la-fase-regular-de-la-primera-fuerza-en-la-liga-municipal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/"},{"@type":"ListItem","position":2,"name":"UMSNH cierra con triunfo la fase regular de la Primera Fuerza en la Liga Municipal"}]},{"@type":"WebSite","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/","name":"Diario ABC de Michoac\u00e1n","description":"Las noticias al momento","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/0546f9c3407148f7452ca932715c5e88","name":"MB","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/adcd41fde6b8d0b5d9d0de001d3112b3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/adcd41fde6b8d0b5d9d0de001d3112b3?s=96&d=mm&r=g","caption":"MB"},"url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/author\/bomariano03\/"}]}},"_links":{"self":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/65342","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/comments?post=65342"}],"version-history":[{"count":1,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/65342\/revisions"}],"predecessor-version":[{"id":65344,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/65342\/revisions\/65344"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/media\/65343"}],"wp:attachment":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/media?parent=65342"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/categories?post=65342"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/tags?post=65342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}