{"id":68540,"date":"2025-09-05T14:18:02","date_gmt":"2025-09-05T20:18:02","guid":{"rendered":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?p=68540"},"modified":"2025-09-05T14:18:02","modified_gmt":"2025-09-05T20:18:02","slug":"gobierno-de-morelia-cierra-filas-en-defensa-de-los-animales","status":"publish","type":"post","link":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gobierno-de-morelia-cierra-filas-en-defensa-de-los-animales\/","title":{"rendered":"Gobierno de Morelia cierra filas en defensa de los animales"},"content":{"rendered":"<h2>Minerva Bautista encabeza gestiones del IMPA ante la Fiscal\u00eda General del Estado<\/h2>\n<p>&nbsp;<\/p>\n<hr \/>\n<p>Morelia, Mich.- Con la voluntad de fortalecer la colaboraci\u00f3n entre instituciones en beneficio de quienes no pueden defenderse solos, el Gobierno de Morelia que encabeza el Alcalde, Alfonso Mart\u00ednez Alc\u00e1zar, a trav\u00e9s del Instituto Moreliano de Protecci\u00f3n Animal (IMPA) y la Fiscal\u00eda General del Estado (FGE), cerraron filas para atender las denuncias por maltrato animal.<\/p>\n<p>En la reuni\u00f3n, la directora del IMPA, Minerva Bautista G\u00f3mez, se entrevist\u00f3 con el Fiscal Coordinador de la FGE, Jos\u00e9 Antonio Cruz Medina, as\u00ed como con representantes de la Fiscal\u00eda Especializada en Medio Ambiente y de la Unidad de Maltrato Animal, logrando acuerdos que permitir\u00e1n avanzar en los casos que y mejorar la efectividad en la defensa de quienes no tienen voz.<\/p>\n<p>\u201cCelebramos la acertada decisi\u00f3n de la FGE al nombrar al nuevo Coordinador Fiscal, con quien confiamos en que lograremos un avance\u201d, destac\u00f3 Minerva Bautista, quien tambi\u00e9n inform\u00f3 que actualmente est\u00e1n en proceso 45 denuncias por maltrato animal, a las cuales se les dar\u00e1 el seguimiento puntual.<\/p>\n<p>Aunado a esto, la Fiscal\u00eda capacitar\u00e1 al personal del IMPA sobre tr\u00e1mites y procesos de denuncias penales correspondientes al delito de maltrato y crueldad a animal, mientras que el Instituto Moreliano ofrecer\u00e1 talleres de concientizaci\u00f3n a trabajadores de la Fiscal\u00eda, a fin de sensibilizar sobre los seres sintientes.<\/p>\n<p>Con esta coordinaci\u00f3n entre instancias municipales y estatales, el Gobierno de Morelia refrenda su compromiso de salvaguardar la integridad de todas y todos, construyendo una ciudad m\u00e1s justa y sensible hacia el cuidado de los animales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Minerva Bautista encabeza gestiones del IMPA ante la Fiscal\u00eda General del Estado &nbsp; Morelia, Mich.- Con la voluntad de fortalecer la colaboraci\u00f3n entre instituciones en beneficio de quienes no pueden defenderse solos, el Gobierno de Morelia que encabeza el Alcalde, Alfonso Mart\u00ednez Alc\u00e1zar, a trav\u00e9s del Instituto Moreliano de Protecci\u00f3n Animal (IMPA) y la Fiscal\u00eda [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":68541,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18,7,28,27],"tags":[],"class_list":{"0":"post-68540","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-ayuntamiento-de-morelia","8":"category-morelia","9":"category-politica","10":"category-slider"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gobierno de Morelia cierra filas en defensa de los animales - Diario ABC de Michoac\u00e1n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gobierno-de-morelia-cierra-filas-en-defensa-de-los-animales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gobierno de Morelia cierra filas en defensa de los animales - Diario ABC de Michoac\u00e1n\" \/>\n<meta property=\"og:description\" content=\"Minerva Bautista encabeza gestiones del IMPA ante la Fiscal\u00eda General del Estado &nbsp; Morelia, Mich.- Con la voluntad de fortalecer la colaboraci\u00f3n entre instituciones en beneficio de quienes no pueden defenderse solos, el Gobierno de Morelia que encabeza el Alcalde, Alfonso Mart\u00ednez Alc\u00e1zar, a trav\u00e9s del Instituto Moreliano de Protecci\u00f3n Animal (IMPA) y la Fiscal\u00eda [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gobierno-de-morelia-cierra-filas-en-defensa-de-los-animales\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario ABC de Michoac\u00e1n\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-05T20:18:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/09\/Imagen-de-WhatsApp-2025-09-05-a-las-13.10.51_d5af3c43.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1316\" \/>\n\t<meta property=\"og:image:height\" content=\"1029\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"AR\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"AR\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gobierno-de-morelia-cierra-filas-en-defensa-de-los-animales\/\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gobierno-de-morelia-cierra-filas-en-defensa-de-los-animales\/\",\"name\":\"Gobierno de Morelia cierra filas en defensa de los animales - Diario ABC de Michoac\u00e1n\",\"isPartOf\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gobierno-de-morelia-cierra-filas-en-defensa-de-los-animales\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gobierno-de-morelia-cierra-filas-en-defensa-de-los-animales\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/09\/Imagen-de-WhatsApp-2025-09-05-a-las-13.10.51_d5af3c43.jpg\",\"datePublished\":\"2025-09-05T20:18:02+00:00\",\"dateModified\":\"2025-09-05T20:18:02+00:00\",\"author\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/19ae376040f6cbc489682ebdd8524852\"},\"breadcrumb\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gobierno-de-morelia-cierra-filas-en-defensa-de-los-animales\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gobierno-de-morelia-cierra-filas-en-defensa-de-los-animales\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gobierno-de-morelia-cierra-filas-en-defensa-de-los-animales\/#primaryimage\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/09\/Imagen-de-WhatsApp-2025-09-05-a-las-13.10.51_d5af3c43.jpg\",\"contentUrl\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/09\/Imagen-de-WhatsApp-2025-09-05-a-las-13.10.51_d5af3c43.jpg\",\"width\":1316,\"height\":1029},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gobierno-de-morelia-cierra-filas-en-defensa-de-los-animales\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gobierno de Morelia cierra filas en defensa de los animales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/\",\"name\":\"Diario ABC de Michoac\u00e1n\",\"description\":\"Las noticias al momento\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/19ae376040f6cbc489682ebdd8524852\",\"name\":\"AR\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/44eca2ff970262234e20e1e082872af0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/44eca2ff970262234e20e1e082872af0?s=96&d=mm&r=g\",\"caption\":\"AR\"},\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/author\/adrian\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gobierno de Morelia cierra filas en defensa de los animales - Diario ABC de Michoac\u00e1n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gobierno-de-morelia-cierra-filas-en-defensa-de-los-animales\/","og_locale":"es_ES","og_type":"article","og_title":"Gobierno de Morelia cierra filas en defensa de los animales - Diario ABC de Michoac\u00e1n","og_description":"Minerva Bautista encabeza gestiones del IMPA ante la Fiscal\u00eda General del Estado &nbsp; Morelia, Mich.- Con la voluntad de fortalecer la colaboraci\u00f3n entre instituciones en beneficio de quienes no pueden defenderse solos, el Gobierno de Morelia que encabeza el Alcalde, Alfonso Mart\u00ednez Alc\u00e1zar, a trav\u00e9s del Instituto Moreliano de Protecci\u00f3n Animal (IMPA) y la Fiscal\u00eda [&hellip;]","og_url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gobierno-de-morelia-cierra-filas-en-defensa-de-los-animales\/","og_site_name":"Diario ABC de Michoac\u00e1n","article_published_time":"2025-09-05T20:18:02+00:00","og_image":[{"width":1316,"height":1029,"url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/09\/Imagen-de-WhatsApp-2025-09-05-a-las-13.10.51_d5af3c43.jpg","type":"image\/jpeg"}],"author":"AR","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"AR","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gobierno-de-morelia-cierra-filas-en-defensa-de-los-animales\/","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gobierno-de-morelia-cierra-filas-en-defensa-de-los-animales\/","name":"Gobierno de Morelia cierra filas en defensa de los animales - Diario ABC de Michoac\u00e1n","isPartOf":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gobierno-de-morelia-cierra-filas-en-defensa-de-los-animales\/#primaryimage"},"image":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gobierno-de-morelia-cierra-filas-en-defensa-de-los-animales\/#primaryimage"},"thumbnailUrl":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/09\/Imagen-de-WhatsApp-2025-09-05-a-las-13.10.51_d5af3c43.jpg","datePublished":"2025-09-05T20:18:02+00:00","dateModified":"2025-09-05T20:18:02+00:00","author":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/19ae376040f6cbc489682ebdd8524852"},"breadcrumb":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gobierno-de-morelia-cierra-filas-en-defensa-de-los-animales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gobierno-de-morelia-cierra-filas-en-defensa-de-los-animales\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gobierno-de-morelia-cierra-filas-en-defensa-de-los-animales\/#primaryimage","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/09\/Imagen-de-WhatsApp-2025-09-05-a-las-13.10.51_d5af3c43.jpg","contentUrl":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/09\/Imagen-de-WhatsApp-2025-09-05-a-las-13.10.51_d5af3c43.jpg","width":1316,"height":1029},{"@type":"BreadcrumbList","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gobierno-de-morelia-cierra-filas-en-defensa-de-los-animales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/"},{"@type":"ListItem","position":2,"name":"Gobierno de Morelia cierra filas en defensa de los animales"}]},{"@type":"WebSite","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/","name":"Diario ABC de Michoac\u00e1n","description":"Las noticias al momento","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/19ae376040f6cbc489682ebdd8524852","name":"AR","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/44eca2ff970262234e20e1e082872af0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/44eca2ff970262234e20e1e082872af0?s=96&d=mm&r=g","caption":"AR"},"url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/author\/adrian\/"}]}},"_links":{"self":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/68540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/comments?post=68540"}],"version-history":[{"count":1,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/68540\/revisions"}],"predecessor-version":[{"id":68542,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/68540\/revisions\/68542"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/media\/68541"}],"wp:attachment":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/media?parent=68540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/categories?post=68540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/tags?post=68540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}