{"id":68864,"date":"2025-09-11T11:54:45","date_gmt":"2025-09-11T17:54:45","guid":{"rendered":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?p=68864"},"modified":"2025-09-11T11:54:45","modified_gmt":"2025-09-11T17:54:45","slug":"sedum-inicia-jornada-balizamiento-en-la-avenida-madero-frente-a-catedral","status":"publish","type":"post","link":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/sedum-inicia-jornada-balizamiento-en-la-avenida-madero-frente-a-catedral\/","title":{"rendered":"SEDUM inicia jornada balizamiento en la Avenida Madero, frente a Catedral"},"content":{"rendered":"<h2>Cierre de circulaci\u00f3n ser\u00e1 de 09:00 a 12:30 horas, este jueves y viernes<\/h2>\n<ul>\n<li>Pato Peat\u00f3n, Cebra Lisa y Frida Canina, participan con la promoci\u00f3n de la educaci\u00f3n vial<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<hr \/>\n<p>Morelia, Mich.- La Secretar\u00eda de Desarrollo Urbano y Movilidad (SEDUM) realiza una jornada especial de balizamiento sobre la Avenida Madero, en el primer cuadro de la ciudad, como parte de los preparativos para las pr\u00f3ximas fiestas patrias en la capital michoacana.<\/p>\n<p>Los trabajos comenzaron hoy jueves 11 de septiembre, en el tramo comprendido entre las calles de Abasolo y Morelos; y se prev\u00e9 que concluyan este viernes. La vialidad se cerrar\u00e1 a la circulaci\u00f3n vehicular de las 09:00 a las 12: 30 horas, y despu\u00e9s de este horario se abrir\u00e1 nuevamente.<\/p>\n<p>Las labores incluyen la aplicaci\u00f3n de flechas de sentido, l\u00edneas divisorias, pasos peatonales y tri\u00e1ngulos de prioridad ciclista, con el objetivo de fortalecer la seguridad vial, mejorar la movilidad y garantizar un entorno ordenado para las y los morelianos que asistir\u00e1n a las celebraciones patrias.<\/p>\n<p>En esta jornada, se cont\u00f3 con el apoyo de Pato Peat\u00f3n, Cebra Lisa y Frida Canina, personajes guardianes de la movilidad que se suman a la difusi\u00f3n de la importancia del respeto a las y los peatones, ciclistas y conductores.<\/p>\n<p>La SEDUM invita a la ciudadan\u00eda a tomar precauciones durante el tiempo que duren las labores, utilizando v\u00edas alternas, y sum\u00e1ndose a la construcci\u00f3n de una movilidad m\u00e1s segura para todas y todos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cierre de circulaci\u00f3n ser\u00e1 de 09:00 a 12:30 horas, este jueves y viernes Pato Peat\u00f3n, Cebra Lisa y Frida Canina, participan con la promoci\u00f3n de la educaci\u00f3n vial &nbsp; Morelia, Mich.- La Secretar\u00eda de Desarrollo Urbano y Movilidad (SEDUM) realiza una jornada especial de balizamiento sobre la Avenida Madero, en el primer cuadro de la [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":68865,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,17,27],"tags":[],"class_list":{"0":"post-68864","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-estado","8":"category-gobierno-de-michoacan","9":"category-slider"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>SEDUM inicia jornada balizamiento en la Avenida Madero, frente a Catedral - Diario ABC de Michoac\u00e1n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/sedum-inicia-jornada-balizamiento-en-la-avenida-madero-frente-a-catedral\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SEDUM inicia jornada balizamiento en la Avenida Madero, frente a Catedral - Diario ABC de Michoac\u00e1n\" \/>\n<meta property=\"og:description\" content=\"Cierre de circulaci\u00f3n ser\u00e1 de 09:00 a 12:30 horas, este jueves y viernes Pato Peat\u00f3n, Cebra Lisa y Frida Canina, participan con la promoci\u00f3n de la educaci\u00f3n vial &nbsp; Morelia, Mich.- La Secretar\u00eda de Desarrollo Urbano y Movilidad (SEDUM) realiza una jornada especial de balizamiento sobre la Avenida Madero, en el primer cuadro de la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/sedum-inicia-jornada-balizamiento-en-la-avenida-madero-frente-a-catedral\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario ABC de Michoac\u00e1n\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-11T17:54:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/09\/Imagen-de-WhatsApp-2025-09-11-a-las-11.46.45_10983ef9-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"AR\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"AR\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/sedum-inicia-jornada-balizamiento-en-la-avenida-madero-frente-a-catedral\/\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/sedum-inicia-jornada-balizamiento-en-la-avenida-madero-frente-a-catedral\/\",\"name\":\"SEDUM inicia jornada balizamiento en la Avenida Madero, frente a Catedral - Diario ABC de Michoac\u00e1n\",\"isPartOf\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/sedum-inicia-jornada-balizamiento-en-la-avenida-madero-frente-a-catedral\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/sedum-inicia-jornada-balizamiento-en-la-avenida-madero-frente-a-catedral\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/09\/Imagen-de-WhatsApp-2025-09-11-a-las-11.46.45_10983ef9-scaled.jpg\",\"datePublished\":\"2025-09-11T17:54:45+00:00\",\"dateModified\":\"2025-09-11T17:54:45+00:00\",\"author\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/19ae376040f6cbc489682ebdd8524852\"},\"breadcrumb\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/sedum-inicia-jornada-balizamiento-en-la-avenida-madero-frente-a-catedral\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/sedum-inicia-jornada-balizamiento-en-la-avenida-madero-frente-a-catedral\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/sedum-inicia-jornada-balizamiento-en-la-avenida-madero-frente-a-catedral\/#primaryimage\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/09\/Imagen-de-WhatsApp-2025-09-11-a-las-11.46.45_10983ef9-scaled.jpg\",\"contentUrl\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/09\/Imagen-de-WhatsApp-2025-09-11-a-las-11.46.45_10983ef9-scaled.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/sedum-inicia-jornada-balizamiento-en-la-avenida-madero-frente-a-catedral\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SEDUM inicia jornada balizamiento en la Avenida Madero, frente a Catedral\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/\",\"name\":\"Diario ABC de Michoac\u00e1n\",\"description\":\"Las noticias al momento\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/19ae376040f6cbc489682ebdd8524852\",\"name\":\"AR\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/44eca2ff970262234e20e1e082872af0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/44eca2ff970262234e20e1e082872af0?s=96&d=mm&r=g\",\"caption\":\"AR\"},\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/author\/adrian\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SEDUM inicia jornada balizamiento en la Avenida Madero, frente a Catedral - Diario ABC de Michoac\u00e1n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/sedum-inicia-jornada-balizamiento-en-la-avenida-madero-frente-a-catedral\/","og_locale":"es_ES","og_type":"article","og_title":"SEDUM inicia jornada balizamiento en la Avenida Madero, frente a Catedral - Diario ABC de Michoac\u00e1n","og_description":"Cierre de circulaci\u00f3n ser\u00e1 de 09:00 a 12:30 horas, este jueves y viernes Pato Peat\u00f3n, Cebra Lisa y Frida Canina, participan con la promoci\u00f3n de la educaci\u00f3n vial &nbsp; Morelia, Mich.- La Secretar\u00eda de Desarrollo Urbano y Movilidad (SEDUM) realiza una jornada especial de balizamiento sobre la Avenida Madero, en el primer cuadro de la [&hellip;]","og_url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/sedum-inicia-jornada-balizamiento-en-la-avenida-madero-frente-a-catedral\/","og_site_name":"Diario ABC de Michoac\u00e1n","article_published_time":"2025-09-11T17:54:45+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/09\/Imagen-de-WhatsApp-2025-09-11-a-las-11.46.45_10983ef9-scaled.jpg","type":"image\/jpeg"}],"author":"AR","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"AR","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/sedum-inicia-jornada-balizamiento-en-la-avenida-madero-frente-a-catedral\/","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/sedum-inicia-jornada-balizamiento-en-la-avenida-madero-frente-a-catedral\/","name":"SEDUM inicia jornada balizamiento en la Avenida Madero, frente a Catedral - Diario ABC de Michoac\u00e1n","isPartOf":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/sedum-inicia-jornada-balizamiento-en-la-avenida-madero-frente-a-catedral\/#primaryimage"},"image":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/sedum-inicia-jornada-balizamiento-en-la-avenida-madero-frente-a-catedral\/#primaryimage"},"thumbnailUrl":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/09\/Imagen-de-WhatsApp-2025-09-11-a-las-11.46.45_10983ef9-scaled.jpg","datePublished":"2025-09-11T17:54:45+00:00","dateModified":"2025-09-11T17:54:45+00:00","author":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/19ae376040f6cbc489682ebdd8524852"},"breadcrumb":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/sedum-inicia-jornada-balizamiento-en-la-avenida-madero-frente-a-catedral\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/sedum-inicia-jornada-balizamiento-en-la-avenida-madero-frente-a-catedral\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/sedum-inicia-jornada-balizamiento-en-la-avenida-madero-frente-a-catedral\/#primaryimage","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/09\/Imagen-de-WhatsApp-2025-09-11-a-las-11.46.45_10983ef9-scaled.jpg","contentUrl":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/09\/Imagen-de-WhatsApp-2025-09-11-a-las-11.46.45_10983ef9-scaled.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/sedum-inicia-jornada-balizamiento-en-la-avenida-madero-frente-a-catedral\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/"},{"@type":"ListItem","position":2,"name":"SEDUM inicia jornada balizamiento en la Avenida Madero, frente a Catedral"}]},{"@type":"WebSite","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/","name":"Diario ABC de Michoac\u00e1n","description":"Las noticias al momento","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/19ae376040f6cbc489682ebdd8524852","name":"AR","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/44eca2ff970262234e20e1e082872af0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/44eca2ff970262234e20e1e082872af0?s=96&d=mm&r=g","caption":"AR"},"url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/author\/adrian\/"}]}},"_links":{"self":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/68864","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/comments?post=68864"}],"version-history":[{"count":1,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/68864\/revisions"}],"predecessor-version":[{"id":68866,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/68864\/revisions\/68866"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/media\/68865"}],"wp:attachment":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/media?parent=68864"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/categories?post=68864"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/tags?post=68864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}