{"id":69376,"date":"2025-09-29T10:23:32","date_gmt":"2025-09-29T16:23:32","guid":{"rendered":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?p=69376"},"modified":"2025-09-29T10:23:32","modified_gmt":"2025-09-29T16:23:32","slug":"gerencia-del-centro-historico-da-mantenimiento-a-casa-natal-de-morelos","status":"publish","type":"post","link":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gerencia-del-centro-historico-da-mantenimiento-a-casa-natal-de-morelos\/","title":{"rendered":"Gerencia del Centro Hist\u00f3rico da mantenimiento a Casa Natal de Morelos"},"content":{"rendered":"<h2>Personal hace retiro de flora nociva, as\u00ed como limpieza a piezas de canter\u00eda.<\/h2>\n<p>&nbsp;<\/p>\n<hr \/>\n<p>Morelia, Mich.- Con el fin de mantener en \u00f3ptimas y dignas condiciones este ic\u00f3nico espacio que es sin\u00f3nimo de uno de los m\u00e1s grandes personajes de nuestra Patria, el Gobierno de Morelia encabezado por el presidente municipal, Alfonso Mart\u00ednez Alc\u00e1zar, realiz\u00f3 mantenimiento de la Casa Natal de Morelos.<\/p>\n<p>La Gerencia del Centro Hist\u00f3rico, encabezada por su titular Gaspar Hern\u00e1ndez Razo, contin\u00faa realizando trabajos de protecci\u00f3n, restauraci\u00f3n y conservaci\u00f3n a edificios y monumentos del centro hist\u00f3rico patrimonio de la humanidad, con la intenci\u00f3n de evitar su deterioro estructural.<\/p>\n<p>Uno de los principales inmuebles a preservar es la Casa Natal de Morelos. Ubicado en la calle Corregidora, este recinto alberga pertenencias y documentos del General\u00edsimo, y cientos de visitantes pueden acudir de manera gratuita a disfrutar de la historia de este personaje de la Independencia de M\u00e9xico.<\/p>\n<p>Por ello, se iniciaron trabajos en dicho edificio con especial \u00e9nfasis en el retiro de flora nociva. En ese sentido, es importante destacar que aunque a simple vista parezcan solo plantas inofensivas, tienen el potencial de deteriorar los inmuebles ya que favorecen la humedad que se filtra hacia el interior de la estructura.<\/p>\n<p>Adem\u00e1s, se emprendi\u00f3 la limpieza de piedras de canter\u00eda con lama y piso de cantera, con el fin de mantener su apariencia est\u00e9tica, prevenir el da\u00f1o y la degradaci\u00f3n de la piedra, evitar el deslizamiento y asegurar la salubridad del ambiente al eliminar organismos perjudiciales.<\/p>\n<p>Con el cuidado a nuestros espacios ic\u00f3nicos, la administraci\u00f3n del presidente Alfonso Mart\u00ednez sigue construyendo el mejor lugar para vivir.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Personal hace retiro de flora nociva, as\u00ed como limpieza a piezas de canter\u00eda. &nbsp; Morelia, Mich.- Con el fin de mantener en \u00f3ptimas y dignas condiciones este ic\u00f3nico espacio que es sin\u00f3nimo de uno de los m\u00e1s grandes personajes de nuestra Patria, el Gobierno de Morelia encabezado por el presidente municipal, Alfonso Mart\u00ednez Alc\u00e1zar, realiz\u00f3 [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":69377,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18,7,28,27],"tags":[],"class_list":{"0":"post-69376","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-ayuntamiento-de-morelia","8":"category-morelia","9":"category-politica","10":"category-slider"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gerencia del Centro Hist\u00f3rico da mantenimiento a Casa Natal de Morelos - Diario ABC de Michoac\u00e1n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gerencia-del-centro-historico-da-mantenimiento-a-casa-natal-de-morelos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gerencia del Centro Hist\u00f3rico da mantenimiento a Casa Natal de Morelos - Diario ABC de Michoac\u00e1n\" \/>\n<meta property=\"og:description\" content=\"Personal hace retiro de flora nociva, as\u00ed como limpieza a piezas de canter\u00eda. &nbsp; Morelia, Mich.- Con el fin de mantener en \u00f3ptimas y dignas condiciones este ic\u00f3nico espacio que es sin\u00f3nimo de uno de los m\u00e1s grandes personajes de nuestra Patria, el Gobierno de Morelia encabezado por el presidente municipal, Alfonso Mart\u00ednez Alc\u00e1zar, realiz\u00f3 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gerencia-del-centro-historico-da-mantenimiento-a-casa-natal-de-morelos\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario ABC de Michoac\u00e1n\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-29T16:23:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/09\/Imagen-de-WhatsApp-2025-09-29-a-las-10.09.14_b014a4aa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"AR\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"AR\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gerencia-del-centro-historico-da-mantenimiento-a-casa-natal-de-morelos\/\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gerencia-del-centro-historico-da-mantenimiento-a-casa-natal-de-morelos\/\",\"name\":\"Gerencia del Centro Hist\u00f3rico da mantenimiento a Casa Natal de Morelos - Diario ABC de Michoac\u00e1n\",\"isPartOf\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gerencia-del-centro-historico-da-mantenimiento-a-casa-natal-de-morelos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gerencia-del-centro-historico-da-mantenimiento-a-casa-natal-de-morelos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/09\/Imagen-de-WhatsApp-2025-09-29-a-las-10.09.14_b014a4aa.jpg\",\"datePublished\":\"2025-09-29T16:23:32+00:00\",\"dateModified\":\"2025-09-29T16:23:32+00:00\",\"author\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/19ae376040f6cbc489682ebdd8524852\"},\"breadcrumb\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gerencia-del-centro-historico-da-mantenimiento-a-casa-natal-de-morelos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gerencia-del-centro-historico-da-mantenimiento-a-casa-natal-de-morelos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gerencia-del-centro-historico-da-mantenimiento-a-casa-natal-de-morelos\/#primaryimage\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/09\/Imagen-de-WhatsApp-2025-09-29-a-las-10.09.14_b014a4aa.jpg\",\"contentUrl\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/09\/Imagen-de-WhatsApp-2025-09-29-a-las-10.09.14_b014a4aa.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gerencia-del-centro-historico-da-mantenimiento-a-casa-natal-de-morelos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gerencia del Centro Hist\u00f3rico da mantenimiento a Casa Natal de Morelos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/\",\"name\":\"Diario ABC de Michoac\u00e1n\",\"description\":\"Las noticias al momento\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/19ae376040f6cbc489682ebdd8524852\",\"name\":\"AR\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/44eca2ff970262234e20e1e082872af0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/44eca2ff970262234e20e1e082872af0?s=96&d=mm&r=g\",\"caption\":\"AR\"},\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/author\/adrian\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gerencia del Centro Hist\u00f3rico da mantenimiento a Casa Natal de Morelos - Diario ABC de Michoac\u00e1n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gerencia-del-centro-historico-da-mantenimiento-a-casa-natal-de-morelos\/","og_locale":"es_ES","og_type":"article","og_title":"Gerencia del Centro Hist\u00f3rico da mantenimiento a Casa Natal de Morelos - Diario ABC de Michoac\u00e1n","og_description":"Personal hace retiro de flora nociva, as\u00ed como limpieza a piezas de canter\u00eda. &nbsp; Morelia, Mich.- Con el fin de mantener en \u00f3ptimas y dignas condiciones este ic\u00f3nico espacio que es sin\u00f3nimo de uno de los m\u00e1s grandes personajes de nuestra Patria, el Gobierno de Morelia encabezado por el presidente municipal, Alfonso Mart\u00ednez Alc\u00e1zar, realiz\u00f3 [&hellip;]","og_url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gerencia-del-centro-historico-da-mantenimiento-a-casa-natal-de-morelos\/","og_site_name":"Diario ABC de Michoac\u00e1n","article_published_time":"2025-09-29T16:23:32+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/09\/Imagen-de-WhatsApp-2025-09-29-a-las-10.09.14_b014a4aa.jpg","type":"image\/jpeg"}],"author":"AR","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"AR","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gerencia-del-centro-historico-da-mantenimiento-a-casa-natal-de-morelos\/","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gerencia-del-centro-historico-da-mantenimiento-a-casa-natal-de-morelos\/","name":"Gerencia del Centro Hist\u00f3rico da mantenimiento a Casa Natal de Morelos - Diario ABC de Michoac\u00e1n","isPartOf":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gerencia-del-centro-historico-da-mantenimiento-a-casa-natal-de-morelos\/#primaryimage"},"image":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gerencia-del-centro-historico-da-mantenimiento-a-casa-natal-de-morelos\/#primaryimage"},"thumbnailUrl":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/09\/Imagen-de-WhatsApp-2025-09-29-a-las-10.09.14_b014a4aa.jpg","datePublished":"2025-09-29T16:23:32+00:00","dateModified":"2025-09-29T16:23:32+00:00","author":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/19ae376040f6cbc489682ebdd8524852"},"breadcrumb":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gerencia-del-centro-historico-da-mantenimiento-a-casa-natal-de-morelos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gerencia-del-centro-historico-da-mantenimiento-a-casa-natal-de-morelos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gerencia-del-centro-historico-da-mantenimiento-a-casa-natal-de-morelos\/#primaryimage","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/09\/Imagen-de-WhatsApp-2025-09-29-a-las-10.09.14_b014a4aa.jpg","contentUrl":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/09\/Imagen-de-WhatsApp-2025-09-29-a-las-10.09.14_b014a4aa.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/gerencia-del-centro-historico-da-mantenimiento-a-casa-natal-de-morelos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/"},{"@type":"ListItem","position":2,"name":"Gerencia del Centro Hist\u00f3rico da mantenimiento a Casa Natal de Morelos"}]},{"@type":"WebSite","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/","name":"Diario ABC de Michoac\u00e1n","description":"Las noticias al momento","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/19ae376040f6cbc489682ebdd8524852","name":"AR","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/44eca2ff970262234e20e1e082872af0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/44eca2ff970262234e20e1e082872af0?s=96&d=mm&r=g","caption":"AR"},"url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/author\/adrian\/"}]}},"_links":{"self":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/69376","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/comments?post=69376"}],"version-history":[{"count":1,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/69376\/revisions"}],"predecessor-version":[{"id":69378,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/69376\/revisions\/69378"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/media\/69377"}],"wp:attachment":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/media?parent=69376"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/categories?post=69376"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/tags?post=69376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}