{"id":70045,"date":"2025-10-10T15:11:43","date_gmt":"2025-10-10T21:11:43","guid":{"rendered":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?p=70045"},"modified":"2025-10-10T15:11:43","modified_gmt":"2025-10-10T21:11:43","slug":"vive-la-semana-de-noche-de-muertos-en-michoacan-estas-son-las-actividades-del-24-de-octubre-al-2-de-noviembre","status":"publish","type":"post","link":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/vive-la-semana-de-noche-de-muertos-en-michoacan-estas-son-las-actividades-del-24-de-octubre-al-2-de-noviembre\/","title":{"rendered":"Vive la Semana de Noche de Muertos en Michoac\u00e1n; estas son las actividades del 24 de octubre al 2 de noviembre"},"content":{"rendered":"<h2>Adem\u00e1s habr\u00e1 representaciones en Xcaret y Espa\u00f1a, que cautivar\u00e1n al mundo entero<\/h2>\n<p>&nbsp;<\/p>\n<hr \/>\n<p>P\u00e1tzcuaro, Mich.- Del 24 de octubre al 2 de noviembre, la Noche de \u00c1nimas se vive en Michoac\u00e1n, estado donde tiene sus ra\u00edces esta ancestral celebraci\u00f3n que cada a\u00f1o cautiva al mundo entero por la forma en la que las comunidades de los 113 municipios del estado recuerdan a sus familiares que se adelantaron en el camino, dejando en claro que en \u201cel alma de M\u00e9xico\u201d no se entierra, se siembra a los seres queridos para dar vida.<\/p>\n<p>Adem\u00e1s menci\u00f3n especial merece la manera tan \u00fanica que se recuerda a los difuntos en los panteones de la ribera del lago de P\u00e1tzcuaro, momento emblem\u00e1tico que representa al estado a nivel internacional atrayendo al turismo de distintos estados y pa\u00edses que se acercan a este m\u00e1gico encuentro entre vivos y muertos.<\/p><div id=\"diari-1375594093\" class=\"diari-contenido diari-entity-placement\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-05-07-at-10.12.40-a.m.jpeg\" alt=\"\"  srcset=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-05-07-at-10.12.40-a.m.jpeg 400w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-05-07-at-10.12.40-a.m-150x150.jpeg 150w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-05-07-at-10.12.40-a.m-300x300.jpeg 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" width=\"400\" height=\"400\"  style=\"display: inline-block;\" \/><\/div>\n<p>Por segundo a\u00f1o consecutivo, la Secretar\u00eda de Turismo de Michoac\u00e1n (Sectur), en colaboraci\u00f3n con las comunidades, autoridades municipales, artesanos y cocineras tradicionales, se unen para presentar la Semana de Celebraci\u00f3n de Noche de Muertos que este 2025 integra 13 talleres donde los turistas y visitantes podr\u00e1n ver y ser parte activa de los preparativos previos al 1 y 2 de noviembre.<\/p>\n<p>Roberto Monroy Garc\u00eda, titular de la Sectur Michoac\u00e1n destac\u00f3 que dentro de estos talleres con costos que oscilan entre los 100 y 250 pesos monto que ya incluye los materiales, se encuentran alfarer\u00eda, cerer\u00eda, figuras de az\u00facar, bateas, barro vidriado, hoja de ma\u00edz, popote de trigo, cocina tradicional, m\u00e1scaras de madera, dulce t\u00edpico, arcos tradicionales, papel picado y globos de cantoya y chuspata.<\/p>\n<p>\u201cLa zona lacustre de Michoac\u00e1n fue clave para que esta celebraci\u00f3n milenaria obtuviera el nombramiento por parte de la UNESCO, con P\u00e1tzcuaro, Tzintzuntzan, Quiroga y Erongar\u00edcuaro. Este a\u00f1o prevemos que lleguen m\u00e1s de 420 mil turistas y visitantes en esta Semana de Celebraci\u00f3n de la Noche de Muertos que dejen una derrama econ\u00f3mica cercana a los 500 millones de pesos\u201d.<\/p>\n<p>Z\u00e1yin Villavicencio S\u00e1nchez, coordinadora de Comunicaci\u00f3n destac\u00f3 que la Noche de \u00c1nimas se vivir\u00e1 en varios municipios del estado, \u201cy este a\u00f1o P\u00e1tzcuaro los recibe con su nuevo Mercado Municipal, e invitar a que los turistas y visitantes vengan a ver la recuperaci\u00f3n del lago de P\u00e1tzcuaro y los manantiales de Urand\u00e9n\u201d.<\/p>\n<p>Julio Arreola V\u00e1zquez, presidente municipal de P\u00e1tzcuaro agradeci\u00f3 el apoyo de la administraci\u00f3n del gobernador Alfredo Ram\u00edrez Bedolla por impulsar las tradiciones de Michoac\u00e1n, \u201cno es lo mismo ver la celebraci\u00f3n de Noche de Muertos en otros municipios que donde se origin\u00f3, si lo viven aqu\u00ed se dar\u00e1n cuenta de esta experiencia. Los invitamos a que vengan a disfrutar de las diversas actividades planeadas\u201d.<\/p>\n<p>Destac\u00f3 que al momento los hoteles registrados de P\u00e1tzcuaro est\u00e1n a m\u00e1s del 90 por ciento de ocupaci\u00f3n, \u201cadem\u00e1s est\u00e1 la oferta de Airbnb a donde llega una afluencia muy grande\u201d.<\/p>\n<p>Adem\u00e1s, tambi\u00e9n este 2025, la Noche de \u00c1nimas de Michoac\u00e1n llega a Xcaret que se desarrollar\u00e1 del 30 de octubre al 2 de noviembre, y en Espa\u00f1a se realizar\u00e1, durante todo el mes de noviembre, la representaci\u00f3n de un pante\u00f3n de la ribera del lago de P\u00e1tzcuaro que plasma lo que solo se vive al visitar \u201cel alma de M\u00e9xico\u201d.<\/p>\n<p>Todos los detalles de las actividades, horarios, y sedes pueden consultarse en https:\/\/visitmichoacan.com.mx\/ #Michoac\u00e1nSeVive<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Adem\u00e1s habr\u00e1 representaciones en Xcaret y Espa\u00f1a, que cautivar\u00e1n al mundo entero &nbsp; P\u00e1tzcuaro, Mich.- Del 24 de octubre al 2 de noviembre, la Noche de \u00c1nimas se vive en Michoac\u00e1n, estado donde tiene sus ra\u00edces esta ancestral celebraci\u00f3n que cada a\u00f1o cautiva al mundo entero por la forma en la que las comunidades de [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":70046,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,17,7,28,27],"tags":[],"class_list":["post-70045","post","type-post","status-publish","format-standard","has-post-thumbnail","category-estado","category-gobierno-de-michoacan","category-morelia","category-politica","category-slider"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vive la Semana de Noche de Muertos en Michoac\u00e1n; estas son las actividades del 24 de octubre al 2 de noviembre - Diario ABC de Michoac\u00e1n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/vive-la-semana-de-noche-de-muertos-en-michoacan-estas-son-las-actividades-del-24-de-octubre-al-2-de-noviembre\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vive la Semana de Noche de Muertos en Michoac\u00e1n; estas son las actividades del 24 de octubre al 2 de noviembre - Diario ABC de Michoac\u00e1n\" \/>\n<meta property=\"og:description\" content=\"Adem\u00e1s habr\u00e1 representaciones en Xcaret y Espa\u00f1a, que cautivar\u00e1n al mundo entero &nbsp; P\u00e1tzcuaro, Mich.- Del 24 de octubre al 2 de noviembre, la Noche de \u00c1nimas se vive en Michoac\u00e1n, estado donde tiene sus ra\u00edces esta ancestral celebraci\u00f3n que cada a\u00f1o cautiva al mundo entero por la forma en la que las comunidades de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/vive-la-semana-de-noche-de-muertos-en-michoacan-estas-son-las-actividades-del-24-de-octubre-al-2-de-noviembre\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario ABC de Michoac\u00e1n\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-10T21:11:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/10\/Imagen-de-WhatsApp-2025-10-09-a-las-17.47.29_61a0e618.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"852\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"AR\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"AR\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/vive-la-semana-de-noche-de-muertos-en-michoacan-estas-son-las-actividades-del-24-de-octubre-al-2-de-noviembre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/vive-la-semana-de-noche-de-muertos-en-michoacan-estas-son-las-actividades-del-24-de-octubre-al-2-de-noviembre\\\/\"},\"author\":{\"name\":\"AR\",\"@id\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/#\\\/schema\\\/person\\\/19ae376040f6cbc489682ebdd8524852\"},\"headline\":\"Vive la Semana de Noche de Muertos en Michoac\u00e1n; estas son las actividades del 24 de octubre al 2 de noviembre\",\"datePublished\":\"2025-10-10T21:11:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/vive-la-semana-de-noche-de-muertos-en-michoacan-estas-son-las-actividades-del-24-de-octubre-al-2-de-noviembre\\\/\"},\"wordCount\":623,\"image\":{\"@id\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/vive-la-semana-de-noche-de-muertos-en-michoacan-estas-son-las-actividades-del-24-de-octubre-al-2-de-noviembre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Imagen-de-WhatsApp-2025-10-09-a-las-17.47.29_61a0e618.jpg\",\"articleSection\":[\"Estado\",\"Gobierno de Michoac\u00e1n\",\"Morelia\",\"Pol\u00edtica\",\"Slider\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/vive-la-semana-de-noche-de-muertos-en-michoacan-estas-son-las-actividades-del-24-de-octubre-al-2-de-noviembre\\\/\",\"url\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/vive-la-semana-de-noche-de-muertos-en-michoacan-estas-son-las-actividades-del-24-de-octubre-al-2-de-noviembre\\\/\",\"name\":\"Vive la Semana de Noche de Muertos en Michoac\u00e1n; estas son las actividades del 24 de octubre al 2 de noviembre - Diario ABC de Michoac\u00e1n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/vive-la-semana-de-noche-de-muertos-en-michoacan-estas-son-las-actividades-del-24-de-octubre-al-2-de-noviembre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/vive-la-semana-de-noche-de-muertos-en-michoacan-estas-son-las-actividades-del-24-de-octubre-al-2-de-noviembre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Imagen-de-WhatsApp-2025-10-09-a-las-17.47.29_61a0e618.jpg\",\"datePublished\":\"2025-10-10T21:11:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/#\\\/schema\\\/person\\\/19ae376040f6cbc489682ebdd8524852\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/vive-la-semana-de-noche-de-muertos-en-michoacan-estas-son-las-actividades-del-24-de-octubre-al-2-de-noviembre\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/vive-la-semana-de-noche-de-muertos-en-michoacan-estas-son-las-actividades-del-24-de-octubre-al-2-de-noviembre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/vive-la-semana-de-noche-de-muertos-en-michoacan-estas-son-las-actividades-del-24-de-octubre-al-2-de-noviembre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Imagen-de-WhatsApp-2025-10-09-a-las-17.47.29_61a0e618.jpg\",\"contentUrl\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Imagen-de-WhatsApp-2025-10-09-a-las-17.47.29_61a0e618.jpg\",\"width\":1280,\"height\":852},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/vive-la-semana-de-noche-de-muertos-en-michoacan-estas-son-las-actividades-del-24-de-octubre-al-2-de-noviembre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vive la Semana de Noche de Muertos en Michoac\u00e1n; estas son las actividades del 24 de octubre al 2 de noviembre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/#website\",\"url\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/\",\"name\":\"Diario ABC de Michoac\u00e1n\",\"description\":\"Las noticias al momento\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/#\\\/schema\\\/person\\\/19ae376040f6cbc489682ebdd8524852\",\"name\":\"AR\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/620dde31bffc1d1abdb08a27461f06f796e6d74bba9feb506eda89b4e07120bb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/620dde31bffc1d1abdb08a27461f06f796e6d74bba9feb506eda89b4e07120bb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/620dde31bffc1d1abdb08a27461f06f796e6d74bba9feb506eda89b4e07120bb?s=96&d=mm&r=g\",\"caption\":\"AR\"},\"url\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/author\\\/adrian\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vive la Semana de Noche de Muertos en Michoac\u00e1n; estas son las actividades del 24 de octubre al 2 de noviembre - Diario ABC de Michoac\u00e1n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/vive-la-semana-de-noche-de-muertos-en-michoacan-estas-son-las-actividades-del-24-de-octubre-al-2-de-noviembre\/","og_locale":"es_ES","og_type":"article","og_title":"Vive la Semana de Noche de Muertos en Michoac\u00e1n; estas son las actividades del 24 de octubre al 2 de noviembre - Diario ABC de Michoac\u00e1n","og_description":"Adem\u00e1s habr\u00e1 representaciones en Xcaret y Espa\u00f1a, que cautivar\u00e1n al mundo entero &nbsp; P\u00e1tzcuaro, Mich.- Del 24 de octubre al 2 de noviembre, la Noche de \u00c1nimas se vive en Michoac\u00e1n, estado donde tiene sus ra\u00edces esta ancestral celebraci\u00f3n que cada a\u00f1o cautiva al mundo entero por la forma en la que las comunidades de [&hellip;]","og_url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/vive-la-semana-de-noche-de-muertos-en-michoacan-estas-son-las-actividades-del-24-de-octubre-al-2-de-noviembre\/","og_site_name":"Diario ABC de Michoac\u00e1n","article_published_time":"2025-10-10T21:11:43+00:00","og_image":[{"width":1280,"height":852,"url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/10\/Imagen-de-WhatsApp-2025-10-09-a-las-17.47.29_61a0e618.jpg","type":"image\/jpeg"}],"author":"AR","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"AR","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/vive-la-semana-de-noche-de-muertos-en-michoacan-estas-son-las-actividades-del-24-de-octubre-al-2-de-noviembre\/#article","isPartOf":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/vive-la-semana-de-noche-de-muertos-en-michoacan-estas-son-las-actividades-del-24-de-octubre-al-2-de-noviembre\/"},"author":{"name":"AR","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/19ae376040f6cbc489682ebdd8524852"},"headline":"Vive la Semana de Noche de Muertos en Michoac\u00e1n; estas son las actividades del 24 de octubre al 2 de noviembre","datePublished":"2025-10-10T21:11:43+00:00","mainEntityOfPage":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/vive-la-semana-de-noche-de-muertos-en-michoacan-estas-son-las-actividades-del-24-de-octubre-al-2-de-noviembre\/"},"wordCount":623,"image":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/vive-la-semana-de-noche-de-muertos-en-michoacan-estas-son-las-actividades-del-24-de-octubre-al-2-de-noviembre\/#primaryimage"},"thumbnailUrl":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/10\/Imagen-de-WhatsApp-2025-10-09-a-las-17.47.29_61a0e618.jpg","articleSection":["Estado","Gobierno de Michoac\u00e1n","Morelia","Pol\u00edtica","Slider"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/vive-la-semana-de-noche-de-muertos-en-michoacan-estas-son-las-actividades-del-24-de-octubre-al-2-de-noviembre\/","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/vive-la-semana-de-noche-de-muertos-en-michoacan-estas-son-las-actividades-del-24-de-octubre-al-2-de-noviembre\/","name":"Vive la Semana de Noche de Muertos en Michoac\u00e1n; estas son las actividades del 24 de octubre al 2 de noviembre - Diario ABC de Michoac\u00e1n","isPartOf":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/vive-la-semana-de-noche-de-muertos-en-michoacan-estas-son-las-actividades-del-24-de-octubre-al-2-de-noviembre\/#primaryimage"},"image":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/vive-la-semana-de-noche-de-muertos-en-michoacan-estas-son-las-actividades-del-24-de-octubre-al-2-de-noviembre\/#primaryimage"},"thumbnailUrl":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/10\/Imagen-de-WhatsApp-2025-10-09-a-las-17.47.29_61a0e618.jpg","datePublished":"2025-10-10T21:11:43+00:00","author":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/19ae376040f6cbc489682ebdd8524852"},"breadcrumb":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/vive-la-semana-de-noche-de-muertos-en-michoacan-estas-son-las-actividades-del-24-de-octubre-al-2-de-noviembre\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/vive-la-semana-de-noche-de-muertos-en-michoacan-estas-son-las-actividades-del-24-de-octubre-al-2-de-noviembre\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/vive-la-semana-de-noche-de-muertos-en-michoacan-estas-son-las-actividades-del-24-de-octubre-al-2-de-noviembre\/#primaryimage","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/10\/Imagen-de-WhatsApp-2025-10-09-a-las-17.47.29_61a0e618.jpg","contentUrl":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/10\/Imagen-de-WhatsApp-2025-10-09-a-las-17.47.29_61a0e618.jpg","width":1280,"height":852},{"@type":"BreadcrumbList","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/vive-la-semana-de-noche-de-muertos-en-michoacan-estas-son-las-actividades-del-24-de-octubre-al-2-de-noviembre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/"},{"@type":"ListItem","position":2,"name":"Vive la Semana de Noche de Muertos en Michoac\u00e1n; estas son las actividades del 24 de octubre al 2 de noviembre"}]},{"@type":"WebSite","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/","name":"Diario ABC de Michoac\u00e1n","description":"Las noticias al momento","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/19ae376040f6cbc489682ebdd8524852","name":"AR","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/620dde31bffc1d1abdb08a27461f06f796e6d74bba9feb506eda89b4e07120bb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/620dde31bffc1d1abdb08a27461f06f796e6d74bba9feb506eda89b4e07120bb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/620dde31bffc1d1abdb08a27461f06f796e6d74bba9feb506eda89b4e07120bb?s=96&d=mm&r=g","caption":"AR"},"url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/author\/adrian\/"}]}},"_links":{"self":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/70045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/comments?post=70045"}],"version-history":[{"count":1,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/70045\/revisions"}],"predecessor-version":[{"id":70048,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/70045\/revisions\/70048"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/media\/70046"}],"wp:attachment":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/media?parent=70045"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/categories?post=70045"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/tags?post=70045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}