{"id":70156,"date":"2025-10-13T14:37:25","date_gmt":"2025-10-13T20:37:25","guid":{"rendered":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?p=70156"},"modified":"2025-10-13T14:37:25","modified_gmt":"2025-10-13T20:37:25","slug":"garantizada-la-atencion-a-la-poblacion-personal-de-17-sindicatos-labora-con-normalidad-ssm","status":"publish","type":"post","link":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/garantizada-la-atencion-a-la-poblacion-personal-de-17-sindicatos-labora-con-normalidad-ssm\/","title":{"rendered":"Garantizada la atenci\u00f3n a la poblaci\u00f3n, personal de 17 sindicatos labora con normalidad: SSM"},"content":{"rendered":"<h2>Gobierno del Estado ha cumplido puntualmente con las obligaciones laborales y presupuestales.<\/h2>\n<p>&nbsp;<\/p>\n<hr \/>\n<p>Morelia, Mich.- La Secretar\u00eda de Salud de Michoac\u00e1n (SSM) informa a la ciudadan\u00eda que, a pesar de la toma de \u00e1reas administrativas y del Centro de Salud de Morelia por parte de tres grupos sindicales, la atenci\u00f3n m\u00e9dica y los servicios de salud a la poblaci\u00f3n michoacana se mantienen con normalidad.<\/p>\n<p>La SSM destaca el compromiso del personal de salud agremiado a 17 sindicatos, quienes contin\u00faan laborando de manera habitual en las distintas unidades m\u00e9dicas del estado, anteponiendo la salud y el bienestar de las y los michoacanos. Este amplio sector de trabajadores mantiene una operaci\u00f3n continua y sin interrupciones en la atenci\u00f3n a pacientes.<\/p>\n<p>En relaci\u00f3n a las demandas de los grupos manifestantes, la Secretar\u00eda de Salud es enf\u00e1tica al se\u00f1alar que no existe ning\u00fan adeudo pendiente de quincenas ni prestaciones con el personal de salud. La dependencia ha cumplido y contin\u00faa cumpliendo cabalmente con todas sus obligaciones salariales y contractuales.<\/p>\n<p>La Secretar\u00eda de Salud reitera su compromiso con el di\u00e1logo y la transparencia, prueba de ello es que, en un ejercicio de apertura institucional, las peticiones y demandas presentadas por los l\u00edderes sindicales fueron atendidas en conjunto con una comisi\u00f3n de diputados en el Sal\u00f3n de Recepciones del Congreso del Estado, donde se revis\u00f3 y constat\u00f3 la situaci\u00f3n actual de los pagos.<\/p>\n<p>El Gobierno del Estado ha cumplido puntualmente con las obligaciones laborales y presupuestales, garantizando la estabilidad y el funcionamiento del sistema de salud.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gobierno del Estado ha cumplido puntualmente con las obligaciones laborales y presupuestales. &nbsp; Morelia, Mich.- La Secretar\u00eda de Salud de Michoac\u00e1n (SSM) informa a la ciudadan\u00eda que, a pesar de la toma de \u00e1reas administrativas y del Centro de Salud de Morelia por parte de tres grupos sindicales, la atenci\u00f3n m\u00e9dica y los servicios de [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":70157,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,17,29,27],"tags":[],"class_list":{"0":"post-70156","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-estado","8":"category-gobierno-de-michoacan","9":"category-salud","10":"category-slider"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Garantizada la atenci\u00f3n a la poblaci\u00f3n, personal de 17 sindicatos labora con normalidad: SSM - Diario ABC de Michoac\u00e1n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/garantizada-la-atencion-a-la-poblacion-personal-de-17-sindicatos-labora-con-normalidad-ssm\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Garantizada la atenci\u00f3n a la poblaci\u00f3n, personal de 17 sindicatos labora con normalidad: SSM - Diario ABC de Michoac\u00e1n\" \/>\n<meta property=\"og:description\" content=\"Gobierno del Estado ha cumplido puntualmente con las obligaciones laborales y presupuestales. &nbsp; Morelia, Mich.- La Secretar\u00eda de Salud de Michoac\u00e1n (SSM) informa a la ciudadan\u00eda que, a pesar de la toma de \u00e1reas administrativas y del Centro de Salud de Morelia por parte de tres grupos sindicales, la atenci\u00f3n m\u00e9dica y los servicios de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/garantizada-la-atencion-a-la-poblacion-personal-de-17-sindicatos-labora-con-normalidad-ssm\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario ABC de Michoac\u00e1n\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-13T20:37:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/10\/Imagen-de-WhatsApp-2025-10-13-a-las-11.24.19_7ccd68d4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"880\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"AR\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"AR\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/garantizada-la-atencion-a-la-poblacion-personal-de-17-sindicatos-labora-con-normalidad-ssm\/\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/garantizada-la-atencion-a-la-poblacion-personal-de-17-sindicatos-labora-con-normalidad-ssm\/\",\"name\":\"Garantizada la atenci\u00f3n a la poblaci\u00f3n, personal de 17 sindicatos labora con normalidad: SSM - Diario ABC de Michoac\u00e1n\",\"isPartOf\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/garantizada-la-atencion-a-la-poblacion-personal-de-17-sindicatos-labora-con-normalidad-ssm\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/garantizada-la-atencion-a-la-poblacion-personal-de-17-sindicatos-labora-con-normalidad-ssm\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/10\/Imagen-de-WhatsApp-2025-10-13-a-las-11.24.19_7ccd68d4.jpg\",\"datePublished\":\"2025-10-13T20:37:25+00:00\",\"dateModified\":\"2025-10-13T20:37:25+00:00\",\"author\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/19ae376040f6cbc489682ebdd8524852\"},\"breadcrumb\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/garantizada-la-atencion-a-la-poblacion-personal-de-17-sindicatos-labora-con-normalidad-ssm\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/garantizada-la-atencion-a-la-poblacion-personal-de-17-sindicatos-labora-con-normalidad-ssm\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/garantizada-la-atencion-a-la-poblacion-personal-de-17-sindicatos-labora-con-normalidad-ssm\/#primaryimage\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/10\/Imagen-de-WhatsApp-2025-10-13-a-las-11.24.19_7ccd68d4.jpg\",\"contentUrl\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/10\/Imagen-de-WhatsApp-2025-10-13-a-las-11.24.19_7ccd68d4.jpg\",\"width\":1280,\"height\":880},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/garantizada-la-atencion-a-la-poblacion-personal-de-17-sindicatos-labora-con-normalidad-ssm\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Garantizada la atenci\u00f3n a la poblaci\u00f3n, personal de 17 sindicatos labora con normalidad: SSM\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/\",\"name\":\"Diario ABC de Michoac\u00e1n\",\"description\":\"Las noticias al momento\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/19ae376040f6cbc489682ebdd8524852\",\"name\":\"AR\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/44eca2ff970262234e20e1e082872af0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/44eca2ff970262234e20e1e082872af0?s=96&d=mm&r=g\",\"caption\":\"AR\"},\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/author\/adrian\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Garantizada la atenci\u00f3n a la poblaci\u00f3n, personal de 17 sindicatos labora con normalidad: SSM - Diario ABC de Michoac\u00e1n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/garantizada-la-atencion-a-la-poblacion-personal-de-17-sindicatos-labora-con-normalidad-ssm\/","og_locale":"es_ES","og_type":"article","og_title":"Garantizada la atenci\u00f3n a la poblaci\u00f3n, personal de 17 sindicatos labora con normalidad: SSM - Diario ABC de Michoac\u00e1n","og_description":"Gobierno del Estado ha cumplido puntualmente con las obligaciones laborales y presupuestales. &nbsp; Morelia, Mich.- La Secretar\u00eda de Salud de Michoac\u00e1n (SSM) informa a la ciudadan\u00eda que, a pesar de la toma de \u00e1reas administrativas y del Centro de Salud de Morelia por parte de tres grupos sindicales, la atenci\u00f3n m\u00e9dica y los servicios de [&hellip;]","og_url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/garantizada-la-atencion-a-la-poblacion-personal-de-17-sindicatos-labora-con-normalidad-ssm\/","og_site_name":"Diario ABC de Michoac\u00e1n","article_published_time":"2025-10-13T20:37:25+00:00","og_image":[{"width":1280,"height":880,"url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/10\/Imagen-de-WhatsApp-2025-10-13-a-las-11.24.19_7ccd68d4.jpg","type":"image\/jpeg"}],"author":"AR","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"AR","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/garantizada-la-atencion-a-la-poblacion-personal-de-17-sindicatos-labora-con-normalidad-ssm\/","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/garantizada-la-atencion-a-la-poblacion-personal-de-17-sindicatos-labora-con-normalidad-ssm\/","name":"Garantizada la atenci\u00f3n a la poblaci\u00f3n, personal de 17 sindicatos labora con normalidad: SSM - Diario ABC de Michoac\u00e1n","isPartOf":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/garantizada-la-atencion-a-la-poblacion-personal-de-17-sindicatos-labora-con-normalidad-ssm\/#primaryimage"},"image":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/garantizada-la-atencion-a-la-poblacion-personal-de-17-sindicatos-labora-con-normalidad-ssm\/#primaryimage"},"thumbnailUrl":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/10\/Imagen-de-WhatsApp-2025-10-13-a-las-11.24.19_7ccd68d4.jpg","datePublished":"2025-10-13T20:37:25+00:00","dateModified":"2025-10-13T20:37:25+00:00","author":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/19ae376040f6cbc489682ebdd8524852"},"breadcrumb":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/garantizada-la-atencion-a-la-poblacion-personal-de-17-sindicatos-labora-con-normalidad-ssm\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/garantizada-la-atencion-a-la-poblacion-personal-de-17-sindicatos-labora-con-normalidad-ssm\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/garantizada-la-atencion-a-la-poblacion-personal-de-17-sindicatos-labora-con-normalidad-ssm\/#primaryimage","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/10\/Imagen-de-WhatsApp-2025-10-13-a-las-11.24.19_7ccd68d4.jpg","contentUrl":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/10\/Imagen-de-WhatsApp-2025-10-13-a-las-11.24.19_7ccd68d4.jpg","width":1280,"height":880},{"@type":"BreadcrumbList","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/garantizada-la-atencion-a-la-poblacion-personal-de-17-sindicatos-labora-con-normalidad-ssm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/"},{"@type":"ListItem","position":2,"name":"Garantizada la atenci\u00f3n a la poblaci\u00f3n, personal de 17 sindicatos labora con normalidad: SSM"}]},{"@type":"WebSite","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/","name":"Diario ABC de Michoac\u00e1n","description":"Las noticias al momento","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/19ae376040f6cbc489682ebdd8524852","name":"AR","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/44eca2ff970262234e20e1e082872af0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/44eca2ff970262234e20e1e082872af0?s=96&d=mm&r=g","caption":"AR"},"url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/author\/adrian\/"}]}},"_links":{"self":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/70156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/comments?post=70156"}],"version-history":[{"count":1,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/70156\/revisions"}],"predecessor-version":[{"id":70158,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/70156\/revisions\/70158"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/media\/70157"}],"wp:attachment":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/media?parent=70156"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/categories?post=70156"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/tags?post=70156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}