{"id":72946,"date":"2025-12-03T14:08:36","date_gmt":"2025-12-03T20:08:36","guid":{"rendered":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?p=72946"},"modified":"2025-12-03T14:08:36","modified_gmt":"2025-12-03T20:08:36","slug":"somos-lideres-logramos-nuestro-primer-objetivo-cristian-el-tigre-castro","status":"publish","type":"post","link":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/somos-lideres-logramos-nuestro-primer-objetivo-cristian-el-tigre-castro\/","title":{"rendered":"Somos l\u00edderes, logramos nuestro primer objetivo: Cristian \u2018El Tigre\u2019 Castro"},"content":{"rendered":"<h2>El goleador del Atl\u00e9tico Morelia-UMSNH comparti\u00f3 que desde el inicio de la temporada se hab\u00edan trazado encabezar el grupo y calificar a Copa Conecta.<\/h2>\n<p>&nbsp;<\/p>\n<hr \/>\n<p>Morelia, Mich. &#8211; A falta de una jornada para que termine la primera vuelta de la Liga de Tercera Divisi\u00f3n Profesional (TDP) varonil, el Atl\u00e9tico Morelia-Universidad Michoacana asegur\u00f3 el liderato del Grupo 11, lo que le da la calificaci\u00f3n a Copa Conecta, con lo que se cumpli\u00f3 el primer objetivo, as\u00ed lo comparti\u00f3 el delantero, capit\u00e1n y goleador, Cristian Castro.<\/p>\n<p>\u201cEl grupo est\u00e1 muy feliz, desde el principio era nuestro objetivo y lo logramos. Ahora la meta ser\u00e1 seguir con el liderato y con el gran paso que tenemos de victorias, adem\u00e1s de la Copa Conecta, tenemos que pensar en eso\u201d.<\/p><div id=\"diari-3671788360\" class=\"diari-contenido diari-entity-placement\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-05-07-at-10.12.40-a.m.jpeg\" alt=\"\"  srcset=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-05-07-at-10.12.40-a.m.jpeg 400w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-05-07-at-10.12.40-a.m-150x150.jpeg 150w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-05-07-at-10.12.40-a.m-300x300.jpeg 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" width=\"400\" height=\"400\"  style=\"display: inline-block;\" \/><\/div>\n<p>En lo que se refiere al plano individual, \u2018El Tigre\u2019, quien actualmente es l\u00edder de goleo del sector y es sexto a nivel nacional con 16 anotaciones en 10 partidos, se mostr\u00f3 satisfecho por ayudar a la escuadra.<\/p>\n<p>\u201cPersonalmente me siento muy feliz, creo que el equipo ha trabajado muy bien y yo sigo aportando goles\u201d, asegur\u00f3 Castro Ortiz, quien busca el bicampeonato de goleo del Grupo 11.<\/p>\n<p>Por su parte, el tambi\u00e9n delantero nicolaita, Amir Marines tambi\u00e9n destac\u00f3 el nivel que ha manifestado el conjunto, adem\u00e1s se mostr\u00f3 contento por el buen momento personal que vive. \u201cNo podemos bajar la cabeza, esto es lo que nos representa, cada uno de los jugadores da todo por el equipo. Me siento muy feliz, hubo una rachita en la que no me sal\u00edan las cosas en el gol, pero yo creo que ahorita no tengo que bajar el ritmo\u201d.<\/p>\n<p>Cabe mencionar que por el momento los Zorros tienen unos d\u00edas de vacaciones y pr\u00f3ximamente retomar\u00e1n los entrenamientos de cara a la segunda vuelta del campeonato y de la Copa Conecta, que se jugar\u00e1n a partir de mediados de enero.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El goleador del Atl\u00e9tico Morelia-UMSNH comparti\u00f3 que desde el inicio de la temporada se hab\u00edan trazado encabezar el grupo y calificar a Copa Conecta. &nbsp; Morelia, Mich. &#8211; A falta de una jornada para que termine la primera vuelta de la Liga de Tercera Divisi\u00f3n Profesional (TDP) varonil, el Atl\u00e9tico Morelia-Universidad Michoacana asegur\u00f3 el liderato [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":72947,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,27,23],"tags":[],"class_list":["post-72946","post","type-post","status-publish","format-standard","has-post-thumbnail","category-deportes","category-slider","category-universidad-michoacana"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Somos l\u00edderes, logramos nuestro primer objetivo: Cristian \u2018El Tigre\u2019 Castro - Diario ABC de Michoac\u00e1n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/somos-lideres-logramos-nuestro-primer-objetivo-cristian-el-tigre-castro\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Somos l\u00edderes, logramos nuestro primer objetivo: Cristian \u2018El Tigre\u2019 Castro - Diario ABC de Michoac\u00e1n\" \/>\n<meta property=\"og:description\" content=\"El goleador del Atl\u00e9tico Morelia-UMSNH comparti\u00f3 que desde el inicio de la temporada se hab\u00edan trazado encabezar el grupo y calificar a Copa Conecta. &nbsp; Morelia, Mich. &#8211; A falta de una jornada para que termine la primera vuelta de la Liga de Tercera Divisi\u00f3n Profesional (TDP) varonil, el Atl\u00e9tico Morelia-Universidad Michoacana asegur\u00f3 el liderato [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/somos-lideres-logramos-nuestro-primer-objetivo-cristian-el-tigre-castro\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario ABC de Michoac\u00e1n\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-03T20:08:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/12\/Imagen-de-WhatsApp-2025-12-02-a-las-18.55.17_e2a9dbec.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"AR\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"AR\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/somos-lideres-logramos-nuestro-primer-objetivo-cristian-el-tigre-castro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/somos-lideres-logramos-nuestro-primer-objetivo-cristian-el-tigre-castro\\\/\"},\"author\":{\"name\":\"AR\",\"@id\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/#\\\/schema\\\/person\\\/19ae376040f6cbc489682ebdd8524852\"},\"headline\":\"Somos l\u00edderes, logramos nuestro primer objetivo: Cristian \u2018El Tigre\u2019 Castro\",\"datePublished\":\"2025-12-03T20:08:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/somos-lideres-logramos-nuestro-primer-objetivo-cristian-el-tigre-castro\\\/\"},\"wordCount\":336,\"image\":{\"@id\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/somos-lideres-logramos-nuestro-primer-objetivo-cristian-el-tigre-castro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Imagen-de-WhatsApp-2025-12-02-a-las-18.55.17_e2a9dbec.jpg\",\"articleSection\":[\"Deportes\",\"Slider\",\"Universidad Michoacana\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/somos-lideres-logramos-nuestro-primer-objetivo-cristian-el-tigre-castro\\\/\",\"url\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/somos-lideres-logramos-nuestro-primer-objetivo-cristian-el-tigre-castro\\\/\",\"name\":\"Somos l\u00edderes, logramos nuestro primer objetivo: Cristian \u2018El Tigre\u2019 Castro - Diario ABC de Michoac\u00e1n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/somos-lideres-logramos-nuestro-primer-objetivo-cristian-el-tigre-castro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/somos-lideres-logramos-nuestro-primer-objetivo-cristian-el-tigre-castro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Imagen-de-WhatsApp-2025-12-02-a-las-18.55.17_e2a9dbec.jpg\",\"datePublished\":\"2025-12-03T20:08:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/#\\\/schema\\\/person\\\/19ae376040f6cbc489682ebdd8524852\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/somos-lideres-logramos-nuestro-primer-objetivo-cristian-el-tigre-castro\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/somos-lideres-logramos-nuestro-primer-objetivo-cristian-el-tigre-castro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/somos-lideres-logramos-nuestro-primer-objetivo-cristian-el-tigre-castro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Imagen-de-WhatsApp-2025-12-02-a-las-18.55.17_e2a9dbec.jpg\",\"contentUrl\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Imagen-de-WhatsApp-2025-12-02-a-las-18.55.17_e2a9dbec.jpg\",\"width\":960,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/somos-lideres-logramos-nuestro-primer-objetivo-cristian-el-tigre-castro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Somos l\u00edderes, logramos nuestro primer objetivo: Cristian \u2018El Tigre\u2019 Castro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/#website\",\"url\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/\",\"name\":\"Diario ABC de Michoac\u00e1n\",\"description\":\"Las noticias al momento\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/#\\\/schema\\\/person\\\/19ae376040f6cbc489682ebdd8524852\",\"name\":\"AR\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/620dde31bffc1d1abdb08a27461f06f796e6d74bba9feb506eda89b4e07120bb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/620dde31bffc1d1abdb08a27461f06f796e6d74bba9feb506eda89b4e07120bb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/620dde31bffc1d1abdb08a27461f06f796e6d74bba9feb506eda89b4e07120bb?s=96&d=mm&r=g\",\"caption\":\"AR\"},\"url\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/author\\\/adrian\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Somos l\u00edderes, logramos nuestro primer objetivo: Cristian \u2018El Tigre\u2019 Castro - Diario ABC de Michoac\u00e1n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/somos-lideres-logramos-nuestro-primer-objetivo-cristian-el-tigre-castro\/","og_locale":"es_ES","og_type":"article","og_title":"Somos l\u00edderes, logramos nuestro primer objetivo: Cristian \u2018El Tigre\u2019 Castro - Diario ABC de Michoac\u00e1n","og_description":"El goleador del Atl\u00e9tico Morelia-UMSNH comparti\u00f3 que desde el inicio de la temporada se hab\u00edan trazado encabezar el grupo y calificar a Copa Conecta. &nbsp; Morelia, Mich. &#8211; A falta de una jornada para que termine la primera vuelta de la Liga de Tercera Divisi\u00f3n Profesional (TDP) varonil, el Atl\u00e9tico Morelia-Universidad Michoacana asegur\u00f3 el liderato [&hellip;]","og_url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/somos-lideres-logramos-nuestro-primer-objetivo-cristian-el-tigre-castro\/","og_site_name":"Diario ABC de Michoac\u00e1n","article_published_time":"2025-12-03T20:08:36+00:00","og_image":[{"width":960,"height":1280,"url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/12\/Imagen-de-WhatsApp-2025-12-02-a-las-18.55.17_e2a9dbec.jpg","type":"image\/jpeg"}],"author":"AR","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"AR","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/somos-lideres-logramos-nuestro-primer-objetivo-cristian-el-tigre-castro\/#article","isPartOf":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/somos-lideres-logramos-nuestro-primer-objetivo-cristian-el-tigre-castro\/"},"author":{"name":"AR","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/19ae376040f6cbc489682ebdd8524852"},"headline":"Somos l\u00edderes, logramos nuestro primer objetivo: Cristian \u2018El Tigre\u2019 Castro","datePublished":"2025-12-03T20:08:36+00:00","mainEntityOfPage":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/somos-lideres-logramos-nuestro-primer-objetivo-cristian-el-tigre-castro\/"},"wordCount":336,"image":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/somos-lideres-logramos-nuestro-primer-objetivo-cristian-el-tigre-castro\/#primaryimage"},"thumbnailUrl":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/12\/Imagen-de-WhatsApp-2025-12-02-a-las-18.55.17_e2a9dbec.jpg","articleSection":["Deportes","Slider","Universidad Michoacana"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/somos-lideres-logramos-nuestro-primer-objetivo-cristian-el-tigre-castro\/","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/somos-lideres-logramos-nuestro-primer-objetivo-cristian-el-tigre-castro\/","name":"Somos l\u00edderes, logramos nuestro primer objetivo: Cristian \u2018El Tigre\u2019 Castro - Diario ABC de Michoac\u00e1n","isPartOf":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/somos-lideres-logramos-nuestro-primer-objetivo-cristian-el-tigre-castro\/#primaryimage"},"image":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/somos-lideres-logramos-nuestro-primer-objetivo-cristian-el-tigre-castro\/#primaryimage"},"thumbnailUrl":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/12\/Imagen-de-WhatsApp-2025-12-02-a-las-18.55.17_e2a9dbec.jpg","datePublished":"2025-12-03T20:08:36+00:00","author":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/19ae376040f6cbc489682ebdd8524852"},"breadcrumb":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/somos-lideres-logramos-nuestro-primer-objetivo-cristian-el-tigre-castro\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/somos-lideres-logramos-nuestro-primer-objetivo-cristian-el-tigre-castro\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/somos-lideres-logramos-nuestro-primer-objetivo-cristian-el-tigre-castro\/#primaryimage","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/12\/Imagen-de-WhatsApp-2025-12-02-a-las-18.55.17_e2a9dbec.jpg","contentUrl":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2025\/12\/Imagen-de-WhatsApp-2025-12-02-a-las-18.55.17_e2a9dbec.jpg","width":960,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/somos-lideres-logramos-nuestro-primer-objetivo-cristian-el-tigre-castro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/"},{"@type":"ListItem","position":2,"name":"Somos l\u00edderes, logramos nuestro primer objetivo: Cristian \u2018El Tigre\u2019 Castro"}]},{"@type":"WebSite","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/","name":"Diario ABC de Michoac\u00e1n","description":"Las noticias al momento","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/19ae376040f6cbc489682ebdd8524852","name":"AR","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/620dde31bffc1d1abdb08a27461f06f796e6d74bba9feb506eda89b4e07120bb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/620dde31bffc1d1abdb08a27461f06f796e6d74bba9feb506eda89b4e07120bb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/620dde31bffc1d1abdb08a27461f06f796e6d74bba9feb506eda89b4e07120bb?s=96&d=mm&r=g","caption":"AR"},"url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/author\/adrian\/"}]}},"_links":{"self":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/72946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/comments?post=72946"}],"version-history":[{"count":1,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/72946\/revisions"}],"predecessor-version":[{"id":72948,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/72946\/revisions\/72948"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/media\/72947"}],"wp:attachment":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/media?parent=72946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/categories?post=72946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/tags?post=72946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}