{"id":78610,"date":"2026-04-12T13:45:06","date_gmt":"2026-04-12T19:45:06","guid":{"rendered":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?p=78610"},"modified":"2026-04-12T13:45:06","modified_gmt":"2026-04-12T19:45:06","slug":"fabiola-alanis-reconoce-el-liderazgo-de-las-mujeres-en-la-agroindustria-de-la-fresa-en-jacona","status":"publish","type":"post","link":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/fabiola-alanis-reconoce-el-liderazgo-de-las-mujeres-en-la-agroindustria-de-la-fresa-en-jacona\/","title":{"rendered":"Fabiola Alan\u00eds reconoce el liderazgo de las mujeres en la agroindustria de la fresa en Jacona"},"content":{"rendered":"<p>Jacona, Michoac\u00e1n, a 12 de abril de 2026.\u2013 En una visita a un huerto de fresa en el municipio de Jacona, la diputada Fabiola Alan\u00eds destac\u00f3 el papel estrat\u00e9gico de las y los trabajadores del campo en el desarrollo econ\u00f3mico de la regi\u00f3n, con especial \u00e9nfasis en la participaci\u00f3n de las mujeres dentro de la agroindustria.<\/p>\n<p>Durante el recorrido por el sembrad\u00edo \u2014que cuenta con certificaciones de calidad para exportaci\u00f3n\u2014 se inform\u00f3 que cerca de 60 personas laboran en este espacio productivo, de las cuales entre el 80 y 85 por ciento son mujeres. Su participaci\u00f3n es clave en las distintas etapas del proceso, desde la siembra hasta la cosecha y selecci\u00f3n del producto.<\/p><div id=\"diari-4238605636\" class=\"diari-contenido diari-entity-placement\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-05-07-at-10.12.40-a.m.jpeg\" alt=\"\"  srcset=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-05-07-at-10.12.40-a.m.jpeg 400w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-05-07-at-10.12.40-a.m-150x150.jpeg 150w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-05-07-at-10.12.40-a.m-300x300.jpeg 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" width=\"400\" height=\"400\"  style=\"display: inline-block;\" \/><\/div>\n<p>\u201cReconocer el trabajo de las mujeres en el campo no es opcional, es un acto de justicia. Son ellas quienes sostienen gran parte de la agroindustria en nuestro estado. Por eso debemos garantizar condiciones de igualdad, incluyendo salario igual por trabajo igual\u201d, subray\u00f3 la legisladora.<\/p>\n<p>En este contexto, destac\u00f3 que Jacona se ha consolidado como uno de los principales polos de producci\u00f3n de fresa de calidad de exportaci\u00f3n, con env\u00edos constantes principalmente hacia Estados Unidos. Si bien el pico de producci\u00f3n se concentra en febrero, la actividad se mantiene durante buena parte del a\u00f1o, lo que permite una presencia sostenida en mercados internacionales.<\/p>\n<p>Fabiola Alan\u00eds enfatiz\u00f3 que el fortalecimiento de la agroindustria no solo impulsa la competitividad de Michoac\u00e1n, sino que tambi\u00e9n representa una v\u00eda directa para mejorar la calidad de vida de miles de familias.<\/p>\n<p>\u201cCuando apoyamos al campo, apoyamos la econom\u00eda de nuestras comunidades. Aqu\u00ed se generan empleos, se construye bienestar y se abren oportunidades reales para las familias michoacanas\u201d, afirm\u00f3.<\/p>\n<p>Finalmente, resalt\u00f3 que Jacona no solo destaca por la producci\u00f3n agr\u00edcola, sino tambi\u00e9n por su capacidad de integraci\u00f3n a cadenas de valor, a trav\u00e9s de procesos como el empaque y la transformaci\u00f3n de la fresa, lo que ampl\u00eda su aprovechamiento en distintas industrias y fortalece su impacto econ\u00f3mico en la regi\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jacona, Michoac\u00e1n, a 12 de abril de 2026.\u2013 En una visita a un huerto de fresa en el municipio de Jacona, la diputada Fabiola Alan\u00eds destac\u00f3 el papel estrat\u00e9gico de las y los trabajadores del campo en el desarrollo econ\u00f3mico de la regi\u00f3n, con especial \u00e9nfasis en la participaci\u00f3n de las mujeres dentro de la [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":78611,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,22,10,28,5],"tags":[],"class_list":["post-78610","post","type-post","status-publish","format-standard","has-post-thumbnail","category-congreso","category-congreso-de-michoacan","category-estado","category-politica","category-zamora"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fabiola Alan\u00eds reconoce el liderazgo de las mujeres en la agroindustria de la fresa en Jacona - Diario ABC de Michoac\u00e1n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/fabiola-alanis-reconoce-el-liderazgo-de-las-mujeres-en-la-agroindustria-de-la-fresa-en-jacona\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fabiola Alan\u00eds reconoce el liderazgo de las mujeres en la agroindustria de la fresa en Jacona - Diario ABC de Michoac\u00e1n\" \/>\n<meta property=\"og:description\" content=\"Jacona, Michoac\u00e1n, a 12 de abril de 2026.\u2013 En una visita a un huerto de fresa en el municipio de Jacona, la diputada Fabiola Alan\u00eds destac\u00f3 el papel estrat\u00e9gico de las y los trabajadores del campo en el desarrollo econ\u00f3mico de la regi\u00f3n, con especial \u00e9nfasis en la participaci\u00f3n de las mujeres dentro de la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/fabiola-alanis-reconoce-el-liderazgo-de-las-mujeres-en-la-agroindustria-de-la-fresa-en-jacona\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario ABC de Michoac\u00e1n\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-12T19:45:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2026\/04\/IMG-20260412-WA0020.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1066\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MB\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MB\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/fabiola-alanis-reconoce-el-liderazgo-de-las-mujeres-en-la-agroindustria-de-la-fresa-en-jacona\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/fabiola-alanis-reconoce-el-liderazgo-de-las-mujeres-en-la-agroindustria-de-la-fresa-en-jacona\\\/\"},\"author\":{\"name\":\"MB\",\"@id\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/#\\\/schema\\\/person\\\/0546f9c3407148f7452ca932715c5e88\"},\"headline\":\"Fabiola Alan\u00eds reconoce el liderazgo de las mujeres en la agroindustria de la fresa en Jacona\",\"datePublished\":\"2026-04-12T19:45:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/fabiola-alanis-reconoce-el-liderazgo-de-las-mujeres-en-la-agroindustria-de-la-fresa-en-jacona\\\/\"},\"wordCount\":369,\"image\":{\"@id\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/fabiola-alanis-reconoce-el-liderazgo-de-las-mujeres-en-la-agroindustria-de-la-fresa-en-jacona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/IMG-20260412-WA0020.jpg\",\"articleSection\":[\"Congreso\",\"Congreso de Michoac\u00e1n\",\"Estado\",\"Pol\u00edtica\",\"Zamora\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/fabiola-alanis-reconoce-el-liderazgo-de-las-mujeres-en-la-agroindustria-de-la-fresa-en-jacona\\\/\",\"url\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/fabiola-alanis-reconoce-el-liderazgo-de-las-mujeres-en-la-agroindustria-de-la-fresa-en-jacona\\\/\",\"name\":\"Fabiola Alan\u00eds reconoce el liderazgo de las mujeres en la agroindustria de la fresa en Jacona - Diario ABC de Michoac\u00e1n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/fabiola-alanis-reconoce-el-liderazgo-de-las-mujeres-en-la-agroindustria-de-la-fresa-en-jacona\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/fabiola-alanis-reconoce-el-liderazgo-de-las-mujeres-en-la-agroindustria-de-la-fresa-en-jacona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/IMG-20260412-WA0020.jpg\",\"datePublished\":\"2026-04-12T19:45:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/#\\\/schema\\\/person\\\/0546f9c3407148f7452ca932715c5e88\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/fabiola-alanis-reconoce-el-liderazgo-de-las-mujeres-en-la-agroindustria-de-la-fresa-en-jacona\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/fabiola-alanis-reconoce-el-liderazgo-de-las-mujeres-en-la-agroindustria-de-la-fresa-en-jacona\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/fabiola-alanis-reconoce-el-liderazgo-de-las-mujeres-en-la-agroindustria-de-la-fresa-en-jacona\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/IMG-20260412-WA0020.jpg\",\"contentUrl\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/IMG-20260412-WA0020.jpg\",\"width\":1600,\"height\":1066},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/fabiola-alanis-reconoce-el-liderazgo-de-las-mujeres-en-la-agroindustria-de-la-fresa-en-jacona\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fabiola Alan\u00eds reconoce el liderazgo de las mujeres en la agroindustria de la fresa en Jacona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/#website\",\"url\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/\",\"name\":\"Diario ABC de Michoac\u00e1n\",\"description\":\"Las noticias al momento\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/#\\\/schema\\\/person\\\/0546f9c3407148f7452ca932715c5e88\",\"name\":\"MB\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ac036f018f6a8431a5687a020efaf39d914da6a3fc78ce6029ab7ae29c5130e2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ac036f018f6a8431a5687a020efaf39d914da6a3fc78ce6029ab7ae29c5130e2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ac036f018f6a8431a5687a020efaf39d914da6a3fc78ce6029ab7ae29c5130e2?s=96&d=mm&r=g\",\"caption\":\"MB\"},\"url\":\"https:\\\/\\\/diarioabcdemichoacan.com.mx\\\/lasnoticias\\\/author\\\/bomariano03\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fabiola Alan\u00eds reconoce el liderazgo de las mujeres en la agroindustria de la fresa en Jacona - Diario ABC de Michoac\u00e1n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/fabiola-alanis-reconoce-el-liderazgo-de-las-mujeres-en-la-agroindustria-de-la-fresa-en-jacona\/","og_locale":"es_ES","og_type":"article","og_title":"Fabiola Alan\u00eds reconoce el liderazgo de las mujeres en la agroindustria de la fresa en Jacona - Diario ABC de Michoac\u00e1n","og_description":"Jacona, Michoac\u00e1n, a 12 de abril de 2026.\u2013 En una visita a un huerto de fresa en el municipio de Jacona, la diputada Fabiola Alan\u00eds destac\u00f3 el papel estrat\u00e9gico de las y los trabajadores del campo en el desarrollo econ\u00f3mico de la regi\u00f3n, con especial \u00e9nfasis en la participaci\u00f3n de las mujeres dentro de la [&hellip;]","og_url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/fabiola-alanis-reconoce-el-liderazgo-de-las-mujeres-en-la-agroindustria-de-la-fresa-en-jacona\/","og_site_name":"Diario ABC de Michoac\u00e1n","article_published_time":"2026-04-12T19:45:06+00:00","og_image":[{"width":1600,"height":1066,"url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2026\/04\/IMG-20260412-WA0020.jpg","type":"image\/jpeg"}],"author":"MB","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"MB","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/fabiola-alanis-reconoce-el-liderazgo-de-las-mujeres-en-la-agroindustria-de-la-fresa-en-jacona\/#article","isPartOf":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/fabiola-alanis-reconoce-el-liderazgo-de-las-mujeres-en-la-agroindustria-de-la-fresa-en-jacona\/"},"author":{"name":"MB","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/0546f9c3407148f7452ca932715c5e88"},"headline":"Fabiola Alan\u00eds reconoce el liderazgo de las mujeres en la agroindustria de la fresa en Jacona","datePublished":"2026-04-12T19:45:06+00:00","mainEntityOfPage":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/fabiola-alanis-reconoce-el-liderazgo-de-las-mujeres-en-la-agroindustria-de-la-fresa-en-jacona\/"},"wordCount":369,"image":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/fabiola-alanis-reconoce-el-liderazgo-de-las-mujeres-en-la-agroindustria-de-la-fresa-en-jacona\/#primaryimage"},"thumbnailUrl":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2026\/04\/IMG-20260412-WA0020.jpg","articleSection":["Congreso","Congreso de Michoac\u00e1n","Estado","Pol\u00edtica","Zamora"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/fabiola-alanis-reconoce-el-liderazgo-de-las-mujeres-en-la-agroindustria-de-la-fresa-en-jacona\/","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/fabiola-alanis-reconoce-el-liderazgo-de-las-mujeres-en-la-agroindustria-de-la-fresa-en-jacona\/","name":"Fabiola Alan\u00eds reconoce el liderazgo de las mujeres en la agroindustria de la fresa en Jacona - Diario ABC de Michoac\u00e1n","isPartOf":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/fabiola-alanis-reconoce-el-liderazgo-de-las-mujeres-en-la-agroindustria-de-la-fresa-en-jacona\/#primaryimage"},"image":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/fabiola-alanis-reconoce-el-liderazgo-de-las-mujeres-en-la-agroindustria-de-la-fresa-en-jacona\/#primaryimage"},"thumbnailUrl":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2026\/04\/IMG-20260412-WA0020.jpg","datePublished":"2026-04-12T19:45:06+00:00","author":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/0546f9c3407148f7452ca932715c5e88"},"breadcrumb":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/fabiola-alanis-reconoce-el-liderazgo-de-las-mujeres-en-la-agroindustria-de-la-fresa-en-jacona\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/fabiola-alanis-reconoce-el-liderazgo-de-las-mujeres-en-la-agroindustria-de-la-fresa-en-jacona\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/fabiola-alanis-reconoce-el-liderazgo-de-las-mujeres-en-la-agroindustria-de-la-fresa-en-jacona\/#primaryimage","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2026\/04\/IMG-20260412-WA0020.jpg","contentUrl":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2026\/04\/IMG-20260412-WA0020.jpg","width":1600,"height":1066},{"@type":"BreadcrumbList","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/fabiola-alanis-reconoce-el-liderazgo-de-las-mujeres-en-la-agroindustria-de-la-fresa-en-jacona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/"},{"@type":"ListItem","position":2,"name":"Fabiola Alan\u00eds reconoce el liderazgo de las mujeres en la agroindustria de la fresa en Jacona"}]},{"@type":"WebSite","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/","name":"Diario ABC de Michoac\u00e1n","description":"Las noticias al momento","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/0546f9c3407148f7452ca932715c5e88","name":"MB","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/ac036f018f6a8431a5687a020efaf39d914da6a3fc78ce6029ab7ae29c5130e2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ac036f018f6a8431a5687a020efaf39d914da6a3fc78ce6029ab7ae29c5130e2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ac036f018f6a8431a5687a020efaf39d914da6a3fc78ce6029ab7ae29c5130e2?s=96&d=mm&r=g","caption":"MB"},"url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/author\/bomariano03\/"}]}},"_links":{"self":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/78610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/comments?post=78610"}],"version-history":[{"count":1,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/78610\/revisions"}],"predecessor-version":[{"id":78612,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/78610\/revisions\/78612"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/media\/78611"}],"wp:attachment":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/media?parent=78610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/categories?post=78610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/tags?post=78610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}