{"id":79638,"date":"2026-05-11T17:01:05","date_gmt":"2026-05-11T23:01:05","guid":{"rendered":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?p=79638"},"modified":"2026-05-11T17:01:05","modified_gmt":"2026-05-11T23:01:05","slug":"bedolla-llama-a-mantener-buena-relacion-con-sindicatos-ante-huelga-en-la-umsnh","status":"publish","type":"post","link":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/bedolla-llama-a-mantener-buena-relacion-con-sindicatos-ante-huelga-en-la-umsnh\/","title":{"rendered":"Bedolla llama a mantener buena relaci\u00f3n con sindicatos, ante huelga en la UMSNH"},"content":{"rendered":"<p>Por Mariano Bola\u00f1os Monta\u00f1ez<\/p>\n<hr \/>\n<p>Morelia, Mich.- A casi tres semanas del estallamiento de huelga en la Universidad Michoacana de San Nicol\u00e1s de Hidalgo (UMSNH), el gobernador Alfredo Ram\u00edrez Bedolla expres\u00f3 su confianza en que pronto se alcance un acuerdo entre las partes involucradas para reanudar las clases presenciales.<\/p>\n<p>Durante conferencia de prensa, el mandatario estatal se\u00f1al\u00f3 que las huelgas generan \u201cdeterioro y p\u00e9rdida\u201d, adem\u00e1s de reconocer que las negociaciones suelen ser complejas, por lo que hizo un llamado a evitarlas y cuidar la relaci\u00f3n con los sindicatos, aun cuando existan diferencias de postura.<\/p>\n<p>Bedolla record\u00f3 que contin\u00faan las mesas de di\u00e1logo entre la Rector\u00eda de la Casa de Hidalgo y el Sindicato \u00danico de Empleados de la Universidad Michoacana (SUEUM), destacando que la m\u00e1s reciente reuni\u00f3n se realiz\u00f3 el pasado s\u00e1bado.<\/p>\n<p>Finalmente reconoci\u00f3 que aunque el gobierno estatal ha acompa\u00f1ado el conflicto laboral, las resoluciones requieren consenso y tiempo, confiando en que pronto se retiren las banderas rojinegras de las facultades y dependencias universitarias<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Mariano Bola\u00f1os Monta\u00f1ez Morelia, Mich.- A casi tres semanas del estallamiento de huelga en la Universidad Michoacana de San Nicol\u00e1s de Hidalgo (UMSNH), el gobernador Alfredo Ram\u00edrez Bedolla expres\u00f3 su confianza en que pronto se alcance un acuerdo entre las partes involucradas para reanudar las clases presenciales. Durante conferencia de prensa, el mandatario estatal [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":79639,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,10,17,23],"tags":[],"class_list":{"0":"post-79638","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-educacion","8":"category-estado","9":"category-gobierno-de-michoacan","10":"category-universidad-michoacana"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bedolla llama a mantener buena relaci\u00f3n con sindicatos, ante huelga en la UMSNH - Diario ABC de Michoac\u00e1n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/bedolla-llama-a-mantener-buena-relacion-con-sindicatos-ante-huelga-en-la-umsnh\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bedolla llama a mantener buena relaci\u00f3n con sindicatos, ante huelga en la UMSNH - Diario ABC de Michoac\u00e1n\" \/>\n<meta property=\"og:description\" content=\"Por Mariano Bola\u00f1os Monta\u00f1ez Morelia, Mich.- A casi tres semanas del estallamiento de huelga en la Universidad Michoacana de San Nicol\u00e1s de Hidalgo (UMSNH), el gobernador Alfredo Ram\u00edrez Bedolla expres\u00f3 su confianza en que pronto se alcance un acuerdo entre las partes involucradas para reanudar las clases presenciales. Durante conferencia de prensa, el mandatario estatal [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/bedolla-llama-a-mantener-buena-relacion-con-sindicatos-ante-huelga-en-la-umsnh\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario ABC de Michoac\u00e1n\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-11T23:01:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2026\/05\/286179e2-3f8f-4181-943f-8b3bf8c33c9f.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"964\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MB\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MB\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/bedolla-llama-a-mantener-buena-relacion-con-sindicatos-ante-huelga-en-la-umsnh\/\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/bedolla-llama-a-mantener-buena-relacion-con-sindicatos-ante-huelga-en-la-umsnh\/\",\"name\":\"Bedolla llama a mantener buena relaci\u00f3n con sindicatos, ante huelga en la UMSNH - Diario ABC de Michoac\u00e1n\",\"isPartOf\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/bedolla-llama-a-mantener-buena-relacion-con-sindicatos-ante-huelga-en-la-umsnh\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/bedolla-llama-a-mantener-buena-relacion-con-sindicatos-ante-huelga-en-la-umsnh\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2026\/05\/286179e2-3f8f-4181-943f-8b3bf8c33c9f.jpg\",\"datePublished\":\"2026-05-11T23:01:05+00:00\",\"dateModified\":\"2026-05-11T23:01:05+00:00\",\"author\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/0546f9c3407148f7452ca932715c5e88\"},\"breadcrumb\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/bedolla-llama-a-mantener-buena-relacion-con-sindicatos-ante-huelga-en-la-umsnh\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/bedolla-llama-a-mantener-buena-relacion-con-sindicatos-ante-huelga-en-la-umsnh\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/bedolla-llama-a-mantener-buena-relacion-con-sindicatos-ante-huelga-en-la-umsnh\/#primaryimage\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2026\/05\/286179e2-3f8f-4181-943f-8b3bf8c33c9f.jpg\",\"contentUrl\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2026\/05\/286179e2-3f8f-4181-943f-8b3bf8c33c9f.jpg\",\"width\":1600,\"height\":964},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/bedolla-llama-a-mantener-buena-relacion-con-sindicatos-ante-huelga-en-la-umsnh\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bedolla llama a mantener buena relaci\u00f3n con sindicatos, ante huelga en la UMSNH\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/\",\"name\":\"Diario ABC de Michoac\u00e1n\",\"description\":\"Las noticias al momento\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/0546f9c3407148f7452ca932715c5e88\",\"name\":\"MB\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/adcd41fde6b8d0b5d9d0de001d3112b3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/adcd41fde6b8d0b5d9d0de001d3112b3?s=96&d=mm&r=g\",\"caption\":\"MB\"},\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/author\/bomariano03\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bedolla llama a mantener buena relaci\u00f3n con sindicatos, ante huelga en la UMSNH - Diario ABC de Michoac\u00e1n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/bedolla-llama-a-mantener-buena-relacion-con-sindicatos-ante-huelga-en-la-umsnh\/","og_locale":"es_ES","og_type":"article","og_title":"Bedolla llama a mantener buena relaci\u00f3n con sindicatos, ante huelga en la UMSNH - Diario ABC de Michoac\u00e1n","og_description":"Por Mariano Bola\u00f1os Monta\u00f1ez Morelia, Mich.- A casi tres semanas del estallamiento de huelga en la Universidad Michoacana de San Nicol\u00e1s de Hidalgo (UMSNH), el gobernador Alfredo Ram\u00edrez Bedolla expres\u00f3 su confianza en que pronto se alcance un acuerdo entre las partes involucradas para reanudar las clases presenciales. Durante conferencia de prensa, el mandatario estatal [&hellip;]","og_url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/bedolla-llama-a-mantener-buena-relacion-con-sindicatos-ante-huelga-en-la-umsnh\/","og_site_name":"Diario ABC de Michoac\u00e1n","article_published_time":"2026-05-11T23:01:05+00:00","og_image":[{"width":1600,"height":964,"url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2026\/05\/286179e2-3f8f-4181-943f-8b3bf8c33c9f.jpg","type":"image\/jpeg"}],"author":"MB","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"MB","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/bedolla-llama-a-mantener-buena-relacion-con-sindicatos-ante-huelga-en-la-umsnh\/","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/bedolla-llama-a-mantener-buena-relacion-con-sindicatos-ante-huelga-en-la-umsnh\/","name":"Bedolla llama a mantener buena relaci\u00f3n con sindicatos, ante huelga en la UMSNH - Diario ABC de Michoac\u00e1n","isPartOf":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/bedolla-llama-a-mantener-buena-relacion-con-sindicatos-ante-huelga-en-la-umsnh\/#primaryimage"},"image":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/bedolla-llama-a-mantener-buena-relacion-con-sindicatos-ante-huelga-en-la-umsnh\/#primaryimage"},"thumbnailUrl":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2026\/05\/286179e2-3f8f-4181-943f-8b3bf8c33c9f.jpg","datePublished":"2026-05-11T23:01:05+00:00","dateModified":"2026-05-11T23:01:05+00:00","author":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/0546f9c3407148f7452ca932715c5e88"},"breadcrumb":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/bedolla-llama-a-mantener-buena-relacion-con-sindicatos-ante-huelga-en-la-umsnh\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/bedolla-llama-a-mantener-buena-relacion-con-sindicatos-ante-huelga-en-la-umsnh\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/bedolla-llama-a-mantener-buena-relacion-con-sindicatos-ante-huelga-en-la-umsnh\/#primaryimage","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2026\/05\/286179e2-3f8f-4181-943f-8b3bf8c33c9f.jpg","contentUrl":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2026\/05\/286179e2-3f8f-4181-943f-8b3bf8c33c9f.jpg","width":1600,"height":964},{"@type":"BreadcrumbList","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/bedolla-llama-a-mantener-buena-relacion-con-sindicatos-ante-huelga-en-la-umsnh\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/"},{"@type":"ListItem","position":2,"name":"Bedolla llama a mantener buena relaci\u00f3n con sindicatos, ante huelga en la UMSNH"}]},{"@type":"WebSite","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/","name":"Diario ABC de Michoac\u00e1n","description":"Las noticias al momento","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/0546f9c3407148f7452ca932715c5e88","name":"MB","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/adcd41fde6b8d0b5d9d0de001d3112b3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/adcd41fde6b8d0b5d9d0de001d3112b3?s=96&d=mm&r=g","caption":"MB"},"url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/author\/bomariano03\/"}]}},"_links":{"self":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/79638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/comments?post=79638"}],"version-history":[{"count":1,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/79638\/revisions"}],"predecessor-version":[{"id":79640,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/79638\/revisions\/79640"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/media\/79639"}],"wp:attachment":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/media?parent=79638"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/categories?post=79638"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/tags?post=79638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}