{"id":79887,"date":"2026-05-17T15:26:42","date_gmt":"2026-05-17T21:26:42","guid":{"rendered":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?p=79887"},"modified":"2026-05-23T15:32:51","modified_gmt":"2026-05-23T21:32:51","slug":"llamado-de-la-diputada-sandra-garibay-a-las-fuerzas-del-orden-para-que-restablezcan-la-paz-en-apatzingan","status":"publish","type":"post","link":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/llamado-de-la-diputada-sandra-garibay-a-las-fuerzas-del-orden-para-que-restablezcan-la-paz-en-apatzingan\/","title":{"rendered":"Llamado de la diputada Sandra Garibay a las fuerzas del orden para que restablezcan la paz, en Apatzing\u00e1n"},"content":{"rendered":"<p>Apatzing\u00e1n, Mich., 17 de mayo de 2026.- La gente trabajadora del municipio de Apatzing\u00e1n, misma que d\u00eda a d\u00eda sale a ganarse la vida con esfuerzo y dignidad, no puede normalizar la violencia, se\u00f1al\u00f3 Sandra Olimpia Garibay, diputada local.<\/p>\n<p>\u00abAqu\u00ed hay jornaleros que desde las cuatro de la ma\u00f1ana parte al corte de lim\u00f3n, mientras que los comerciantes abren sus negocios desde temprano y familias enteras que dependen del trabajo honesto, se activan todas las ma\u00f1anas para salir adelante\u00bb expuso la legisladora.<\/p><div id=\"diari-1351372811\" class=\"diari-contenido diari-entity-placement\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-05-07-at-10.12.40-a.m.jpeg\" alt=\"\"  srcset=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-05-07-at-10.12.40-a.m.jpeg 400w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-05-07-at-10.12.40-a.m-150x150.jpeg 150w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-05-07-at-10.12.40-a.m-300x300.jpeg 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" width=\"400\" height=\"400\"  style=\"display: inline-block;\" \/><\/div>\n<p>\u00abPor eso no podemos normalizar la violencia ni acostumbrarnos a vivir con miedo, ya que somos gente de trabajo\u00bb, agreg\u00f3 Sandra Garibay.<\/p>\n<p>Agreg\u00f3 que los enfrentamientos ocurridos la ma\u00f1ana del viernes en una de las colonias m\u00e1s grandes de Apatzing\u00e1n, son una muestra alarmante de la situaci\u00f3n que hoy viven las familias apatzinguenses y califico la inseguridad como un mal que afecta no solamente a las comunidades, sino que tambi\u00e9n alcanza nuestras calles, nuestros comercios y a quienes \u00fanicamente quieren trabajar y regresar con bien a sus casas.<\/p>\n<p>\u00abComo diputada local, hago un llamado firme y urgente a los tres niveles de gobierno para que dejen de actuar de manera aislada y asuman con responsabilidad su obligaci\u00f3n de garantizar la seguridad de los ciudadanos\u00bb, expuso Sandra Garibay.<\/p>\n<p>Agreg\u00f3 que \u00abla gente de Apatzing\u00e1n merece vivir en paz y salir a trabajar sin temor, abrir sus negocios sin incertidumbre y transitar libremente por su municipio\u00bb.<\/p>\n<p>Expuso que \u00abno podemos permitir que la violencia le siga arrebatando la tranquilidad a nuestra gente\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apatzing\u00e1n, Mich., 17 de mayo de 2026.- La gente trabajadora del municipio de Apatzing\u00e1n, misma que d\u00eda a d\u00eda sale a ganarse la vida con esfuerzo y dignidad, no puede normalizar la violencia, se\u00f1al\u00f3 Sandra Olimpia Garibay, diputada local. \u00abAqu\u00ed hay jornaleros que desde las cuatro de la ma\u00f1ana parte al corte de lim\u00f3n, mientras [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":79888,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,13,22,10],"tags":[],"class_list":["post-79887","post","type-post","status-publish","format-standard","has-post-thumbnail","category-apatzingan","category-congreso","category-congreso-de-michoacan","category-estado"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Llamado de la diputada Sandra Garibay a las fuerzas del orden para que restablezcan la paz, en Apatzing\u00e1n - Diario ABC de Michoac\u00e1n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/llamado-de-la-diputada-sandra-garibay-a-las-fuerzas-del-orden-para-que-restablezcan-la-paz-en-apatzingan\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Llamado de la diputada Sandra Garibay a las fuerzas del orden para que restablezcan la paz, en Apatzing\u00e1n - Diario ABC de Michoac\u00e1n\" \/>\n<meta property=\"og:description\" content=\"Apatzing\u00e1n, Mich., 17 de mayo de 2026.- La gente trabajadora del municipio de Apatzing\u00e1n, misma que d\u00eda a d\u00eda sale a ganarse la vida con esfuerzo y dignidad, no puede normalizar la violencia, se\u00f1al\u00f3 Sandra Olimpia Garibay, diputada local. \u00abAqu\u00ed hay jornaleros que desde las cuatro de la ma\u00f1ana parte al corte de lim\u00f3n, mientras [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/llamado-de-la-diputada-sandra-garibay-a-las-fuerzas-del-orden-para-que-restablezcan-la-paz-en-apatzingan\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario ABC de Michoac\u00e1n\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-17T21:26:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-23T21:32:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2026\/05\/d5dd824f-aa44-40d6-a8dc-3edf44bffd42.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1375\" \/>\n\t<meta property=\"og:image:height\" content=\"1079\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MB\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MB\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/llamado-de-la-diputada-sandra-garibay-a-las-fuerzas-del-orden-para-que-restablezcan-la-paz-en-apatzingan\/\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/llamado-de-la-diputada-sandra-garibay-a-las-fuerzas-del-orden-para-que-restablezcan-la-paz-en-apatzingan\/\",\"name\":\"Llamado de la diputada Sandra Garibay a las fuerzas del orden para que restablezcan la paz, en Apatzing\u00e1n - Diario ABC de Michoac\u00e1n\",\"isPartOf\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/llamado-de-la-diputada-sandra-garibay-a-las-fuerzas-del-orden-para-que-restablezcan-la-paz-en-apatzingan\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/llamado-de-la-diputada-sandra-garibay-a-las-fuerzas-del-orden-para-que-restablezcan-la-paz-en-apatzingan\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2026\/05\/d5dd824f-aa44-40d6-a8dc-3edf44bffd42.jpg\",\"datePublished\":\"2026-05-17T21:26:42+00:00\",\"dateModified\":\"2026-05-23T21:32:51+00:00\",\"author\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/0546f9c3407148f7452ca932715c5e88\"},\"breadcrumb\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/llamado-de-la-diputada-sandra-garibay-a-las-fuerzas-del-orden-para-que-restablezcan-la-paz-en-apatzingan\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/llamado-de-la-diputada-sandra-garibay-a-las-fuerzas-del-orden-para-que-restablezcan-la-paz-en-apatzingan\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/llamado-de-la-diputada-sandra-garibay-a-las-fuerzas-del-orden-para-que-restablezcan-la-paz-en-apatzingan\/#primaryimage\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2026\/05\/d5dd824f-aa44-40d6-a8dc-3edf44bffd42.jpg\",\"contentUrl\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2026\/05\/d5dd824f-aa44-40d6-a8dc-3edf44bffd42.jpg\",\"width\":1375,\"height\":1079},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/llamado-de-la-diputada-sandra-garibay-a-las-fuerzas-del-orden-para-que-restablezcan-la-paz-en-apatzingan\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Llamado de la diputada Sandra Garibay a las fuerzas del orden para que restablezcan la paz, en Apatzing\u00e1n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/\",\"name\":\"Diario ABC de Michoac\u00e1n\",\"description\":\"Las noticias al momento\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/0546f9c3407148f7452ca932715c5e88\",\"name\":\"MB\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ac036f018f6a8431a5687a020efaf39d914da6a3fc78ce6029ab7ae29c5130e2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ac036f018f6a8431a5687a020efaf39d914da6a3fc78ce6029ab7ae29c5130e2?s=96&d=mm&r=g\",\"caption\":\"MB\"},\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/author\/bomariano03\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Llamado de la diputada Sandra Garibay a las fuerzas del orden para que restablezcan la paz, en Apatzing\u00e1n - Diario ABC de Michoac\u00e1n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/llamado-de-la-diputada-sandra-garibay-a-las-fuerzas-del-orden-para-que-restablezcan-la-paz-en-apatzingan\/","og_locale":"es_ES","og_type":"article","og_title":"Llamado de la diputada Sandra Garibay a las fuerzas del orden para que restablezcan la paz, en Apatzing\u00e1n - Diario ABC de Michoac\u00e1n","og_description":"Apatzing\u00e1n, Mich., 17 de mayo de 2026.- La gente trabajadora del municipio de Apatzing\u00e1n, misma que d\u00eda a d\u00eda sale a ganarse la vida con esfuerzo y dignidad, no puede normalizar la violencia, se\u00f1al\u00f3 Sandra Olimpia Garibay, diputada local. \u00abAqu\u00ed hay jornaleros que desde las cuatro de la ma\u00f1ana parte al corte de lim\u00f3n, mientras [&hellip;]","og_url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/llamado-de-la-diputada-sandra-garibay-a-las-fuerzas-del-orden-para-que-restablezcan-la-paz-en-apatzingan\/","og_site_name":"Diario ABC de Michoac\u00e1n","article_published_time":"2026-05-17T21:26:42+00:00","article_modified_time":"2026-05-23T21:32:51+00:00","og_image":[{"width":1375,"height":1079,"url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2026\/05\/d5dd824f-aa44-40d6-a8dc-3edf44bffd42.jpg","type":"image\/jpeg"}],"author":"MB","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"MB","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/llamado-de-la-diputada-sandra-garibay-a-las-fuerzas-del-orden-para-que-restablezcan-la-paz-en-apatzingan\/","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/llamado-de-la-diputada-sandra-garibay-a-las-fuerzas-del-orden-para-que-restablezcan-la-paz-en-apatzingan\/","name":"Llamado de la diputada Sandra Garibay a las fuerzas del orden para que restablezcan la paz, en Apatzing\u00e1n - Diario ABC de Michoac\u00e1n","isPartOf":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/llamado-de-la-diputada-sandra-garibay-a-las-fuerzas-del-orden-para-que-restablezcan-la-paz-en-apatzingan\/#primaryimage"},"image":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/llamado-de-la-diputada-sandra-garibay-a-las-fuerzas-del-orden-para-que-restablezcan-la-paz-en-apatzingan\/#primaryimage"},"thumbnailUrl":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2026\/05\/d5dd824f-aa44-40d6-a8dc-3edf44bffd42.jpg","datePublished":"2026-05-17T21:26:42+00:00","dateModified":"2026-05-23T21:32:51+00:00","author":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/0546f9c3407148f7452ca932715c5e88"},"breadcrumb":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/llamado-de-la-diputada-sandra-garibay-a-las-fuerzas-del-orden-para-que-restablezcan-la-paz-en-apatzingan\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/llamado-de-la-diputada-sandra-garibay-a-las-fuerzas-del-orden-para-que-restablezcan-la-paz-en-apatzingan\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/llamado-de-la-diputada-sandra-garibay-a-las-fuerzas-del-orden-para-que-restablezcan-la-paz-en-apatzingan\/#primaryimage","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2026\/05\/d5dd824f-aa44-40d6-a8dc-3edf44bffd42.jpg","contentUrl":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2026\/05\/d5dd824f-aa44-40d6-a8dc-3edf44bffd42.jpg","width":1375,"height":1079},{"@type":"BreadcrumbList","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/llamado-de-la-diputada-sandra-garibay-a-las-fuerzas-del-orden-para-que-restablezcan-la-paz-en-apatzingan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/"},{"@type":"ListItem","position":2,"name":"Llamado de la diputada Sandra Garibay a las fuerzas del orden para que restablezcan la paz, en Apatzing\u00e1n"}]},{"@type":"WebSite","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/","name":"Diario ABC de Michoac\u00e1n","description":"Las noticias al momento","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/0546f9c3407148f7452ca932715c5e88","name":"MB","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ac036f018f6a8431a5687a020efaf39d914da6a3fc78ce6029ab7ae29c5130e2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ac036f018f6a8431a5687a020efaf39d914da6a3fc78ce6029ab7ae29c5130e2?s=96&d=mm&r=g","caption":"MB"},"url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/author\/bomariano03\/"}]}},"_links":{"self":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/79887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/comments?post=79887"}],"version-history":[{"count":1,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/79887\/revisions"}],"predecessor-version":[{"id":79889,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/79887\/revisions\/79889"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/media\/79888"}],"wp:attachment":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/media?parent=79887"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/categories?post=79887"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/tags?post=79887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}