{"id":82684,"date":"2026-05-21T10:06:00","date_gmt":"2026-05-21T16:06:00","guid":{"rendered":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?p=82684"},"modified":"2026-07-10T10:07:26","modified_gmt":"2026-07-10T16:07:26","slug":"el-estadio-morelos-vuelve-a-ser-casa-de-los-zorros","status":"publish","type":"post","link":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/el-estadio-morelos-vuelve-a-ser-casa-de-los-zorros\/","title":{"rendered":"El Estadio Morelos vuelve a ser Casa de los Zorros"},"content":{"rendered":"<p>El Atl\u00e9tico Morelia-UMSNH se jugar\u00e1 el boleto a la gran final de la Liga TDP, el domingo en el \u2018Coloso del Quinceo\u2019<\/p>\n<hr \/>\n<p class=\"wp-block-paragraph\">Morelia, Michoac\u00e1n, a 21 de mayo de 2026.- El imponente Estadio Morelos volver\u00e1 a fungir como casa del Atl\u00e9tico Morelia-Universidad Michoacana para un importante compromiso en el que estar\u00e1 en juego el pase a la gran final de la liguilla de filiales de Liga de Tercera Divisi\u00f3n Profesional (TDP).<\/p><div id=\"diari-1032033504\" class=\"diari-contenido diari-entity-placement\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-05-07-at-10.12.40-a.m.jpeg\" alt=\"\"  srcset=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-05-07-at-10.12.40-a.m.jpeg 400w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-05-07-at-10.12.40-a.m-150x150.jpeg 150w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-05-07-at-10.12.40-a.m-300x300.jpeg 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" width=\"400\" height=\"400\"  style=\"display: inline-block;\" \/><\/div>\n<p class=\"wp-block-paragraph\">El \u2018Coloso del Quinceo\u2019 ser\u00e1 sede el domingo 24 de mayo en punto de las 12:00 horas para el partido de vuelta de semifinales, donde los Zorros ser\u00e1n anfitriones de los Gorilas de Juanacatl\u00e1n. Las puertas del recinto abrir\u00e1n desde las 11:30 horas y la entrada ser\u00e1 completamente gratuita, tanto para la comunidad nicolaita y para el p\u00fablico en general.<\/p>\n<p class=\"wp-block-paragraph\">Cabe recordar que el inmueble rojiamarillo ya fue casa del cuadro nicolaita en la vuelta de los dieciseisavos de final, partido en el que los representantes de la Casa de Hidalgo se impusieron 2-1 en un vibrante partido en el que el bicampe\u00f3n de goleo del Grupo 11, Cristian Castro, marc\u00f3 un doblete para sentenciar la eliminatoria por 4-2.<\/p>\n<p class=\"wp-block-paragraph\">\u201cPara nosotros es algo muy bonito, muy importante el que la Universidad Michoacana pueda estar una vez m\u00e1s dentro del Estadio Morelos, que es un referente del deporte en el estado y la casa del equipo de Expansi\u00f3n, el Atl\u00e9tico Morelia\u201d, manifest\u00f3 el t\u00e9cnico nicolaita, Gustavo Far\u00edas.<\/p>\n<p class=\"wp-block-paragraph\">El estratega del representativo de la Casa de Hidalgo asever\u00f3 que es emocionante jugar en un recinto que fue de Primera Divisi\u00f3n y que la comunidad universitaria se haga presente en las gradas. \u201cEs una motivaci\u00f3n muy importante, pero m\u00e1s motivaci\u00f3n va a ser ver a las y los nicolaitas llenando las tribunas del Morelos. Dentro de la liguilla estamos muy contentos, va a ser un partido muy complicado, respetamos mucho al rival, pero tenemos muchas ilusiones de hacer una gran serie\u201d.<\/p>\n<p class=\"wp-block-paragraph\">Este ser\u00e1 el \u00faltimo partido de la Temporada 2025-2026 que los Zorros jugar\u00e1n en la capital michoacana, pues en caso de avanzar a la final la disputar\u00eda en las instalaciones de la Federaci\u00f3n Mexicana de F\u00fatbol (FMF) en Toluca, Estado de M\u00e9xico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Atl\u00e9tico Morelia-UMSNH se jugar\u00e1 el boleto a la gran final de la Liga TDP, el domingo en el \u2018Coloso del Quinceo\u2019 Morelia, Michoac\u00e1n, a 21 de mayo de 2026.- El imponente Estadio Morelos volver\u00e1 a fungir como casa del Atl\u00e9tico Morelia-Universidad Michoacana para un importante compromiso en el que estar\u00e1 en juego el pase [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":82685,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,15,10,23],"tags":[],"class_list":["post-82684","post","type-post","status-publish","format-standard","has-post-thumbnail","category-deportes","category-educacion","category-estado","category-universidad-michoacana"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El Estadio Morelos vuelve a ser Casa de los Zorros - Diario ABC de Michoac\u00e1n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/el-estadio-morelos-vuelve-a-ser-casa-de-los-zorros\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Estadio Morelos vuelve a ser Casa de los Zorros - Diario ABC de Michoac\u00e1n\" \/>\n<meta property=\"og:description\" content=\"El Atl\u00e9tico Morelia-UMSNH se jugar\u00e1 el boleto a la gran final de la Liga TDP, el domingo en el \u2018Coloso del Quinceo\u2019 Morelia, Michoac\u00e1n, a 21 de mayo de 2026.- El imponente Estadio Morelos volver\u00e1 a fungir como casa del Atl\u00e9tico Morelia-Universidad Michoacana para un importante compromiso en el que estar\u00e1 en juego el pase [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/el-estadio-morelos-vuelve-a-ser-casa-de-los-zorros\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario ABC de Michoac\u00e1n\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-21T16:06:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T16:07:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2026\/07\/35a730be-3796-4495-8e94-ad70aadf5355.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"763\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MB\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MB\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/el-estadio-morelos-vuelve-a-ser-casa-de-los-zorros\/\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/el-estadio-morelos-vuelve-a-ser-casa-de-los-zorros\/\",\"name\":\"El Estadio Morelos vuelve a ser Casa de los Zorros - Diario ABC de Michoac\u00e1n\",\"isPartOf\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/el-estadio-morelos-vuelve-a-ser-casa-de-los-zorros\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/el-estadio-morelos-vuelve-a-ser-casa-de-los-zorros\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2026\/07\/35a730be-3796-4495-8e94-ad70aadf5355.jpg\",\"datePublished\":\"2026-05-21T16:06:00+00:00\",\"dateModified\":\"2026-07-10T16:07:26+00:00\",\"author\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/0546f9c3407148f7452ca932715c5e88\"},\"breadcrumb\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/el-estadio-morelos-vuelve-a-ser-casa-de-los-zorros\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/el-estadio-morelos-vuelve-a-ser-casa-de-los-zorros\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/el-estadio-morelos-vuelve-a-ser-casa-de-los-zorros\/#primaryimage\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2026\/07\/35a730be-3796-4495-8e94-ad70aadf5355.jpg\",\"contentUrl\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2026\/07\/35a730be-3796-4495-8e94-ad70aadf5355.jpg\",\"width\":1280,\"height\":763},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/el-estadio-morelos-vuelve-a-ser-casa-de-los-zorros\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Estadio Morelos vuelve a ser Casa de los Zorros\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/\",\"name\":\"Diario ABC de Michoac\u00e1n\",\"description\":\"Las noticias al momento\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/0546f9c3407148f7452ca932715c5e88\",\"name\":\"MB\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ac036f018f6a8431a5687a020efaf39d914da6a3fc78ce6029ab7ae29c5130e2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ac036f018f6a8431a5687a020efaf39d914da6a3fc78ce6029ab7ae29c5130e2?s=96&d=mm&r=g\",\"caption\":\"MB\"},\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/author\/bomariano03\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Estadio Morelos vuelve a ser Casa de los Zorros - Diario ABC de Michoac\u00e1n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/el-estadio-morelos-vuelve-a-ser-casa-de-los-zorros\/","og_locale":"es_ES","og_type":"article","og_title":"El Estadio Morelos vuelve a ser Casa de los Zorros - Diario ABC de Michoac\u00e1n","og_description":"El Atl\u00e9tico Morelia-UMSNH se jugar\u00e1 el boleto a la gran final de la Liga TDP, el domingo en el \u2018Coloso del Quinceo\u2019 Morelia, Michoac\u00e1n, a 21 de mayo de 2026.- El imponente Estadio Morelos volver\u00e1 a fungir como casa del Atl\u00e9tico Morelia-Universidad Michoacana para un importante compromiso en el que estar\u00e1 en juego el pase [&hellip;]","og_url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/el-estadio-morelos-vuelve-a-ser-casa-de-los-zorros\/","og_site_name":"Diario ABC de Michoac\u00e1n","article_published_time":"2026-05-21T16:06:00+00:00","article_modified_time":"2026-07-10T16:07:26+00:00","og_image":[{"width":1280,"height":763,"url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2026\/07\/35a730be-3796-4495-8e94-ad70aadf5355.jpg","type":"image\/jpeg"}],"author":"MB","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"MB","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/el-estadio-morelos-vuelve-a-ser-casa-de-los-zorros\/","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/el-estadio-morelos-vuelve-a-ser-casa-de-los-zorros\/","name":"El Estadio Morelos vuelve a ser Casa de los Zorros - Diario ABC de Michoac\u00e1n","isPartOf":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/el-estadio-morelos-vuelve-a-ser-casa-de-los-zorros\/#primaryimage"},"image":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/el-estadio-morelos-vuelve-a-ser-casa-de-los-zorros\/#primaryimage"},"thumbnailUrl":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2026\/07\/35a730be-3796-4495-8e94-ad70aadf5355.jpg","datePublished":"2026-05-21T16:06:00+00:00","dateModified":"2026-07-10T16:07:26+00:00","author":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/0546f9c3407148f7452ca932715c5e88"},"breadcrumb":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/el-estadio-morelos-vuelve-a-ser-casa-de-los-zorros\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/el-estadio-morelos-vuelve-a-ser-casa-de-los-zorros\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/el-estadio-morelos-vuelve-a-ser-casa-de-los-zorros\/#primaryimage","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2026\/07\/35a730be-3796-4495-8e94-ad70aadf5355.jpg","contentUrl":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2026\/07\/35a730be-3796-4495-8e94-ad70aadf5355.jpg","width":1280,"height":763},{"@type":"BreadcrumbList","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/el-estadio-morelos-vuelve-a-ser-casa-de-los-zorros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/"},{"@type":"ListItem","position":2,"name":"El Estadio Morelos vuelve a ser Casa de los Zorros"}]},{"@type":"WebSite","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/","name":"Diario ABC de Michoac\u00e1n","description":"Las noticias al momento","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/0546f9c3407148f7452ca932715c5e88","name":"MB","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ac036f018f6a8431a5687a020efaf39d914da6a3fc78ce6029ab7ae29c5130e2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ac036f018f6a8431a5687a020efaf39d914da6a3fc78ce6029ab7ae29c5130e2?s=96&d=mm&r=g","caption":"MB"},"url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/author\/bomariano03\/"}]}},"_links":{"self":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/82684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/comments?post=82684"}],"version-history":[{"count":2,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/82684\/revisions"}],"predecessor-version":[{"id":82687,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/82684\/revisions\/82687"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/media\/82685"}],"wp:attachment":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/media?parent=82684"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/categories?post=82684"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/tags?post=82684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}