{"id":82844,"date":"2026-07-01T22:01:26","date_gmt":"2026-07-02T04:01:26","guid":{"rendered":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?p=82844"},"modified":"2026-07-13T22:03:09","modified_gmt":"2026-07-14T04:03:09","slug":"con-inversion-historica-de-24-mil-mdp-ingenieros-locales-ejecutan-el-95-de-la-obra-publica-bedolla","status":"publish","type":"post","link":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/con-inversion-historica-de-24-mil-mdp-ingenieros-locales-ejecutan-el-95-de-la-obra-publica-bedolla\/","title":{"rendered":"Con inversi\u00f3n hist\u00f3rica de 24 mil mdp, ingenieros locales ejecutan el 95% de la obra p\u00fablica: Bedolla"},"content":{"rendered":"<p>Antonio Jes\u00fas Tinoco Zamudio, vicepresidente nacional de la CMIC, reconoci\u00f3 la visi\u00f3n de la actual administraci\u00f3n para consolidar obras estrat\u00e9gicas<\/p>\n<hr \/>\n<p>Morelia, Michoac\u00e1n, 1 de julio 2026.- En el marco de la conmemoraci\u00f3n del D\u00eda del Ingeniero, el gobernador Alfredo Ram\u00edrez Bedolla destac\u00f3 que el 95 por ciento de las obras p\u00fablicas en la entidad son construidas por ingenieras e ingenieros michoacanos. Esta estrategia no solo prioriza el talento local, sino que impulsa de manera directa el desarrollo de la infraestructura y la econom\u00eda regional, se\u00f1al\u00f3.<\/p><div id=\"diari-1134428871\" class=\"diari-contenido diari-entity-placement\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-05-07-at-10.12.40-a.m.jpeg\" alt=\"\"  srcset=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-05-07-at-10.12.40-a.m.jpeg 400w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-05-07-at-10.12.40-a.m-150x150.jpeg 150w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-05-07-at-10.12.40-a.m-300x300.jpeg 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" width=\"400\" height=\"400\"  style=\"display: inline-block;\" \/><\/div>\n<p>El mandatario estatal enfatiz\u00f3 que, durante el periodo 2022-2025, Michoac\u00e1n ha consolidado una inversi\u00f3n hist\u00f3rica de 24 mil millones de pesos en obra p\u00fablica, ejecutada con transparencia y sin contratar deuda p\u00fablica.<\/p>\n<p>\u201cNo estamos hipotecando el futuro de las michoacanas y michoacanos para hacer las obras que hoy realizamos\u201d, resalt\u00f3 Ram\u00edrez Bedolla y atribuy\u00f3 este \u00e9xito a la correcta implementaci\u00f3n del esquema multianual, un modelo financiero y de planeaci\u00f3n que ha permitido llevar acciones y proyectos de infraestructura a todos los municipios del estado, transformando la calidad de vida de sus habitantes.<\/p>\n<p>Por su parte, Antonio Jes\u00fas Tinoco Zamudio, vicepresidente nacional de Infraestructura Social y presidente del Comit\u00e9 Consultivo de la CMIC Michoac\u00e1n, reconoci\u00f3 la visi\u00f3n de la actual administraci\u00f3n para consolidar obras estrat\u00e9gicas con resultados tangibles para la poblaci\u00f3n.<\/p>\n<p>\u201cCelebramos que exista una visi\u00f3n que entiende la infraestructura como una herramienta para reducir desigualdades, fortalecer la econom\u00eda y construir mejores oportunidades para las futuras generaciones\u201d, detall\u00f3 Tinoco Zamudio.<\/p>\n<p>Asimismo, Alejandro Vargas Acosta, presidente de la CMIC, Delegaci\u00f3n Michoac\u00e1n, coincidi\u00f3 en que esta pol\u00edtica estrat\u00e9gica ha convertido a la infraestructura en el principal motor de desarrollo del estado, logrando atender un rezago hist\u00f3rico de m\u00e1s de 50 a\u00f1os.<\/p>\n<p>Subray\u00f3 adem\u00e1s la capacidad del Gobierno del Estado para construir acuerdos s\u00f3lidos con los municipios, poniendo siempre en el centro el bienestar de la ciudadan\u00eda.<\/p>\n<p>Asistieron Ra\u00fal Zepeda Villase\u00f1or, secretario de gobierno; Rogelio Zaraz\u00faa S\u00e1nchez, secretario de Comunicaciones y Obras P\u00fablicas; Mar\u00eda Leonor Ramos, primera mujer ingeniera en el estado de Michoac\u00e1n; as\u00ed como Joanna Moreno, secretaria de Desarrollo Urbano y Movilidad de Morelia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Antonio Jes\u00fas Tinoco Zamudio, vicepresidente nacional de la CMIC, reconoci\u00f3 la visi\u00f3n de la actual administraci\u00f3n para consolidar obras estrat\u00e9gicas Morelia, Michoac\u00e1n, 1 de julio 2026.- En el marco de la conmemoraci\u00f3n del D\u00eda del Ingeniero, el gobernador Alfredo Ram\u00edrez Bedolla destac\u00f3 que el 95 por ciento de las obras p\u00fablicas en la entidad son [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":82845,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31,10,17],"tags":[],"class_list":["post-82844","post","type-post","status-publish","format-standard","has-post-thumbnail","category-economia-y-capital-humano","category-estado","category-gobierno-de-michoacan"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Con inversi\u00f3n hist\u00f3rica de 24 mil mdp, ingenieros locales ejecutan el 95% de la obra p\u00fablica: Bedolla - Diario ABC de Michoac\u00e1n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/con-inversion-historica-de-24-mil-mdp-ingenieros-locales-ejecutan-el-95-de-la-obra-publica-bedolla\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Con inversi\u00f3n hist\u00f3rica de 24 mil mdp, ingenieros locales ejecutan el 95% de la obra p\u00fablica: Bedolla - Diario ABC de Michoac\u00e1n\" \/>\n<meta property=\"og:description\" content=\"Antonio Jes\u00fas Tinoco Zamudio, vicepresidente nacional de la CMIC, reconoci\u00f3 la visi\u00f3n de la actual administraci\u00f3n para consolidar obras estrat\u00e9gicas Morelia, Michoac\u00e1n, 1 de julio 2026.- En el marco de la conmemoraci\u00f3n del D\u00eda del Ingeniero, el gobernador Alfredo Ram\u00edrez Bedolla destac\u00f3 que el 95 por ciento de las obras p\u00fablicas en la entidad son [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/con-inversion-historica-de-24-mil-mdp-ingenieros-locales-ejecutan-el-95-de-la-obra-publica-bedolla\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario ABC de Michoac\u00e1n\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-02T04:01:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-14T04:03:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2026\/07\/111803ba-b8f9-41dd-8228-90dc2ed7a3fd.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1126\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MB\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MB\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/con-inversion-historica-de-24-mil-mdp-ingenieros-locales-ejecutan-el-95-de-la-obra-publica-bedolla\/\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/con-inversion-historica-de-24-mil-mdp-ingenieros-locales-ejecutan-el-95-de-la-obra-publica-bedolla\/\",\"name\":\"Con inversi\u00f3n hist\u00f3rica de 24 mil mdp, ingenieros locales ejecutan el 95% de la obra p\u00fablica: Bedolla - Diario ABC de Michoac\u00e1n\",\"isPartOf\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/con-inversion-historica-de-24-mil-mdp-ingenieros-locales-ejecutan-el-95-de-la-obra-publica-bedolla\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/con-inversion-historica-de-24-mil-mdp-ingenieros-locales-ejecutan-el-95-de-la-obra-publica-bedolla\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2026\/07\/111803ba-b8f9-41dd-8228-90dc2ed7a3fd.jpg\",\"datePublished\":\"2026-07-02T04:01:26+00:00\",\"dateModified\":\"2026-07-14T04:03:09+00:00\",\"author\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/0546f9c3407148f7452ca932715c5e88\"},\"breadcrumb\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/con-inversion-historica-de-24-mil-mdp-ingenieros-locales-ejecutan-el-95-de-la-obra-publica-bedolla\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/con-inversion-historica-de-24-mil-mdp-ingenieros-locales-ejecutan-el-95-de-la-obra-publica-bedolla\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/con-inversion-historica-de-24-mil-mdp-ingenieros-locales-ejecutan-el-95-de-la-obra-publica-bedolla\/#primaryimage\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2026\/07\/111803ba-b8f9-41dd-8228-90dc2ed7a3fd.jpg\",\"contentUrl\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2026\/07\/111803ba-b8f9-41dd-8228-90dc2ed7a3fd.jpg\",\"width\":1600,\"height\":1126},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/con-inversion-historica-de-24-mil-mdp-ingenieros-locales-ejecutan-el-95-de-la-obra-publica-bedolla\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Con inversi\u00f3n hist\u00f3rica de 24 mil mdp, ingenieros locales ejecutan el 95% de la obra p\u00fablica: Bedolla\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/\",\"name\":\"Diario ABC de Michoac\u00e1n\",\"description\":\"Las noticias al momento\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/0546f9c3407148f7452ca932715c5e88\",\"name\":\"MB\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ac036f018f6a8431a5687a020efaf39d914da6a3fc78ce6029ab7ae29c5130e2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ac036f018f6a8431a5687a020efaf39d914da6a3fc78ce6029ab7ae29c5130e2?s=96&d=mm&r=g\",\"caption\":\"MB\"},\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/author\/bomariano03\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Con inversi\u00f3n hist\u00f3rica de 24 mil mdp, ingenieros locales ejecutan el 95% de la obra p\u00fablica: Bedolla - Diario ABC de Michoac\u00e1n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/con-inversion-historica-de-24-mil-mdp-ingenieros-locales-ejecutan-el-95-de-la-obra-publica-bedolla\/","og_locale":"es_ES","og_type":"article","og_title":"Con inversi\u00f3n hist\u00f3rica de 24 mil mdp, ingenieros locales ejecutan el 95% de la obra p\u00fablica: Bedolla - Diario ABC de Michoac\u00e1n","og_description":"Antonio Jes\u00fas Tinoco Zamudio, vicepresidente nacional de la CMIC, reconoci\u00f3 la visi\u00f3n de la actual administraci\u00f3n para consolidar obras estrat\u00e9gicas Morelia, Michoac\u00e1n, 1 de julio 2026.- En el marco de la conmemoraci\u00f3n del D\u00eda del Ingeniero, el gobernador Alfredo Ram\u00edrez Bedolla destac\u00f3 que el 95 por ciento de las obras p\u00fablicas en la entidad son [&hellip;]","og_url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/con-inversion-historica-de-24-mil-mdp-ingenieros-locales-ejecutan-el-95-de-la-obra-publica-bedolla\/","og_site_name":"Diario ABC de Michoac\u00e1n","article_published_time":"2026-07-02T04:01:26+00:00","article_modified_time":"2026-07-14T04:03:09+00:00","og_image":[{"width":1600,"height":1126,"url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2026\/07\/111803ba-b8f9-41dd-8228-90dc2ed7a3fd.jpg","type":"image\/jpeg"}],"author":"MB","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"MB","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/con-inversion-historica-de-24-mil-mdp-ingenieros-locales-ejecutan-el-95-de-la-obra-publica-bedolla\/","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/con-inversion-historica-de-24-mil-mdp-ingenieros-locales-ejecutan-el-95-de-la-obra-publica-bedolla\/","name":"Con inversi\u00f3n hist\u00f3rica de 24 mil mdp, ingenieros locales ejecutan el 95% de la obra p\u00fablica: Bedolla - Diario ABC de Michoac\u00e1n","isPartOf":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/con-inversion-historica-de-24-mil-mdp-ingenieros-locales-ejecutan-el-95-de-la-obra-publica-bedolla\/#primaryimage"},"image":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/con-inversion-historica-de-24-mil-mdp-ingenieros-locales-ejecutan-el-95-de-la-obra-publica-bedolla\/#primaryimage"},"thumbnailUrl":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2026\/07\/111803ba-b8f9-41dd-8228-90dc2ed7a3fd.jpg","datePublished":"2026-07-02T04:01:26+00:00","dateModified":"2026-07-14T04:03:09+00:00","author":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/0546f9c3407148f7452ca932715c5e88"},"breadcrumb":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/con-inversion-historica-de-24-mil-mdp-ingenieros-locales-ejecutan-el-95-de-la-obra-publica-bedolla\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/con-inversion-historica-de-24-mil-mdp-ingenieros-locales-ejecutan-el-95-de-la-obra-publica-bedolla\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/con-inversion-historica-de-24-mil-mdp-ingenieros-locales-ejecutan-el-95-de-la-obra-publica-bedolla\/#primaryimage","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2026\/07\/111803ba-b8f9-41dd-8228-90dc2ed7a3fd.jpg","contentUrl":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2026\/07\/111803ba-b8f9-41dd-8228-90dc2ed7a3fd.jpg","width":1600,"height":1126},{"@type":"BreadcrumbList","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/con-inversion-historica-de-24-mil-mdp-ingenieros-locales-ejecutan-el-95-de-la-obra-publica-bedolla\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/"},{"@type":"ListItem","position":2,"name":"Con inversi\u00f3n hist\u00f3rica de 24 mil mdp, ingenieros locales ejecutan el 95% de la obra p\u00fablica: Bedolla"}]},{"@type":"WebSite","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/","name":"Diario ABC de Michoac\u00e1n","description":"Las noticias al momento","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/0546f9c3407148f7452ca932715c5e88","name":"MB","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ac036f018f6a8431a5687a020efaf39d914da6a3fc78ce6029ab7ae29c5130e2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ac036f018f6a8431a5687a020efaf39d914da6a3fc78ce6029ab7ae29c5130e2?s=96&d=mm&r=g","caption":"MB"},"url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/author\/bomariano03\/"}]}},"_links":{"self":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/82844","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/comments?post=82844"}],"version-history":[{"count":2,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/82844\/revisions"}],"predecessor-version":[{"id":82847,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/82844\/revisions\/82847"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/media\/82845"}],"wp:attachment":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/media?parent=82844"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/categories?post=82844"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/tags?post=82844"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}