{"id":8790,"date":"2024-06-02T13:36:12","date_gmt":"2024-06-02T19:36:12","guid":{"rendered":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?p=8790"},"modified":"2024-06-02T13:36:12","modified_gmt":"2024-06-02T19:36:12","slug":"la-jornada-de-este-dia-para-elegir-presidente-de-la-republica-senadores-diputados-federales-diputados-locales-y-presidentes-municipales-ha-transcurrido-en-apatzingan-sin-mayores-contratiempos","status":"publish","type":"post","link":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/la-jornada-de-este-dia-para-elegir-presidente-de-la-republica-senadores-diputados-federales-diputados-locales-y-presidentes-municipales-ha-transcurrido-en-apatzingan-sin-mayores-contratiempos\/","title":{"rendered":"La jornada de este d\u00eda para elegir presidente de la Rep\u00fablica, Senadores, Diputados Federales, Diputados Locales y Presidentes Municipales, ha transcurrido en Apatzing\u00e1n sin mayores contratiempos"},"content":{"rendered":"<h2>Salvo incidentes considerados menores, como el retraso en la instalaci\u00f3n de casillas para la emision del voto.<\/h2>\n<p>&nbsp;<\/p>\n<h6>POR J. JES\u00daS BEFOLLA NAVA, DIARIO ABC DE MICHOAC\u00c1N, 02 DE JUNIO DE 2024.<\/h6>\n<hr \/>\n<p>Apatzing\u00e1n, Mich. &#8211; Salvo incidentes considerados menores, como el retraso en la instalaci\u00f3n de casillas para la emision del voto, entre otros, la jornada de este d\u00eda para elegir presidente de la Rep\u00fablica, Senadores, Diputados Federales, Diputados Locales y Presidentes Municipales, ha transcurrido en Apatzing\u00e1n sin mayores contratiempos, cuando el reloj marca la.13:00 horas de este domingo.<\/p>\n<p>&nbsp;<\/p>\n<p>Los incidentes de tipo log\u00edstico o urriero en la Secci\u00f3n 112, cuya casilla para votar se encuentra ubicada en la escuela L\u00e1zaro C\u00e1rdenas, de la colonia Las Palmas, en donde la votaci\u00f3n inici\u00f3 a las 09:20 horas yn en donde, de acuerdo con la Ley Electoral, se permiti\u00f3 el acceso a las personas discapacitadas y de la tercera edad con problemas para sostenerse y que usaron bordones, pero tambi\u00e9n se sugiri\u00f3 que.\u00bblos que tengan que trabajar pueden pasar a votar por delante\u00bb, lo que.porbovo.laleatar.entre quienes hac\u00edan fila en espers de turno para poder votar.<\/p><div id=\"diari-1192071008\" class=\"diari-contenido diari-entity-placement\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-05-07-at-10.12.40-a.m.jpeg\" alt=\"\"  srcset=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-05-07-at-10.12.40-a.m.jpeg 400w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-05-07-at-10.12.40-a.m-150x150.jpeg 150w, https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-05-07-at-10.12.40-a.m-300x300.jpeg 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" width=\"400\" height=\"400\"  style=\"display: inline-block;\" \/><\/div>\n<p>&nbsp;<\/p>\n<p>La manifestaci\u00f3n de descontento ciudadano hizo que la auxiliar del INE que hab\u00eda otorgado esa facilidad a \u00abquienes tienen que trabajar&#8217;, dierammarcya atr\u00e1s y lammedida se circunscribi\u00f3 solamente a dispacaoitados.<\/p>\n<p>&nbsp;<\/p>\n<p>En otra ocasi\u00f3n se escuch\u00f3 decir a otra auxiliar que se dirig\u00eda a una persona de la tercera edad \u00ab&#8230; vota para que no te quiten tu pensi\u00f3n\u00bb y acto seguido se retir\u00f3 al advertir la presencia de.los reporteros.<\/p>\n<p>&nbsp;<\/p>\n<p>En t\u00e9rminos generales.la constante fue el atraso en la instalaci\u00f3n de las casillas, debido a la irresponsabilidad de los funcionarios de casilla para presentarse a cumplir con un compromiso ciudadano que aseguraron cumplir ante.laa autoridades electorales.<\/p>\n<p>&nbsp;<\/p>\n<p>En estos casos se opto por obtener personal de la fila para tratar de cumplir con el cometido.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Salvo incidentes considerados menores, como el retraso en la instalaci\u00f3n de casillas para la emision del voto. &nbsp; POR J. JES\u00daS BEFOLLA NAVA, DIARIO ABC DE MICHOAC\u00c1N, 02 DE JUNIO DE 2024. Apatzing\u00e1n, Mich. &#8211; Salvo incidentes considerados menores, como el retraso en la instalaci\u00f3n de casillas para la emision del voto, entre otros, la [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":8791,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,28,27],"tags":[],"class_list":["post-8790","post","type-post","status-publish","format-standard","has-post-thumbnail","category-apatzingan","category-politica","category-slider"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La jornada de este d\u00eda para elegir presidente de la Rep\u00fablica, Senadores, Diputados Federales, Diputados Locales y Presidentes Municipales, ha transcurrido en Apatzing\u00e1n sin mayores contratiempos - Diario ABC de Michoac\u00e1n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/la-jornada-de-este-dia-para-elegir-presidente-de-la-republica-senadores-diputados-federales-diputados-locales-y-presidentes-municipales-ha-transcurrido-en-apatzingan-sin-mayores-contratiempos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La jornada de este d\u00eda para elegir presidente de la Rep\u00fablica, Senadores, Diputados Federales, Diputados Locales y Presidentes Municipales, ha transcurrido en Apatzing\u00e1n sin mayores contratiempos - Diario ABC de Michoac\u00e1n\" \/>\n<meta property=\"og:description\" content=\"Salvo incidentes considerados menores, como el retraso en la instalaci\u00f3n de casillas para la emision del voto. &nbsp; POR J. JES\u00daS BEFOLLA NAVA, DIARIO ABC DE MICHOAC\u00c1N, 02 DE JUNIO DE 2024. Apatzing\u00e1n, Mich. &#8211; Salvo incidentes considerados menores, como el retraso en la instalaci\u00f3n de casillas para la emision del voto, entre otros, la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/la-jornada-de-este-dia-para-elegir-presidente-de-la-republica-senadores-diputados-federales-diputados-locales-y-presidentes-municipales-ha-transcurrido-en-apatzingan-sin-mayores-contratiempos\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario ABC de Michoac\u00e1n\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-02T19:36:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-02-at-1.21.25-PM-2.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"AR\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"AR\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/la-jornada-de-este-dia-para-elegir-presidente-de-la-republica-senadores-diputados-federales-diputados-locales-y-presidentes-municipales-ha-transcurrido-en-apatzingan-sin-mayores-contratiempos\/\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/la-jornada-de-este-dia-para-elegir-presidente-de-la-republica-senadores-diputados-federales-diputados-locales-y-presidentes-municipales-ha-transcurrido-en-apatzingan-sin-mayores-contratiempos\/\",\"name\":\"La jornada de este d\u00eda para elegir presidente de la Rep\u00fablica, Senadores, Diputados Federales, Diputados Locales y Presidentes Municipales, ha transcurrido en Apatzing\u00e1n sin mayores contratiempos - Diario ABC de Michoac\u00e1n\",\"isPartOf\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/la-jornada-de-este-dia-para-elegir-presidente-de-la-republica-senadores-diputados-federales-diputados-locales-y-presidentes-municipales-ha-transcurrido-en-apatzingan-sin-mayores-contratiempos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/la-jornada-de-este-dia-para-elegir-presidente-de-la-republica-senadores-diputados-federales-diputados-locales-y-presidentes-municipales-ha-transcurrido-en-apatzingan-sin-mayores-contratiempos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-02-at-1.21.25-PM-2.jpeg\",\"datePublished\":\"2024-06-02T19:36:12+00:00\",\"dateModified\":\"2024-06-02T19:36:12+00:00\",\"author\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/19ae376040f6cbc489682ebdd8524852\"},\"breadcrumb\":{\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/la-jornada-de-este-dia-para-elegir-presidente-de-la-republica-senadores-diputados-federales-diputados-locales-y-presidentes-municipales-ha-transcurrido-en-apatzingan-sin-mayores-contratiempos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/la-jornada-de-este-dia-para-elegir-presidente-de-la-republica-senadores-diputados-federales-diputados-locales-y-presidentes-municipales-ha-transcurrido-en-apatzingan-sin-mayores-contratiempos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/la-jornada-de-este-dia-para-elegir-presidente-de-la-republica-senadores-diputados-federales-diputados-locales-y-presidentes-municipales-ha-transcurrido-en-apatzingan-sin-mayores-contratiempos\/#primaryimage\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-02-at-1.21.25-PM-2.jpeg\",\"contentUrl\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-02-at-1.21.25-PM-2.jpeg\",\"width\":1600,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/la-jornada-de-este-dia-para-elegir-presidente-de-la-republica-senadores-diputados-federales-diputados-locales-y-presidentes-municipales-ha-transcurrido-en-apatzingan-sin-mayores-contratiempos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La jornada de este d\u00eda para elegir presidente de la Rep\u00fablica, Senadores, Diputados Federales, Diputados Locales y Presidentes Municipales, ha transcurrido en Apatzing\u00e1n sin mayores contratiempos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website\",\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/\",\"name\":\"Diario ABC de Michoac\u00e1n\",\"description\":\"Las noticias al momento\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/19ae376040f6cbc489682ebdd8524852\",\"name\":\"AR\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/620dde31bffc1d1abdb08a27461f06f796e6d74bba9feb506eda89b4e07120bb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/620dde31bffc1d1abdb08a27461f06f796e6d74bba9feb506eda89b4e07120bb?s=96&d=mm&r=g\",\"caption\":\"AR\"},\"url\":\"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/author\/adrian\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La jornada de este d\u00eda para elegir presidente de la Rep\u00fablica, Senadores, Diputados Federales, Diputados Locales y Presidentes Municipales, ha transcurrido en Apatzing\u00e1n sin mayores contratiempos - Diario ABC de Michoac\u00e1n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/la-jornada-de-este-dia-para-elegir-presidente-de-la-republica-senadores-diputados-federales-diputados-locales-y-presidentes-municipales-ha-transcurrido-en-apatzingan-sin-mayores-contratiempos\/","og_locale":"es_ES","og_type":"article","og_title":"La jornada de este d\u00eda para elegir presidente de la Rep\u00fablica, Senadores, Diputados Federales, Diputados Locales y Presidentes Municipales, ha transcurrido en Apatzing\u00e1n sin mayores contratiempos - Diario ABC de Michoac\u00e1n","og_description":"Salvo incidentes considerados menores, como el retraso en la instalaci\u00f3n de casillas para la emision del voto. &nbsp; POR J. JES\u00daS BEFOLLA NAVA, DIARIO ABC DE MICHOAC\u00c1N, 02 DE JUNIO DE 2024. Apatzing\u00e1n, Mich. &#8211; Salvo incidentes considerados menores, como el retraso en la instalaci\u00f3n de casillas para la emision del voto, entre otros, la [&hellip;]","og_url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/la-jornada-de-este-dia-para-elegir-presidente-de-la-republica-senadores-diputados-federales-diputados-locales-y-presidentes-municipales-ha-transcurrido-en-apatzingan-sin-mayores-contratiempos\/","og_site_name":"Diario ABC de Michoac\u00e1n","article_published_time":"2024-06-02T19:36:12+00:00","og_image":[{"width":1600,"height":720,"url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-02-at-1.21.25-PM-2.jpeg","type":"image\/jpeg"}],"author":"AR","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"AR","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/la-jornada-de-este-dia-para-elegir-presidente-de-la-republica-senadores-diputados-federales-diputados-locales-y-presidentes-municipales-ha-transcurrido-en-apatzingan-sin-mayores-contratiempos\/","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/la-jornada-de-este-dia-para-elegir-presidente-de-la-republica-senadores-diputados-federales-diputados-locales-y-presidentes-municipales-ha-transcurrido-en-apatzingan-sin-mayores-contratiempos\/","name":"La jornada de este d\u00eda para elegir presidente de la Rep\u00fablica, Senadores, Diputados Federales, Diputados Locales y Presidentes Municipales, ha transcurrido en Apatzing\u00e1n sin mayores contratiempos - Diario ABC de Michoac\u00e1n","isPartOf":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/la-jornada-de-este-dia-para-elegir-presidente-de-la-republica-senadores-diputados-federales-diputados-locales-y-presidentes-municipales-ha-transcurrido-en-apatzingan-sin-mayores-contratiempos\/#primaryimage"},"image":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/la-jornada-de-este-dia-para-elegir-presidente-de-la-republica-senadores-diputados-federales-diputados-locales-y-presidentes-municipales-ha-transcurrido-en-apatzingan-sin-mayores-contratiempos\/#primaryimage"},"thumbnailUrl":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-02-at-1.21.25-PM-2.jpeg","datePublished":"2024-06-02T19:36:12+00:00","dateModified":"2024-06-02T19:36:12+00:00","author":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/19ae376040f6cbc489682ebdd8524852"},"breadcrumb":{"@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/la-jornada-de-este-dia-para-elegir-presidente-de-la-republica-senadores-diputados-federales-diputados-locales-y-presidentes-municipales-ha-transcurrido-en-apatzingan-sin-mayores-contratiempos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/la-jornada-de-este-dia-para-elegir-presidente-de-la-republica-senadores-diputados-federales-diputados-locales-y-presidentes-municipales-ha-transcurrido-en-apatzingan-sin-mayores-contratiempos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/la-jornada-de-este-dia-para-elegir-presidente-de-la-republica-senadores-diputados-federales-diputados-locales-y-presidentes-municipales-ha-transcurrido-en-apatzingan-sin-mayores-contratiempos\/#primaryimage","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-02-at-1.21.25-PM-2.jpeg","contentUrl":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2024-06-02-at-1.21.25-PM-2.jpeg","width":1600,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/la-jornada-de-este-dia-para-elegir-presidente-de-la-republica-senadores-diputados-federales-diputados-locales-y-presidentes-municipales-ha-transcurrido-en-apatzingan-sin-mayores-contratiempos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/"},{"@type":"ListItem","position":2,"name":"La jornada de este d\u00eda para elegir presidente de la Rep\u00fablica, Senadores, Diputados Federales, Diputados Locales y Presidentes Municipales, ha transcurrido en Apatzing\u00e1n sin mayores contratiempos"}]},{"@type":"WebSite","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#website","url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/","name":"Diario ABC de Michoac\u00e1n","description":"Las noticias al momento","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/19ae376040f6cbc489682ebdd8524852","name":"AR","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/620dde31bffc1d1abdb08a27461f06f796e6d74bba9feb506eda89b4e07120bb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/620dde31bffc1d1abdb08a27461f06f796e6d74bba9feb506eda89b4e07120bb?s=96&d=mm&r=g","caption":"AR"},"url":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/author\/adrian\/"}]}},"_links":{"self":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/8790","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/comments?post=8790"}],"version-history":[{"count":1,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/8790\/revisions"}],"predecessor-version":[{"id":8798,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/posts\/8790\/revisions\/8798"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/media\/8791"}],"wp:attachment":[{"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/media?parent=8790"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/categories?post=8790"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioabcdemichoacan.com.mx\/lasnoticias\/wp-json\/wp\/v2\/tags?post=8790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}